{"id":28813,"date":"2024-02-01T17:37:06","date_gmt":"2024-02-01T22:37:06","guid":{"rendered":"https:\/\/www.rsa.com\/?page_id=28813"},"modified":"2026-04-02T12:49:35","modified_gmt":"2026-04-02T16:49:35","slug":"terms-of-use-july-2022","status":"publish","type":"page","link":"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/","title":{"rendered":"Termos de uso - julho de 2022"},"content":{"rendered":"<h4 class=\"size-h6-regular compressed\">Sobre estes Termos de Uso<\/h4>\n<p>Estes termos (\"Termos\") s\u00e3o um acordo legal entre voc\u00ea e a RSA Security LLC e suas afiliadas (\"RSA\"). Os Termos controlam seu uso e acesso aos sites e informa\u00e7\u00f5es on-line da RSA (os \"Sites\" ou \"Site\"). Ao usar os Sites da RSA, voc\u00ea concorda com estes Termos. A RSA pode revisar estes Termos a qualquer momento, atualizando esta p\u00e1gina. Voc\u00ea deve revisitar esta p\u00e1gina periodicamente para determinar quais termos regem seu uso do Site.<\/p>\n<h4 class=\"size-h6-regular compressed\">Isen\u00e7\u00e3o de responsabilidade da licen\u00e7a e restri\u00e7\u00f5es de uso<\/h4>\n<p class=\"compressed\">Nada em qualquer Site da RSA lhe d\u00e1 qualquer licen\u00e7a sob qualquer direito de propriedade intelectual da RSA ou de terceiros. Todos os direitos de propriedade intelectual deste Site pertencem \u00e0 RSA ou a outras partes que licenciaram seu material para a RSA. Sujeito a estes Termos, a RSA lhe concede um direito limitado, revog\u00e1vel e n\u00e3o exclusivo de acessar e usar o Site e os materiais e informa\u00e7\u00f5es nele contidos (\"Conte\u00fado da RSA\"). Esta licen\u00e7a limitada destina-se apenas ao seu uso pessoal e n\u00e3o comercial. Voc\u00ea deve manter os avisos de propriedade da RSA em todas as c\u00f3pias que fizer do Conte\u00fado da RSA. O uso n\u00e3o autorizado do Conte\u00fado da RSA pode violar direitos autorais, marcas registradas, privacidade, comunica\u00e7\u00f5es ou outras leis. O usu\u00e1rio \u00e9 respons\u00e1vel perante a RSA pelo uso n\u00e3o autorizado do Conte\u00fado da RSA. Este direito termina automaticamente se o usu\u00e1rio violar qualquer parte destes Termos. Ap\u00f3s a rescis\u00e3o, o usu\u00e1rio deve destruir imediatamente qualquer Conte\u00fado da RSA em sua posse ou controle. Al\u00e9m do que foi mencionado acima, voc\u00ea n\u00e3o deve:\n<\/p>\n<ul>\n<li>Modificar, alterar, copiar, distribuir, republicar, fazer download, exibir, publicar ou enviar o Conte\u00fado da RSA de qualquer forma ou por qualquer meio sem a permiss\u00e3o pr\u00e9via por escrito da RSA ou do propriet\u00e1rio dos direitos autorais, a menos que o Site indique o contr\u00e1rio em rela\u00e7\u00e3o a um Conte\u00fado da RSA espec\u00edfico;<\/li>\n<li>Decompilar, fazer engenharia reversa, desmontar, tentar derivar o c\u00f3digo-fonte, modificar ou criar trabalhos derivados do software, de quaisquer atualiza\u00e7\u00f5es ou de qualquer parte dele (exceto se e somente na medida em que qualquer restri\u00e7\u00e3o anterior for proibida pela legisla\u00e7\u00e3o aplic\u00e1vel ou na medida permitida pelos termos de licenciamento que regem o uso de quaisquer componentes de c\u00f3digo aberto inclu\u00eddos no software);<\/li>\n<li>Usar o Site ou o Conte\u00fado da RSA para qualquer finalidade que seja ilegal ou proibida por estes Termos;<\/li>\n<li>Usar o Site para solicitar qualquer atividade que seja ilegal ou que possa infringir os direitos de terceiros;<\/li>\n<li>\"Espelhar\" ou \"enquadrar\" qualquer Conte\u00fado da RSA em qualquer outro dispositivo sem a permiss\u00e3o por escrito da RSA;<\/li>\n<li>Usar o Conte\u00fado da RSA para comparar qualquer Conte\u00fado da RSA com produtos, servi\u00e7os ou informa\u00e7\u00f5es de qualquer outra pessoa ou entidade; ou\n<\/li>\n<li class=\"translation-block\">Usar o logotipo da RSA ou da Confer\u00eancia da RSA ou qualquer outra marca registrada da RSA como um link \"quente\" para qualquer parte do Site, a menos que a RSA aprove esse uso por escrito. <a href=\"\/pt_br\/rsa-trademarks\/\" target=\"_self\">Pol\u00edtica de marcas registradas<\/a><\/li>\n<\/ul>\n<h4 class=\"size-h6-regular compressed\">Informa\u00e7\u00f5es sobre direitos autorais<\/h4>\n<p>A lei de direitos autorais protege todo o Conte\u00fado da RSA.<\/p>\n<p>Os direitos autorais de todo o material fornecido neste Site s\u00e3o de propriedade da RSA ou do criador original do material. Exceto conforme declarado neste documento, nenhum material pode ser copiado, reproduzido, distribu\u00eddo, republicado, baixado, exibido, postado ou transmitido de qualquer forma ou por qualquer meio, incluindo, entre outros, eletr\u00f4nico, mec\u00e2nico, fotoc\u00f3pia, grava\u00e7\u00e3o ou outro, sem a permiss\u00e3o pr\u00e9via por escrito da RSA ou do propriet\u00e1rio dos direitos autorais. \u00c9 concedida permiss\u00e3o para exibir, copiar, distribuir e fazer download dos materiais deste Site apenas para uso pessoal e n\u00e3o comercial, desde que os materiais n\u00e3o sejam modificados e que todos os avisos de direitos autorais e outros avisos de propriedade contidos nos materiais sejam mantidos. Voc\u00ea tamb\u00e9m n\u00e3o pode, sem a permiss\u00e3o da RSA, \"espelhar\" qualquer material contido neste Site em qualquer outro servidor. Essa permiss\u00e3o termina automaticamente se o usu\u00e1rio violar qualquer um desses termos ou condi\u00e7\u00f5es. Qualquer uso n\u00e3o autorizado de qualquer material contido neste Site pode violar leis de direitos autorais, leis de marcas registradas, leis de privacidade e publicidade e regulamentos e estatutos de comunica\u00e7\u00f5es.<\/p>\n<h4 class=\"size-h6-regular compressed\">AVISO DA LEI DE DIREITOS AUTORAIS DO MIL\u00caNIO DIGITAL DOS EUA<\/h4>\n<p>Se voc\u00ea acredita que seu trabalho foi copiado de alguma forma sem a sua permiss\u00e3o, forne\u00e7a as seguintes informa\u00e7\u00f5es ao nosso agente para receber a Notifica\u00e7\u00e3o de alega\u00e7\u00e3o de viola\u00e7\u00e3o de direitos autorais identificada abaixo. Sua notifica\u00e7\u00e3o deve conter o seguinte:<\/p>\n<ul>\n<li>Uma assinatura eletr\u00f4nica ou f\u00edsica da pessoa autorizada a agir em nome do propriet\u00e1rio dos direitos autorais ou de outra participa\u00e7\u00e3o<\/li>\n<li>Uma descri\u00e7\u00e3o do trabalho protegido por direitos autorais ou outro trabalho que voc\u00ea alega ter sido violado<\/li>\n<li>Uma descri\u00e7\u00e3o de onde o material que voc\u00ea alega estar sendo violado est\u00e1 localizado em nossos sites, redes ou outros reposit\u00f3rios<\/li>\n<li>Seu endere\u00e7o, n\u00famero de telefone e endere\u00e7o de e-mail<\/li>\n<li>Uma declara\u00e7\u00e3o por escrito de que voc\u00ea acredita de boa f\u00e9 que o uso contestado n\u00e3o est\u00e1 autorizado pelo propriet\u00e1rio dos direitos autorais, seu agente ou pela lei<\/li>\n<li>Uma declara\u00e7\u00e3o sua, feita sob pena de perj\u00fario, de que as informa\u00e7\u00f5es acima em sua notifica\u00e7\u00e3o s\u00e3o precisas e que voc\u00ea \u00e9 o propriet\u00e1rio dos direitos autorais ou est\u00e1 autorizado a agir em nome do propriet\u00e1rio dos direitos autorais<\/li>\n<\/ul>\n<p>Nosso Agente Designado para notifica\u00e7\u00e3o de reclama\u00e7\u00f5es de viola\u00e7\u00e3o de direitos autorais pode ser contatado da seguinte forma:<br \/>\nRSA Security LLC<br \/>\nAttn: IP Legal Department - Copyrights (Departamento Jur\u00eddico de PI - Direitos Autorais)<br \/>\n176 Middlesex Turnpike<br \/>\nBedford, MA 01730<br \/>\nE-mail: <a href=\"mailto:ip@rsa-cybersecurity.com\" rel=\"noopener\" target=\"_blank\">ip@rsa-cybersecurity.com <\/a><\/p>\n<p>Se os materiais contestados tiverem sido postados por um terceiro identific\u00e1vel por meio de esfor\u00e7os razo\u00e1veis, forneceremos uma notifica\u00e7\u00e3o razo\u00e1vel a esse terceiro sobre a acusa\u00e7\u00e3o. Se o terceiro responder com uma contranotifica\u00e7\u00e3o v\u00e1lida, forneceremos uma c\u00f3pia para que voc\u00ea possa tomar quaisquer outras medidas que considere apropriadas.<\/p>\n<h4 class=\"size-h6-regular compressed\">Privacidade<\/h4>\n<p>A Pol\u00edtica de Privacidade da RSA se aplica ao seu uso do Site e faz parte destes Termos. Leia a Pol\u00edtica de Privacidade da RSA e as informa\u00e7\u00f5es relacionadas sobre sua privacidade e o uso de suas informa\u00e7\u00f5es pela RSA. O usu\u00e1rio reconhece e concorda que \u00e9 respons\u00e1vel por:<\/p>\n<ul>\n<li>Proteger todas as informa\u00e7\u00f5es de conta e senha aplic\u00e1veis ao seu uso do Site;<\/li>\n<li>Restringir o uso e o acesso ao seu computador, smartphone ou outro dispositivo usado para acessar o Site; e<\/li>\n<li>Qualquer atividade que ocorra em sua conta devido \u00e0 sua falha em proteger essas informa\u00e7\u00f5es.<\/li>\n<\/ul>\n<h4 class=\"size-h6-regular compressed\">Comunica\u00e7\u00e3o eletr\u00f4nica<\/h4>\n<p>Ao usar o Site, voc\u00ea est\u00e1 se comunicando com a RSA. Voc\u00ea concorda em receber comunica\u00e7\u00f5es eletr\u00f4nicas relacionadas ao seu uso do Site. A RSA pode se comunicar com voc\u00ea por e-mail ou por meio da publica\u00e7\u00e3o de avisos no Site. Voc\u00ea concorda que todas essas comunica\u00e7\u00f5es atendam a qualquer regra legal que exija que sejam feitas por escrito. A RSA pode enviar avisos ao usu\u00e1rio por e-mail ou por publica\u00e7\u00f5es no Site, e esses avisos entram em vigor na data em que a RSA os envia ou publica.<\/p>\n<h4 class=\"size-h6-regular compressed\">Exporta\u00e7\u00e3o<\/h4>\n<p>Todo o Conte\u00fado da RSA est\u00e1 sujeito \u00e0s leis e regulamentos de controle de exporta\u00e7\u00e3o e san\u00e7\u00f5es econ\u00f4micas dos EUA e tamb\u00e9m pode estar sujeito \u00e0s leis do pa\u00eds onde voc\u00ea reside.<\/p>\n<h4 class=\"size-h6-regular compressed\">Representa\u00e7\u00f5es do usu\u00e1rio do site<\/h4>\n<p>Voc\u00ea declara, garante e concorda que: (a) voc\u00ea est\u00e1 autorizado a acessar e usar o Site; (b) todos os dados de qualquer tipo, instru\u00e7\u00f5es e informa\u00e7\u00f5es que voc\u00ea inserir no Site relacionados aos Servi\u00e7os ser\u00e3o precisos e completos; (c) voc\u00ea verificar\u00e1 e permanecer\u00e1 exclusivamente respons\u00e1vel por todas as instru\u00e7\u00f5es e informa\u00e7\u00f5es inseridas no Site relacionadas aos Servi\u00e7os; (d) voc\u00ea n\u00e3o far\u00e1 upload, transmitir\u00e1, distribuir\u00e1 ou publicar\u00e1 por meio do Site nenhum material que contenha v\u00edrus, worm ou outro componente nocivo ou que possa causar mau funcionamento do Site; e (e) voc\u00ea n\u00e3o descompilar\u00e1, far\u00e1 engenharia reversa, desmontar\u00e1 ou usar\u00e1 ou reproduzir\u00e1 ilegalmente nenhum software ou outro material protegido por direitos autorais ou marcas registradas, segredos comerciais ou outras informa\u00e7\u00f5es propriet\u00e1rias contidas no Site.<\/p>\n<h4 class=\"size-h6-regular compressed\">Seguran\u00e7a<\/h4>\n<p>A seguran\u00e7a das informa\u00e7\u00f5es transmitidas pela Internet nunca pode ser garantida. A RSA n\u00e3o \u00e9 respons\u00e1vel por qualquer intercepta\u00e7\u00e3o ou interrup\u00e7\u00e3o de qualquer comunica\u00e7\u00e3o pela Internet ou por altera\u00e7\u00f5es ou perdas de dados. Voc\u00ea \u00e9 respons\u00e1vel por manter a seguran\u00e7a de qualquer senha, e-mail ou outra forma de autentica\u00e7\u00e3o envolvida na obten\u00e7\u00e3o de acesso a \u00e1reas protegidas por senha ou seguras dos Sites da RSA. Para proteger o usu\u00e1rio e seus dados, a RSA poder\u00e1 reter uma c\u00f3pia de seus dados e suspender seu uso do Site, sem aviso pr\u00e9vio, enquanto se aguarda uma investiga\u00e7\u00e3o, caso haja suspeita de viola\u00e7\u00e3o de seguran\u00e7a. O acesso e o uso de \u00e1reas protegidas por senha e\/ou seguras do Site s\u00e3o restritos apenas a usu\u00e1rios autorizados. O acesso n\u00e3o autorizado a essas \u00e1reas \u00e9 proibido e pode levar a processos criminais.<\/p>\n<h4 class=\"size-h6-regular compressed\">Consentimento para uso de dados<\/h4>\n<p>O usu\u00e1rio concorda que a RSA pode coletar e usar dados t\u00e9cnicos e informa\u00e7\u00f5es relacionadas, incluindo, entre outros, informa\u00e7\u00f5es t\u00e9cnicas sobre seu dispositivo, sistema e software aplicativo e perif\u00e9ricos, que s\u00e3o coletados periodicamente para facilitar o fornecimento de atualiza\u00e7\u00f5es de software, suporte a produtos e outros servi\u00e7os ao usu\u00e1rio (se houver) relacionados ao software. A RSA pode usar essas informa\u00e7\u00f5es, desde que estejam em um formato que n\u00e3o o identifique pessoalmente, para melhorar seus produtos ou fornecer servi\u00e7os ou tecnologias ao usu\u00e1rio.<\/p>\n<h3>Conduta proibida<\/h3>\n<h4>Em geral<\/h4>\n<p>Os usu\u00e1rios s\u00f3 podem usar os Sites da RSA para os fins a que se destinam. Os usu\u00e1rios n\u00e3o devem usar os Sites da RSA para fins ilegais.<\/p>\n<h4>Conte\u00fado inapropriado<\/h4>\n<p>Os usu\u00e1rios n\u00e3o devem usar os Sites da RSA para transmitir, distribuir ou armazenar conte\u00fado: (a) que viole qualquer lei ou regulamento aplic\u00e1vel, incluindo leis ou regulamentos de exporta\u00e7\u00e3o ou criptografia; (b) que possa afetar negativamente os Sites da RSA ou outros clientes da RSA; ou (c) que possa expor a RSA a responsabilidade criminal ou civil.<\/p>\n<p>Os Usu\u00e1rios n\u00e3o devem usar os Sites da RSA para transmitir, distribuir ou armazenar material inapropriado, conforme razoavelmente determinado pela RSA, ou material obsceno (incluindo pornografia infantil), difamat\u00f3rio, calunioso, amea\u00e7ador, abusivo, odioso, racial ou etnicamente ofensivo, assediador, humilhante para outras pessoas (publicamente ou n\u00e3o) ou censur\u00e1vel. Para ser absolutamente claro, os Usu\u00e1rios n\u00e3o devem armazenar (permanente ou temporariamente), processar ou transmitir, por meio de qualquer um dos Sites da RSA, conte\u00fado pornogr\u00e1fico de qualquer tipo.<\/p>\n<p>Se os Usu\u00e1rios tomarem conhecimento de tal uso por qualquer pessoa, concordam em notificar a RSA.<\/p>\n<h4>Direitos de propriedade intelectual<\/h4>\n<p>O material acess\u00edvel por meio de ou contido nos Sites da RSA pode estar sujeito \u00e0 prote\u00e7\u00e3o de leis de privacidade, prote\u00e7\u00e3o de dados ou confidencialidade e pode conter direitos de propriedade intelectual de propriedade da RSA ou de terceiros. A propriedade intelectual pode incluir, mas n\u00e3o est\u00e1 limitada a, direitos autorais, patentes, marcas registradas, nomes comerciais, segredos comerciais ou outras informa\u00e7\u00f5es propriet\u00e1rias. Os usu\u00e1rios n\u00e3o devem usar os Sites da RSA de nenhuma maneira que possa infringir, diluir, apropriar-se indevidamente, violar ou de outra forma violar qualquer um desses direitos ou leis. Os usu\u00e1rios s\u00e3o respons\u00e1veis por garantir que possuem todos os direitos e licen\u00e7as necess\u00e1rios para todo o conte\u00fado que colocam nos Sites da RSA. Os usu\u00e1rios devem indenizar totalmente a RSA em rela\u00e7\u00e3o a quaisquer reivindica\u00e7\u00f5es de terceiros contra a RSA com base em uma alega\u00e7\u00e3o de que o usu\u00e1rio n\u00e3o cumpriu suas obriga\u00e7\u00f5es nos termos deste par\u00e1grafo.<\/p>\n<h4>Conte\u00fado e conduta maliciosos<\/h4>\n<p>Os usu\u00e1rios n\u00e3o devem usar os Sites da RSA para transmitir, distribuir ou armazenar material que possa ser prejudicial ou interferir nos sites da RSA ou em redes, sistemas, servi\u00e7os ou sites de terceiros. O conte\u00fado malicioso inclui, mas n\u00e3o se limita a, v\u00edrus, worms e cavalos de Troia.<\/p>\n<p>Os usu\u00e1rios n\u00e3o devem usar os Sites da RSA para realizar atividades que possam ser prejudiciais ou interferir nos Sites da RSA ou em redes, sistemas, servi\u00e7os ou sites da Web de terceiros, incluindo, entre outros, flooding, mail bombing ou ataques de nega\u00e7\u00e3o de servi\u00e7o. Os usu\u00e1rios est\u00e3o proibidos de violar ou tentar violar a seguran\u00e7a dos Sites da RSA ou dos computadores, contas ou redes de terceiros. Os usu\u00e1rios tamb\u00e9m est\u00e3o proibidos de realizar qualquer atividade considerada precursora de tentativas de viola\u00e7\u00f5es de seguran\u00e7a, incluindo, entre outras, qualquer forma de varredura, sondagem ou outra atividade de teste ou coleta de informa\u00e7\u00f5es. Atividades inadequadas podem resultar em responsabilidade civil ou criminal. A RSA poder\u00e1 investigar tais atividades e poder\u00e1 envolver e cooperar com as autoridades policiais para processar os Usu\u00e1rios envolvidos em tais atividades.<\/p>\n<h4>Conte\u00fado fraudulento e enganoso<\/h4>\n<p>Os usu\u00e1rios n\u00e3o devem usar os Sites da RSA para transmitir ou distribuir material que contenha ofertas fraudulentas de bens ou servi\u00e7os, ou qualquer material publicit\u00e1rio, promocional ou outro que contenha declara\u00e7\u00f5es, reivindica\u00e7\u00f5es ou representa\u00e7\u00f5es falsas, enganosas ou enganosas, ou que n\u00e3o esteja em conformidade com qualquer lei de publicidade aplic\u00e1vel ou pr\u00e1tica comercial padr\u00e3o. Os usu\u00e1rios n\u00e3o devem usar os Sites da RSA para mascarar sua verdadeira identidade ou para fingir ser algu\u00e9m ou algo que n\u00e3o s\u00e3o.<\/p>\n<h4>Coleta de informa\u00e7\u00f5es pessoais<\/h4>\n<p>Os usu\u00e1rios reconhecem e concordam que n\u00e3o t\u00eam permiss\u00e3o para usar nenhuma informa\u00e7\u00e3o de identifica\u00e7\u00e3o pessoal ou dados pessoais e concordam em n\u00e3o copiar, transferir ou distribuir nenhuma informa\u00e7\u00e3o de identifica\u00e7\u00e3o pessoal que n\u00e3o esteja em conformidade com todas as leis e conforme permitido em rela\u00e7\u00e3o aos servi\u00e7os. <\/p>\n<h4>E-mail e mensagens n\u00e3o solicitadas<\/h4>\n<p>Os Usu\u00e1rios n\u00e3o devem usar os Sites da RSA para transmitir mensagens de e-mail n\u00e3o solicitadas, incluindo, sem limita\u00e7\u00e3o, e-mails em massa n\u00e3o solicitados (\"spam\") ou e-mails destinados a assediar ou incomodar outras pessoas. Al\u00e9m disso, os Usu\u00e1rios n\u00e3o devem usar o servi\u00e7o de outro provedor para enviar spam para promover um site hospedado ou conectado aos Sites da RSA.<\/p>\n<h4>Responsabilidade pelo conte\u00fado<\/h4>\n<p>A RSA n\u00e3o \u00e9 respons\u00e1vel por qualquer conte\u00fado fornecido pelo usu\u00e1rio ou conte\u00fado que o usu\u00e1rio possa acessar nos Sites da RSA ou por meio deles. A RSA n\u00e3o \u00e9 obrigada a monitorar ou exercer controle editorial sobre esse conte\u00fado. Se a RSA tomar conhecimento de que qualquer conte\u00fado pode violar os Termos, expor a RSA a responsabilidade civil ou criminal, ou ambos, a RSA poder\u00e1 bloquear o acesso a esse conte\u00fado e suspender ou encerrar o fornecimento dos Sites da RSA a qualquer Usu\u00e1rio que crie, armazene ou divulgue esse material. A RSA tamb\u00e9m pode cooperar com as autoridades legais e terceiros em qualquer investiga\u00e7\u00e3o de suposta irregularidade.<\/p>\n<h4>Suspens\u00e3o e rescis\u00e3o<\/h4>\n<p>Se a RSA determinar que algum Usu\u00e1rio violou qualquer parte dos Termos, a RSA poder\u00e1 encerrar o uso do Site pelos Usu\u00e1rios. A RSA suspender\u00e1 o servi\u00e7o por viola\u00e7\u00e3o dos Termos na base mais limitada que a RSA determinar ser razoavelmente pr\u00e1tica sob as circunst\u00e2ncias para tratar da viola\u00e7\u00e3o subjacente. A RSA tentar\u00e1 notificar o usu\u00e1rio antes de suspender o servi\u00e7o por viola\u00e7\u00e3o dos Termos (que pode ser por e-mail ou qualquer outra notifica\u00e7\u00e3o). No entanto, a RSA pode suspender o servi\u00e7o sem aviso pr\u00e9vio se a RSA tomar conhecimento de uma viola\u00e7\u00e3o dos Termos ou de qualquer lei ou regulamento aplic\u00e1vel que exponha a RSA a responsabilidade criminal ou civil, ou que exponha a RSA ou qualquer propriedade de terceiros a danos. Os danos podem incluir, mas n\u00e3o se limitam a, risco de ter um ou mais endere\u00e7os IP colocados em listas negras. A RSA pode tomar qualquer outra medida que considere apropriada de acordo com as circunst\u00e2ncias para eliminar ou impedir viola\u00e7\u00f5es repetidas. A RSA n\u00e3o se responsabiliza por nenhum tipo de dano que os Usu\u00e1rios ou terceiros possam sofrer em decorr\u00eancia, no todo ou em parte, do exerc\u00edcio dos direitos da RSA nos termos dos Termos. Esta exclus\u00e3o de responsabilidade n\u00e3o inclui a responsabilidade da RSA por morte ou danos pessoais causados por sua neglig\u00eancia, ou qualquer outra responsabilidade que a RSA n\u00e3o possa excluir ou limitar por lei.<\/p>\n<h4>Isen\u00e7\u00f5es de responsabilidade<\/h4>\n<p>O usu\u00e1rio concorda em assumir total responsabilidade pelo uso do Site. A RSA fornece o Site e todo o Conte\u00fado da RSA \"no estado em que se encontram\" e \"conforme dispon\u00edveis\". Especificamente, a RSA:<\/p>\n<ul>\n<li>N\u00e3o faz nenhuma representa\u00e7\u00e3o ou garantia de qualquer tipo;<\/li>\n<li>Isenta-se de todas as garantias, incluindo garantias de comercializa\u00e7\u00e3o, adequa\u00e7\u00e3o, precis\u00e3o, n\u00e3o viola\u00e7\u00e3o ou opera\u00e7\u00e3o; e<\/li>\n<li>N\u00e3o garante que o Site e o Conte\u00fado da RSA estar\u00e3o livres de erros ou defeitos.<\/li>\n<li>N\u00e3o est\u00e1 fornecendo consultoria jur\u00eddica ou tribut\u00e1ria. Consulte um consultor jur\u00eddico ou tribut\u00e1rio profissional para obter orienta\u00e7\u00e3o sobre sua situa\u00e7\u00e3o espec\u00edfica.<\/li>\n<\/ul>\n<h4><strong>Limita\u00e7\u00e3o de responsabilidade<\/strong><\/h4>\n<p><strong>A RSA n\u00e3o \u00e9 respons\u00e1vel, sob nenhuma teoria legal (incluindo neglig\u00eancia), por qualquer tipo de dano, mesmo que a RSA soubesse da possibilidade de tais danos. A RSA n\u00e3o se responsabiliza por perda de dados ou lucros decorrentes de seu uso ou incapacidade de usar o Site ou o Conte\u00fado da RSA. Se o uso do Conte\u00fado da RSA resultar na necessidade de manuten\u00e7\u00e3o, reparo ou corre\u00e7\u00e3o de quaisquer produtos ou dados, o usu\u00e1rio pagar\u00e1 por esses reparos. Algumas jurisdi\u00e7\u00f5es restringem a exclus\u00e3o ou limita\u00e7\u00e3o de determinados danos, portanto, esta disposi\u00e7\u00e3o pode n\u00e3o se aplicar ao seu caso.<\/strong><\/p>\n<h4>Indeniza\u00e7\u00e3o<\/h4>\n<p>O usu\u00e1rio concorda em indenizar, defender e isentar a RSA e seus agentes, funcion\u00e1rios e licenciadores de todas as reivindica\u00e7\u00f5es e despesas de terceiros, inclusive honor\u00e1rios advocat\u00edcios razo\u00e1veis, relacionadas de alguma forma ao uso do Site ou \u00e0 viola\u00e7\u00e3o destes Termos.<\/p>\n<h4>Diversos<\/h4>\n<ul>\n<li>Estes Termos n\u00e3o criam nenhuma rela\u00e7\u00e3o jur\u00eddica entre voc\u00ea e a RSA.<\/li>\n<li>O fato de a RSA n\u00e3o fazer valer um direito n\u00e3o significa que a RSA tenha renunciado a esse direito.<\/li>\n<li>Se uma corte ou outro tribunal considerar qualquer disposi\u00e7\u00e3o destes Termos inexequ\u00edvel, a RSA alterar\u00e1 essa disposi\u00e7\u00e3o apenas na medida necess\u00e1ria para torn\u00e1-la exequ\u00edvel. Os demais termos permanecer\u00e3o em pleno vigor e efeito.<\/li>\n<li>Qualquer interpreta\u00e7\u00e3o destes Termos dever\u00e1 considerar o significado justo, e as ambiguidades n\u00e3o devem ser interpretadas a favor ou contra qualquer parte.<\/li>\n<li>A RSA poder\u00e1 ceder seus direitos sob estes Termos, mas o usu\u00e1rio n\u00e3o poder\u00e1 faz\u00ea-lo.<\/li>\n<li>Estes Termos, juntamente com quaisquer outros termos com os quais voc\u00ea concorde ao usar o Site, constituem o acordo integral entre a RSA e voc\u00ea sobre o uso deste Site.<\/li>\n<li>Os t\u00edtulos s\u00e3o apenas para refer\u00eancia.<\/li>\n<li>Estes Termos substituem quaisquer acordos anteriores com a RSA sobre o uso deste Site e seu conte\u00fado.<\/li>\n<li>As subsidi\u00e1rias diretas e indiretas da RSA s\u00e3o terceiros benefici\u00e1rios destes Termos.<\/li>\n<\/ul>\n<h4>Lei aplic\u00e1vel; resolu\u00e7\u00e3o de disputas<\/h4>\n<p class=\"translation-block\">Voc\u00ea concorda que as leis da Comunidade de Massachusetts reger\u00e3o qualquer reivindica\u00e7\u00e3o ou lit\u00edgio relacionado a estes Termos, ao Site, ao Conte\u00fado da RSA, ao seu acesso e uso do Site ou a qualquer combina\u00e7\u00e3o desses itens (o \"<b>Disputo<\/b>\"), sem levar em conta os princ\u00edpios de conflitos de leis de Massachusetts. Antes que o usu\u00e1rio ou a RSA entrem com uma a\u00e7\u00e3o judicial referente a um Lit\u00edgio, o usu\u00e1rio e a RSA tentar\u00e3o resolver o Lit\u00edgio por meio de negocia\u00e7\u00e3o ou media\u00e7\u00e3o usando um mediador mutuamente aceit\u00e1vel. Voc\u00ea e a RSA tratar\u00e3o a exist\u00eancia ou os resultados de qualquer negocia\u00e7\u00e3o ou media\u00e7\u00e3o como confidenciais. Se as partes n\u00e3o conseguirem resolver a Disputa no prazo de trinta dias ap\u00f3s a notifica\u00e7\u00e3o da Disputa \u00e0 outra parte, as partes estar\u00e3o livres para buscar todos os recursos dispon\u00edveis por lei ou equidade. N\u00e3o obstante o acima exposto, qualquer uma das partes tem o direito de buscar uma ordem de restri\u00e7\u00e3o tempor\u00e1ria, liminar ou outra medida equitativa de um tribunal de jurisdi\u00e7\u00e3o competente para preservar o status quo, evitar danos irrepar\u00e1veis, evitar a expira\u00e7\u00e3o de quaisquer per\u00edodos de limita\u00e7\u00e3o aplic\u00e1veis ou preservar uma posi\u00e7\u00e3o superior em rela\u00e7\u00e3o a outros credores.<\/p>\n<h3>Fale Conosco<\/h3>\n<p>A RSA \u00e9 propriet\u00e1ria deste Site. Se tiver alguma d\u00favida sobre a coleta ou o uso de informa\u00e7\u00f5es pessoais pela RSA, entre em contato conosco pelo e-mail ou escreva para:<\/p>\n<p>RSA Security LLC<br \/>\nAten\u00e7\u00e3o: Departamento Jur\u00eddico - Privacidade<br \/>\n176 Middlesex Turnpike<br \/>\nBedford, MA 01730 EUA<br \/>\n<a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a><\/p>\n<p>Os residentes da Calif\u00f3rnia tamb\u00e9m podem enviar reclama\u00e7\u00f5es para a Unidade de Assist\u00eancia a Reclama\u00e7\u00f5es da Divis\u00e3o de Servi\u00e7os ao Consumidor do Departamento de Assuntos do Consumidor da Calif\u00f3rnia, pelo correio, no endere\u00e7o 1625 North Market Blvd., Sacramento, CA 95834, ou pelo telefone (916) 445-1254 ou (800) 952-5210.<\/p>\n<p><strong>Data de vig\u00eancia: 27 de julho de 2022<\/strong><\/p>\n<p>Termos de uso anteriores:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-sept-2020\/\">Setembro de 2020<\/a><\/li>\n<\/ul>\n<p><strong>\u00a92022 RSA Security LLC ou suas afiliadas. Todos os direitos reservados. O logotipo da RSA Conference, RSA e outras marcas comerciais s\u00e3o marcas comerciais da RSA Security LLC ou de suas afiliadas. Outras marcas comerciais podem ser marcas comerciais de seus respectivos propriet\u00e1rios.<br \/>\n<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Sobre estes Termos de Uso Estes termos (\u201cTermos\u201d) s\u00e3o um acordo legal entre voc\u00ea e a RSA Security LLC e suas afiliadas (\u201cRSA\u201d). Os Termos controlam seu uso e acesso aos sites e informa\u00e7\u00f5es on-line da RSA (os \u201cSites\u201d ou \u201cSite\u201d). Ao usar os Sites da RSA, voc\u00ea concorda com estes Termos. A RSA pode revisar estes Termos a qualquer momento... <a href=\"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/\">Continua\u00e7\u00e3o<\/a><\/p>","protected":false},"author":2,"featured_media":0,"parent":227,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-policy.blade.php","meta":{"_acf_changed":false,"_searchwp_excluded":"","inline_featured_image":false,"footnotes":""},"class_list":["post-28813","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terms of Use - July 2022 - RSA<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms of Use - July 2022 - RSA\" \/>\n<meta property=\"og:description\" content=\"About These Terms of Use These terms (\u201cTerms\u201d) are a legal agreement between you and RSA Security LLC and its affiliates (\u201cRSA\u201d). The Terms control your use and access to RSA\u2019s websites and online information (the \u201cSites\u201d or \u201cSite\u201d). By using RSA\u2019s Sites, you agree to these Terms. RSA may revise these Terms at any &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"RSA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-02T16:49:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/pt_br\\\/terms-of-use\\\/terms-of-use-july-2022\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/pt_br\\\/terms-of-use\\\/terms-of-use-july-2022\\\/\",\"name\":\"Terms of Use - July 2022 - RSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\"},\"datePublished\":\"2024-02-01T22:37:06+00:00\",\"dateModified\":\"2026-04-02T16:49:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/pt_br\\\/terms-of-use\\\/terms-of-use-july-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rsa.com\\\/pt_br\\\/terms-of-use\\\/terms-of-use-july-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/pt_br\\\/terms-of-use\\\/terms-of-use-july-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/pt_br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms of Use\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/pt_br\\\/terms-of-use\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Terms of Use &#8211; July 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"name\":\"RSA\",\"description\":\"Cybersecurity and Digital Risk Management Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rsa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\",\"name\":\"RSA\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"width\":2880,\"height\":1020,\"caption\":\"RSA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termos de uso - julho de 2022 - RSA","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Terms of Use - July 2022 - RSA","og_description":"About These Terms of Use These terms (\u201cTerms\u201d) are a legal agreement between you and RSA Security LLC and its affiliates (\u201cRSA\u201d). The Terms control your use and access to RSA\u2019s websites and online information (the \u201cSites\u201d or \u201cSite\u201d). By using RSA\u2019s Sites, you agree to these Terms. RSA may revise these Terms at any &hellip; Continued","og_url":"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/","og_site_name":"RSA","article_modified_time":"2026-04-02T16:49:35+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/","url":"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/","name":"Termos de uso - julho de 2022 - RSA","isPartOf":{"@id":"https:\/\/www.rsa.com\/#website"},"datePublished":"2024-02-01T22:37:06+00:00","dateModified":"2026-04-02T16:49:35+00:00","breadcrumb":{"@id":"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/terms-of-use-july-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rsa.com\/pt_br\/"},{"@type":"ListItem","position":2,"name":"Terms of Use","item":"https:\/\/www.rsa.com\/pt_br\/terms-of-use\/"},{"@type":"ListItem","position":3,"name":"Terms of Use &#8211; July 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.rsa.com\/#website","url":"https:\/\/www.rsa.com\/","name":"RSA","description":"Solu\u00e7\u00f5es de seguran\u00e7a cibern\u00e9tica e gerenciamento de riscos digitais","publisher":{"@id":"https:\/\/www.rsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.rsa.com\/#organization","name":"RSA","url":"https:\/\/www.rsa.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","width":2880,"height":1020,"caption":"RSA"},"image":{"@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/pages\/28813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/comments?post=28813"}],"version-history":[{"count":3,"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/pages\/28813\/revisions"}],"predecessor-version":[{"id":28816,"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/pages\/28813\/revisions\/28816"}],"up":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/pages\/227"}],"wp:attachment":[{"href":"https:\/\/www.rsa.com\/pt_br\/wp-json\/wp\/v2\/media?parent=28813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}