{"id":2245,"date":"2021-09-16T12:55:54","date_gmt":"2021-09-16T19:55:54","guid":{"rendered":"https:\/\/live-rsa-hub.pantheonsite.io\/resources\/\/"},"modified":"2025-11-17T12:01:38","modified_gmt":"2025-11-17T17:01:38","slug":"mfa-for-salesforce","status":"publish","type":"resources_post_type","link":"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/","title":{"rendered":"Salesforce\u306e\u305f\u3081\u306e\u6700\u65b0\u306e\u591a\u8981\u7d20\u8a8d\u8a3c"},"content":{"rendered":"","protected":false},"featured_media":17721,"template":"","class_list":["post-2245","resources_post_type","type-resources_post_type","status-publish","has-post-thumbnail","hentry","resource_type-datasheets"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modern Multi-Factor Authentication for Salesforce - RSA<\/title>\n<meta name=\"description\" content=\"RSA SecurID\u00ae Access provides security when a user accesses the native Salesforce login with multi-factor authentication (MFA).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modern Multi-Factor Authentication for Salesforce\" \/>\n<meta property=\"og:description\" content=\"RSA SecurID\u00ae Access provides security when a user accesses the native Salesforce login with multi-factor authentication (MFA).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/\" \/>\n<meta property=\"og:site_name\" content=\"RSA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T17:01:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Modern Multi-Factor Authentication for Salesforce\" \/>\n<meta name=\"twitter:description\" content=\"RSA SecurID\u00ae Access provides security when a user accesses the native Salesforce login with multi-factor authentication (MFA).\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/ja\\\/resources\\\/datasheets\\\/mfa-for-salesforce\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/ja\\\/resources\\\/datasheets\\\/mfa-for-salesforce\\\/\",\"name\":\"Modern Multi-Factor Authentication for Salesforce - RSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/resources\\\/datasheets\\\/mfa-for-salesforce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/resources\\\/datasheets\\\/mfa-for-salesforce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/RSA_Data_sheet_Thumbnail.jpg\",\"datePublished\":\"2021-09-16T19:55:54+00:00\",\"dateModified\":\"2025-11-17T17:01:38+00:00\",\"description\":\"RSA SecurID\u00ae Access provides security when a user accesses the native Salesforce login with multi-factor authentication (MFA).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/ja\\\/resources\\\/datasheets\\\/mfa-for-salesforce\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rsa.com\\\/ja\\\/resources\\\/datasheets\\\/mfa-for-salesforce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/resources\\\/datasheets\\\/mfa-for-salesforce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/RSA_Data_sheet_Thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/RSA_Data_sheet_Thumbnail.jpg\",\"width\":830,\"height\":644},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/ja\\\/resources\\\/datasheets\\\/mfa-for-salesforce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/ja\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modern Multi-Factor Authentication for Salesforce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"name\":\"RSA\",\"description\":\"Cybersecurity and Digital Risk Management Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rsa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\",\"name\":\"RSA\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"width\":2880,\"height\":1020,\"caption\":\"RSA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"knowsAbout\":[\"multi-factor authentication\",\"passwordless authentication\",\"identity and access management\",\"identity governance and administration\",\"zero trust\",\"threat detection and response\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salesforce\u306e\u305f\u3081\u306e\u6700\u65b0\u306e\u591a\u8981\u7d20\u8a8d\u8a3c - RSA","description":"RSA SecurID\u00ae Access \u306f\u3001\u30e6\u30fc\u30b6\u304c\u591a\u8981\u7d20\u8a8d\u8a3c (MFA) \u3092\u4f7f\u7528\u3057\u3066 Salesforce \u30cd\u30a4\u30c6\u30a3\u30d6\u30ed\u30b0\u30a4\u30f3\u306b\u30a2\u30af\u30bb\u30b9\u3059\u308b\u969b\u306e\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u3092\u63d0\u4f9b\u3057\u307e\u3059\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/","og_locale":"ja_JP","og_type":"article","og_title":"Modern Multi-Factor Authentication for Salesforce","og_description":"RSA SecurID\u00ae Access provides security when a user accesses the native Salesforce login with multi-factor authentication (MFA).","og_url":"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/","og_site_name":"RSA","article_modified_time":"2025-11-17T17:01:38+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Modern Multi-Factor Authentication for Salesforce","twitter_description":"RSA SecurID\u00ae Access provides security when a user accesses the native Salesforce login with multi-factor authentication (MFA).","twitter_image":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/","url":"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/","name":"Salesforce\u306e\u305f\u3081\u306e\u6700\u65b0\u306e\u591a\u8981\u7d20\u8a8d\u8a3c - RSA","isPartOf":{"@id":"https:\/\/www.rsa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-salesforce\/#primaryimage"},"image":{"@id":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-salesforce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/RSA_Data_sheet_Thumbnail.jpg","datePublished":"2021-09-16T19:55:54+00:00","dateModified":"2025-11-17T17:01:38+00:00","description":"RSA SecurID\u00ae Access \u306f\u3001\u30e6\u30fc\u30b6\u304c\u591a\u8981\u7d20\u8a8d\u8a3c (MFA) \u3092\u4f7f\u7528\u3057\u3066 Salesforce \u30cd\u30a4\u30c6\u30a3\u30d6\u30ed\u30b0\u30a4\u30f3\u306b\u30a2\u30af\u30bb\u30b9\u3059\u308b\u969b\u306e\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u3092\u63d0\u4f9b\u3057\u307e\u3059\u3002","breadcrumb":{"@id":"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-salesforce\/#primaryimage","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/RSA_Data_sheet_Thumbnail.jpg","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/RSA_Data_sheet_Thumbnail.jpg","width":830,"height":644},{"@type":"BreadcrumbList","@id":"https:\/\/www.rsa.com\/ja\/resources\/datasheets\/mfa-for-salesforce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rsa.com\/ja\/"},{"@type":"ListItem","position":2,"name":"Modern Multi-Factor Authentication for Salesforce"}]},{"@type":"WebSite","@id":"https:\/\/www.rsa.com\/#website","url":"https:\/\/www.rsa.com\/","name":"RSA","description":"\u30b5\u30a4\u30d0\u30fc\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u3068\u30c7\u30b8\u30bf\u30eb\u30ea\u30b9\u30af\u7ba1\u7406\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3","publisher":{"@id":"https:\/\/www.rsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/www.rsa.com\/#organization","name":"RSA","url":"https:\/\/www.rsa.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","width":2880,"height":1020,"caption":"RSA"},"image":{"@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/"},"knowsAbout":["multi-factor authentication","passwordless authentication","identity and access management","identity governance and administration","zero trust","threat detection and response"]}]}},"_links":{"self":[{"href":"https:\/\/www.rsa.com\/ja\/wp-json\/wp\/v2\/resources_post_type\/2245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rsa.com\/ja\/wp-json\/wp\/v2\/resources_post_type"}],"about":[{"href":"https:\/\/www.rsa.com\/ja\/wp-json\/wp\/v2\/types\/resources_post_type"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/ja\/wp-json\/wp\/v2\/media\/17721"}],"wp:attachment":[{"href":"https:\/\/www.rsa.com\/ja\/wp-json\/wp\/v2\/media?parent=2245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}