{"id":2771,"date":"2022-05-31T16:50:53","date_gmt":"2022-05-31T23:50:53","guid":{"rendered":"https:\/\/live-rsa-hub.pantheonsite.io\/?page_id=2771"},"modified":"2025-10-15T16:34:56","modified_gmt":"2025-10-15T20:34:56","slug":"customer-success","status":"publish","type":"page","link":"https:\/\/www.rsa.com\/it\/customer-success\/","title":{"rendered":"Successo del cliente"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-t14-customer-success.blade.php","meta":{"_acf_changed":false,"_searchwp_excluded":"","inline_featured_image":false,"footnotes":""},"class_list":["post-2771","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact RSA Customer Support and Sales<\/title>\n<meta name=\"description\" content=\"Unveil success with a roadmap designed for your journey. Ensure you achieve your business goals and maximize value with your products.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rsa.com\/it\/customer-success\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Customer Success\" \/>\n<meta property=\"og:description\" content=\"RSA is committed to sustainable customer success, with a customer engagement model that provides support for success at every stage of the experience.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rsa.com\/it\/customer-success\/\" \/>\n<meta property=\"og:site_name\" content=\"RSA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T20:34:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Customer Success\" \/>\n<meta name=\"twitter:description\" content=\"RSA is committed to sustainable customer success, with a customer engagement model that provides support for success at every stage of the experience.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/customer-success\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/customer-success\\\/\",\"name\":\"Contact RSA Customer Support and Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\"},\"datePublished\":\"2022-05-31T23:50:53+00:00\",\"dateModified\":\"2025-10-15T20:34:56+00:00\",\"description\":\"Unveil success with a roadmap designed for your journey. Ensure you achieve your business goals and maximize value with your products.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/customer-success\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rsa.com\\\/it\\\/customer-success\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/customer-success\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Customer Success\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"name\":\"RSA\",\"description\":\"Cybersecurity and Digital Risk Management Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rsa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\",\"name\":\"RSA\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"width\":2880,\"height\":1020,\"caption\":\"RSA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contattare l'assistenza clienti e le vendite di RSA","description":"Svelate il successo con una roadmap progettata per il vostro viaggio. Assicuratevi di raggiungere gli obiettivi aziendali e di massimizzare il valore dei vostri prodotti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rsa.com\/it\/customer-success\/","og_locale":"it_IT","og_type":"article","og_title":"Customer Success","og_description":"RSA is committed to sustainable customer success, with a customer engagement model that provides support for success at every stage of the experience.","og_url":"https:\/\/www.rsa.com\/it\/customer-success\/","og_site_name":"RSA","article_modified_time":"2025-10-15T20:34:56+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Customer Success","twitter_description":"RSA is committed to sustainable customer success, with a customer engagement model that provides support for success at every stage of the experience.","twitter_image":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rsa.com\/it\/customer-success\/","url":"https:\/\/www.rsa.com\/it\/customer-success\/","name":"Contattare l'assistenza clienti e le vendite di RSA","isPartOf":{"@id":"https:\/\/www.rsa.com\/#website"},"datePublished":"2022-05-31T23:50:53+00:00","dateModified":"2025-10-15T20:34:56+00:00","description":"Svelate il successo con una roadmap progettata per il vostro viaggio. Assicuratevi di raggiungere gli obiettivi aziendali e di massimizzare il valore dei vostri prodotti.","breadcrumb":{"@id":"https:\/\/www.rsa.com\/it\/customer-success\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rsa.com\/it\/customer-success\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rsa.com\/it\/customer-success\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rsa.com\/it\/"},{"@type":"ListItem","position":2,"name":"Customer Success"}]},{"@type":"WebSite","@id":"https:\/\/www.rsa.com\/#website","url":"https:\/\/www.rsa.com\/","name":"RSA","description":"Soluzioni di cybersecurity e di gestione del rischio digitale","publisher":{"@id":"https:\/\/www.rsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rsa.com\/#organization","name":"RSA","url":"https:\/\/www.rsa.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","width":2880,"height":1020,"caption":"RSA"},"image":{"@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages\/2771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/comments?post=2771"}],"version-history":[{"count":23,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages\/2771\/revisions"}],"predecessor-version":[{"id":35406,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages\/2771\/revisions\/35406"}],"wp:attachment":[{"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/media?parent=2771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}