{"id":24430,"date":"2023-01-12T15:33:49","date_gmt":"2023-01-12T20:33:49","guid":{"rendered":"https:\/\/www.rsa.com\/?page_id=24430"},"modified":"2025-02-07T15:58:34","modified_gmt":"2025-02-07T20:58:34","slug":"privacy-policy-july-2022","status":"publish","type":"page","link":"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/","title":{"rendered":"Informativa sulla privacy - Luglio 2022"},"content":{"rendered":"<h4>Introduzione<\/h4>\n<p>La vostra privacy \u00e8 importante per RSA Security LLC e per questo abbiamo sviluppato questa Informativa sulla privacy che illustra le nostre prassi in materia di trattamento, raccolta, utilizzo e condivisione dei vostri dati personali, nonch\u00e9 i vostri diritti in materia di privacy ai sensi di alcune leggi sulla privacy. Possiamo fornire ulteriori informazioni sulla privacy dei dati utilizzando una o pi\u00f9 informative supplementari sulla privacy. <\/p>\n<p>Nella presente Informativa sulla privacy, \"RSA\", \"nostro\", \"noi\" o \"ci\" si riferisce a RSA Security LLC e alle sue affiliate coinvolte nella raccolta, nell'utilizzo, nella condivisione o nell'elaborazione dei vostri dati personali. <\/p>\n<p>RSA si impegna a proteggere la privacy e la sicurezza di tutti i dati personali che raccogliamo quando accedete, utilizzate o interagite con noi attraverso i nostri siti web, le comunicazioni di marketing e i dati personali che elaboriamo per fornire servizi ai nostri clienti. Riceviamo un numero limitato di dati personali dai nostri clienti.<\/p>\n<p>La presente Informativa sulla privacy non si applica a:<\/p>\n<ul>\n<li class=\"translation-block\">clienti con un <a href=\"https:\/\/www.rsa.com\/it\/standard-form-agreements\/\" target=\"_self\">Data Processing Addendum (DPA)<\/a> in atto, che descrive come trattiamo i dati personali dei nostri clienti.<\/li>\n<li>dati non personali, tra cui dati anonimi e aggregati; e,<\/li>\n<li>informazioni relative ai nostri candidati.<\/li>\n<\/ul>\n<p>La presente Informativa sulla privacy si applica nella misura in cui RSA tratta i dati dell'utente in qualit\u00e0 di responsabile del trattamento. Non si applica quando RSA tratta i dati dell'utente in qualit\u00e0 di responsabile del trattamento dei dati per conto dei clienti. Inoltre, non si applica alle informazioni aggregate, de-identificate o pseudonimizzate.<\/p>\n<h4>1. Informazioni raccolte<\/h4>\n<p>Raccogliamo \"dati personali\", ovvero informazioni relative a un individuo che pu\u00f2 essere identificato, direttamente o indirettamente, con riferimento a un identificatore, come un nome, un numero di identificazione, dati di localizzazione o un identificatore online.<\/p>\n<h5>1.1 Informazioni raccolte dall'utente<\/h5>\n<p>I tipi di informazioni che raccogliamo su di voi dipendono dall'uso che fate dei nostri prodotti e servizi e dalle modalit\u00e0 con cui interagite con noi, e comprendono anche informazioni ottenute da terzi. Queste possono includere informazioni su:<\/p>\n<ul>\n<li>Informazioni di contatto, come nome, paese, indirizzo e-mail, numero di telefono, fuso orario, indirizzo postale.<\/li>\n<li>Informazioni di carattere commerciale, quali il titolo di lavoro, il livello di inquadramento, il ruolo\/funzione lavorativa e altre informazioni di carattere commerciale o aziendale.<\/li>\n<li>Informazioni sugli interessi, come i prodotti o i servizi acquistati, le attivit\u00e0 associate al vostro account e le vostre preferenze.<\/li>\n<li>Informazioni fornite dall'utente nei nostri moduli web (i moduli che l'utente sceglie di compilare indicano se le informazioni richieste sono obbligatorie o volontarie).<\/li>\n<li>I cookie e le informazioni di tracciamento durante l'interazione con i nostri siti web includono il tipo di browser, l'indirizzo IP, il Pixel ID, il numero di identificazione univoco del dispositivo, il sistema operativo, il tipo di dispositivo e le informazioni sulla versione, le impostazioni della lingua, le pagine web visualizzate, il tempo trascorso sulle pagine, l'URL del sito web che ha rimandato l'utente alle nostre pagine, le informazioni geografiche derivate dall'indirizzo IP, altre informazioni tecniche e qualsiasi collegamento ipertestuale o pubblicit\u00e0 selezionata dall'utente.<\/li>\n<li>Informazioni di riferimento del browser sui siti web che vi hanno portato a visitarci.<\/li>\n<li>Rapporti di errore e informazioni sulle prestazioni dei prodotti e su eventuali problemi riscontrati, compresi i rapporti di errore.<\/li>\n<li>Informazioni sul consumo di contenuti sui contenuti multimediali (ad es. TV, app e giochi) a cui accedete attraverso le nostre offerte.<\/li>\n<li>Informazioni di feedback e valutazioni fornite dall'utente, come ad esempio i feedback dei sondaggi dei clienti e le recensioni dei prodotti scritte dall'utente, a meno che non siano anonime.<\/li>\n<li>Le informazioni provenienti da fonti terze possono includere dati personali a integrazione delle informazioni che abbiamo raccolto su di voi.<\/li>\n<li>Siti web e link di terze parti. Possiamo fornire link ad altri siti web che, se cliccati, possono raccogliere informazioni sull'utente e indirizzarlo a tali siti. Le pratiche di informazione dei siti web di terzi collegati al nostro sito sono coperte dalle politiche\/dichiarazioni sulla privacy dei terzi stessi e vi invitiamo a leggerle.<\/li>\n<li>Credenziali quali suggerimenti di password e informazioni di sicurezza simili utilizzate per l'autenticazione e l'accesso a MyAccount.<\/li>\n<li>Informazioni demografiche come l'et\u00e0, il sesso, il paese, gli interessi e le preferenze dell'utente.<\/li>\n<li>Informazioni di pagamento per elaborare i pagamenti, come il numero del vostro strumento di pagamento (ad esempio il numero di una carta di credito) e il codice di sicurezza associato al vostro strumento di pagamento.<\/li>\n<li>Informazioni sulla risoluzione dei problemi e sull'assistenza quando si contatta RSA per il supporto tecnico o i servizi di assistenza clienti, le conversazioni telefoniche o le sessioni di chat con i nostri rappresentanti possono essere monitorate e registrate.<\/li>\n<li>Informazioni necessarie per la fornitura di servizi all'utente.<\/li>\n<li>Qualsiasi altro dato personale che decidiate di condividere con noi.<\/li>\n<\/ul>\n<h5>1.2 Categorie speciali di dati personali<\/h5>\n<p>Non raccogliamo intenzionalmente categorie speciali di dati personali, che comprendono informazioni sensibili quali:<\/p>\n<ul>\n<li>Origine razziale o etnica<\/li>\n<li>Opinioni politiche<\/li>\n<li>Credenze religiose o filosofiche<\/li>\n<li>Iscrizione a un sindacato<\/li>\n<li>Dati genetici<\/li>\n<li>Dati biometrici<\/li>\n<li>Salute o condizione fisica o mentale<\/li>\n<li>Vita sessuale o orientamento sessuale<\/li>\n<\/ul>\n<p>L'utente non \u00e8 tenuto a fornire, n\u00e9 a divulgare, queste informazioni, in quanto non \u00e8 nostra intenzione trattare dati sensibili. Tuttavia, se li rivelate, riconoscete di acconsentire alla raccolta e all'elaborazione di queste categorie speciali di dati da parte nostra.<\/p>\n<h4>2. Come raccogliamo i vostri dati personali<\/h4>\n<p>I tipi di dati personali che raccogliamo su di voi dipendono dall'uso che fate dei nostri prodotti e servizi e dalle modalit\u00e0 con cui interagite con noi.<\/p>\n<h5>2.1 Dati personali raccolti direttamente dall'utente<\/h5>\n<p>Chiediamo e raccogliamo i vostri dati personali nei seguenti casi:<\/p>\n<ul>\n<li>Quando esprimete interesse per i nostri prodotti e servizi e richiedete ulteriori informazioni; quando richiedete una demo; quando richiedete l'assistenza clienti; quando utilizzate la nostra pagina Contatti; quando vi registrate per ricevere comunicazioni da noi; quando partecipate a un programma o a un sondaggio; quando scaricate contenuti dai nostri siti web; quando siete un utente autorizzato dei nostri prodotti e servizi.<\/li>\n<ul>\n<li>Possiamo raccogliere il vostro nome, titolo di lavoro, nome dell'azienda, indirizzo, paese, numero di telefono, indirizzo e-mail, nome utente e password.<\/li>\n<\/ul>\n<li>Quando si effettua un acquisto utilizzando i nostri siti web.<\/li>\n<ul>\n<li>Possiamo raccogliere il vostro nome, la qualifica professionale, il nome della societ\u00e0, l'indirizzo, il paese, il numero di telefono, l'indirizzo e-mail e le informazioni finanziarie per la fatturazione e il pagamento, come il nome e l'indirizzo di fatturazione, lo strumento di pagamento come il numero di carta di credito e il codice di sicurezza associato allo strumento di pagamento o le informazioni sul conto bancario. <\/li>\n<\/ul>\n<li>Quando vi registrate a uno dei nostri eventi.<\/li>\n<ul>\n<li>Possiamo raccogliere il nome, la qualifica professionale, il nome dell'azienda, l'indirizzo, il paese, il numero di telefono, l'indirizzo e-mail e le informazioni finanziarie per la fatturazione e il pagamento, come il nome e l'indirizzo di fatturazione, lo strumento di pagamento, come il numero di carta di credito e il codice di sicurezza associato allo strumento di pagamento, o le informazioni sul conto bancario. Se partecipate a un evento di persona e vi viene rilasciato un badge, possiamo scansionare il badge e accedere alle vostre informazioni, come nome, titolo di lavoro, nome della societ\u00e0, indirizzo, paese, numero di telefono e indirizzo e-mail. Potremmo anche raccogliere la vostra immagine.<\/li>\n<\/ul>\n<li>Quando comunicate con noi per telefono.<\/li>\n<ul>\n<li>Potremmo raccogliere informazioni per verificare l'identit\u00e0 dell'utente e registrare la chiamata a scopo di formazione, in conformit\u00e0 alle leggi vigenti.<\/li>\n<\/ul>\n<li>Quando visitate i nostri uffici.<\/li>\n<ul>\n<li>Possiamo raccogliere il nome, la qualifica professionale, il nome della societ\u00e0, l'indirizzo, il paese, il numero di telefono, l'indirizzo e-mail, l'ora e la data del vostro arrivo. Possiamo anche raccogliere la vostra immagine. <\/li>\n<\/ul>\n<li>Quando interagite con i nostri siti web o con le nostre e-mail.<\/li>\n<ul>\n<li>Possiamo raccogliere informazioni sul vostro dispositivo, sull'utilizzo dei nostri siti web e\/o delle nostre e-mail utilizzando cookie, web beacon o altre tecnologie simili.<\/li>\n<\/ul>\n<li>Quando interagite con i nostri prodotti e servizi.<\/li>\n<ul>\n<li>Possiamo raccogliere informazioni sulla cronologia dell'account e sulle attivit\u00e0 associate al vostro account, come ad esempio informazioni sul vostro dispositivo e sull'utilizzo dei nostri prodotti e servizi attraverso file di log e altre tecnologie.<\/li>\n<\/ul>\n<li>Quando l'utente compila volontariamente un modulo web, partecipa a un sondaggio, risponde a un questionario o condivide dati con noi in un'altra forma di ricerca.<\/li>\n<ul>\n<li>Possiamo raccogliere le informazioni che l'utente sceglie volontariamente di fornire e tutte le informazioni obbligatorie che richiediamo.<\/li>\n<\/ul>\n<\/ul>\n<p> Se fornite dati personali relativi a un altro individuo, dichiarate di avere l'autorit\u00e0 per farlo e, ove richiesto, di aver ottenuto il consenso necessario per condividere tali dati. L'utente riconosce che i dati personali dell'altra persona possono essere utilizzati in conformit\u00e0 con la presente Informativa sulla privacy.<\/p>\n<p class=\"translation-block\">Se ritenete che i vostri dati personali ci siano stati forniti in modo improprio, o se volete esercitare i vostri diritti relativi ai vostri dati personali, contattateci all'indirizzo <a href=\"mailto:privacy@rsa.com\" target=\"_self\">privacy@rsa.com<\/a>.<\/p>\n<h5>2.2 Dati personali raccolti da altri<\/h5>\n<p>Potremmo raccogliere i dati personali dell'utente da altre fonti, quali informazioni pubblicamente disponibili e fonti terze da cui acquistiamo i dati personali. Le fonti terze possono cambiare nel tempo e possono includere:<\/p>\n<ul>\n<li>intermediari di dati da cui acquistiamo dati demografici per integrare i dati personali che abbiamo raccolto su di voi<\/li>\n<li>Servizi di comunicazione, compresi i provider di posta elettronica e i social network, quando ci date il permesso di accedere alle vostre informazioni da tali servizi o reti di terze parti<\/li>\n<li>Partner con i quali offriamo prodotti e servizi in co-branding o con i quali ci impegniamo in attivit\u00e0 di marketing congiunte. <\/li>\n<\/ul>\n<p>I dati personali possono includere identificatori, informazioni professionali o relative all'impiego, informazioni sull'istruzione, informazioni commerciali, informazioni visive, informazioni sull'attivit\u00e0 in Internet, profili di social media e deduzioni su preferenze e comportamenti. Possiamo combinare informazioni provenienti da altre fonti con i dati personali forniti dall'utente.<\/p>\n<p>Questi dati ci aiutano a mantenere aggiornati i nostri registri, a identificare nuovi clienti e a creare pubblicit\u00e0 su misura per prodotti e servizi che potrebbero interessarvi.<\/p>\n<h4>3. Dati sul dispositivo e sull'utilizzo da noi trattati<\/h4>\n<p>Utilizziamo strumenti di raccolta di informazioni come cookie, web beacon, pixel e tecnologie simili per raccogliere automaticamente informazioni che potrebbero contenere i vostri dati personali quando utilizzate i nostri siti e servizi o interagite con le e-mail che vi inviamo.<\/p>\n<h5>3.1 Raccolta automatica<\/h5>\n<p>La maggior parte dei siti web raccoglie automaticamente dati sull'utente quando questi visita il sito. Queste informazioni possono includere:<\/p>\n<ul>\n<li>Identificatori<\/li>\n<li>Informazioni commerciali<\/li>\n<li>Indirizzo IP<\/li>\n<li>Informazioni sul server proxy<\/li>\n<li>Informazioni sul dispositivo e sull'applicazione<\/li>\n<li>Numeri di identificazione<\/li>\n<li>Posizione<\/li>\n<li>Tipo di browser<\/li>\n<li>Plug-in<\/li>\n<li>Integrazioni<\/li>\n<li>Fornitore di servizi Internet<\/li>\n<li>Vettore mobile<\/li>\n<li>Pagine e file visualizzati<\/li>\n<li>Ricerche<\/li>\n<li>Sito web, app o pubblicit\u00e0 di riferimento<\/li>\n<li>Informazioni sulla configurazione del sistema<\/li>\n<li>Preferenze pubblicitarie<\/li>\n<li>Preferenze linguistiche<\/li>\n<li>Data e ora di utilizzo<\/li>\n<li>Frequenza delle visite ai siti web<\/li>\n<\/ul>\n<p>Utilizziamo queste informazioni per analizzare le tendenze generali, per aiutarci a migliorare i nostri siti web, per offrire un'esperienza personalizzata agli utenti del sito, per proteggere e mantenere i nostri siti web.<\/p>\n<p>Raccogliamo inoltre automaticamente informazioni nell'ambito dell'utilizzo dei nostri prodotti e servizi. Queste informazioni possono includere:<\/p>\n<ul>\n<li>Identificatori<\/li>\n<li>Informazioni commerciali<\/li>\n<li>Indirizzo IP<\/li>\n<li>Informazioni sul server proxy<\/li>\n<li>Numero del dispositivo mobile<\/li>\n<li>Numero di identificazione del dispositivo<\/li>\n<li>Numero di identificazione della domanda<\/li>\n<li>Posizione<\/li>\n<li>Tipo di browser<\/li>\n<li>Fornitore di servizi Internet<\/li>\n<li>Vettore mobile<\/li>\n<li>Pagine e file visualizzati<\/li>\n<li>Interazioni con il sito web e le pagine web<\/li>\n<li>Ricerca informazioni<\/li>\n<li>Tipo e versione del sistema operativo<\/li>\n<li>Informazioni sulla configurazione del sistema<\/li>\n<li>Dati e orari di utilizzo<\/li>\n<li>Dettagli sui prodotti e sulle versioni dei prodotti utilizzati<\/li>\n<\/ul>\n<p>Utilizziamo queste informazioni per mantenere la sicurezza dei nostri siti web e dei nostri prodotti e servizi, per fornire le funzionalit\u00e0 necessarie, per migliorare le prestazioni dei servizi, per valutare e migliorare l'esperienza del cliente e dell'utente, per convalidare che l'utente sia un utente autorizzato, per verificare il rispetto dei termini di utilizzo, per identificare le opportunit\u00e0 future di sviluppo dei servizi, per valutare le esigenze e i requisiti di capacit\u00e0 e per identificare le opportunit\u00e0 per i clienti.<\/p>\n<p>I dati relativi ai dispositivi e all'utilizzo vengono utilizzati principalmente per identificare gli usi unici dei nostri siti web, anzich\u00e9 per identificare individui specifici, a meno che l'identit\u00e0 non sia richiesta per motivi di sicurezza o per fornire servizi all'individuo.<\/p>\n<h5>3.2 Tecnologie di tracciamento<\/h5>\n<p>I nostri siti web, i servizi online, le applicazioni interattive, i messaggi e-mail e gli annunci pubblicitari possono utilizzare tecnologie di tracciamento come web beacon, pixel, tag e cookie per aiutarci a personalizzare la vostra esperienza, a comprendere meglio le vostre preferenze, a dirci quali parti dei nostri siti web avete visitato, a facilitare e misurare l'efficacia dei nostri annunci pubblicitari e servizi web basati sugli interessi e a raccogliere informazioni sull'uso dei nostri siti web e sulle interazioni con le nostre e-mail.<\/p>\n<p>I web beacon e i pixel sono utilizzati sui nostri siti web e nelle nostre e-mail per aiutare a consegnare i cookie, raccogliere dati sull'utilizzo e sulle prestazioni, nonch\u00e9 per gestire e migliorare i nostri siti web e le nostre e-mail di marketing.<\/p>\n<p>I cookie sono identificatori alfanumerici che vengono memorizzati sulla memoria locale del dispositivo attraverso il browser web per scopi di registrazione. Alcuni cookie ci consentono di facilitare la navigazione nei nostri siti e servizi, di migliorare e personalizzare la vostra esperienza di navigazione e di dedurre le vostre preferenze di navigazione, mentre altri sono utilizzati per consentire un processo di accesso pi\u00f9 rapido o per permetterci di tracciare le vostre attivit\u00e0 online nel tempo e sulle nostre pagine web. <\/p>\n<p>Utilizziamo sia cookie di sessione che persistenti. <\/p>\n<ul>\n<li>I cookie di sessione esistono solo durante una singola sessione e scompaiono dal vostro dispositivo quando chiudete il browser o spegnete il dispositivo. Utilizziamo i cookie di sessione per consentire ai nostri sistemi di identificarvi in modo univoco durante una sessione o mentre siete connessi ai siti web o ai nostri servizi. Questo ci permette di elaborare le vostre transazioni e richieste online e di verificare la vostra identit\u00e0 dopo che avete effettuato l'accesso, mentre vi muovete attraverso le nostre pagine web e i nostri servizi.<\/li>\n<li>I cookie persistenti rimangono sul dispositivo dell'utente anche dopo la chiusura del browser o lo spegnimento del dispositivo. Utilizziamo i cookie persistenti per tracciare informazioni aggregate e statistiche sull'attivit\u00e0 degli utenti sui nostri siti web.<\/li>\n<\/ul>\n<p>Esistono tre categorie di cookie: obbligatori e funzionali, analitici e di personalizzazione e pubblicitari:<\/p>\n<ul>\n<li>I cookie necessari e funzionali sono necessari per il funzionamento dei nostri siti web, come i cookie di sessione che trasmettono i siti web, i cookie di autenticazione e i cookie di sicurezza. Quando decidete di fornirci i vostri dati personali, possiamo inserire un cookie nel vostro browser per consentirci di identificarvi quando siete connessi ai siti web e di elaborare le transazioni e le richieste che fate. Non \u00e8 possibile rinunciare ai cookie obbligatori e funzionali, poich\u00e9 sono necessari per il funzionamento dei nostri siti web.<\/li>\n<li>I cookie analitici e di personalizzazione sono utilizzati per migliorare le prestazioni, le funzioni e i servizi dei nostri siti web e per fornire all'utente comunicazioni pi\u00f9 pertinenti. Questi possono includere cookie che analizzano il traffico del sito, sono utilizzati per ricerche di mercato e visualizzano pubblicit\u00e0 generica che non \u00e8 diretta a un individuo specifico. Utilizziamo questi cookie per raccogliere informazioni sull'utilizzo dei nostri siti web, per determinare quali pagine vengono visualizzate maggiormente, per fornire interazioni migliorate e comunicazioni pertinenti e per monitorare le prestazioni delle nostre pubblicit\u00e0. \u00c8 possibile scegliere di non utilizzare i nostri cookie analitici e di personalizzazione facendo clic su \"Impostazioni sulla privacy\" nella parte inferiore del nostro sito web. <\/li>\n<li>I cookie pubblicitari tracciano la vostra attivit\u00e0 sui nostri siti web per capire i vostri interessi e per indirizzarvi il marketing. Potete scegliere di non accettare i cookie pubblicitari cliccando su \"Impostazioni sulla privacy\" in fondo al nostro sito web.<\/li>\n<\/ul>\n<h5>3.3 Disabilitazione dei cookie nel browser<\/h5>\n<p>Oltre a utilizzare le nostre impostazioni sulla privacy, \u00e8 possibile rinunciare alla raccolta di dati non essenziali sul dispositivo e sull'utilizzo del browser web. A seconda delle preferenze personali, \u00e8 possibile modificare le opzioni del browser utilizzando la funzione \"Aiuto\" nella barra degli strumenti del browser. \u00c8 possibile impedire al computer di accettare nuovi cookie, far s\u00ec che il browser notifichi la ricezione di un nuovo cookie o disabilitare tutti i cookie. Tuttavia, \u00e8 importante notare che se si bloccano o si eliminano i cookie che utilizziamo sui nostri siti web, sar\u00e0 ancora possibile navigare in alcune aree dei siti web, ma alcune funzioni potrebbero non funzionare correttamente.<\/p>\n<h5>3.4 Oggetti di memoria locale Flash<\/h5>\n<p>Possiamo utilizzare Flash Local Storage Objects (Flash LSO) per memorizzare le vostre preferenze sul sito web e personalizzare la vostra visita. I Flash LSO sono diversi dai cookie del browser per la quantit\u00e0 e il tipo di dati memorizzati. In genere, non \u00e8 possibile controllare, eliminare o disabilitare l'accettazione di tutti i Flash LSO attraverso il browser web.<br \/>\nPer ulteriori informazioni sugli LSO di Flash e per sapere come gestire le impostazioni per gli LSO di Flash, visitate la pagina della Guida di Adobe Flash Player. <\/p>\n<h5>3.5 Immagini invisibili<\/h5>\n<p>Le immagini invisibili sono piccoli elementi grafici dotati di un identificatore univoco, la cui funzione \u00e8 simile a quella dei cookie. A differenza dei cookie, che vengono memorizzati nella memoria locale del dispositivo, queste immagini sono incorporate in modo invisibile nelle pagine web e nelle applicazioni. <\/p>\n<p>Possiamo utilizzare immagini invisibili, note anche come web beacon, web bug o pixel tag, in relazione ai nostri siti web e alle nostre offerte di servizi per, tra l'altro, tracciare le attivit\u00e0 dei visitatori del sito web e degli utenti delle applicazioni, aiutarci a gestire i contenuti e compilare statistiche sull'utilizzo del sito web. <\/p>\n<p>Noi, e i nostri fornitori di servizi terzi, utilizziamo anche immagini invisibili nelle e-mail HTML inviate ai nostri clienti per aiutarci a monitorare i tassi di risposta delle e-mail, a identificare quando le nostre e-mail vengono visualizzate e a monitorare se le nostre e-mail vengono inoltrate.<\/p>\n<h5>3.6 Pubblicit\u00e0 comportamentale o basata sugli interessi<\/h5>\n<p>Noi, e i nostri fornitori di servizi terzi, possiamo utilizzare le informazioni sulla vostra visita ai nostri siti web, come le pagine che visitate, gli articoli che visualizzate e le vostre risposte alle nostre pubblicit\u00e0 ed e-mail. Queste informazioni ci permettono di rendere gli annunci pubblicitari che vedete pi\u00f9 rilevanti per voi. Per aggiornare le proprie preferenze, l'utente pu\u00f2 fare clic su \"Cancella iscrizione\" in qualsiasi comunicazione di marketing via e-mail che gli viene inviata.<\/p>\n<p>Potrebbero essere necessari fino a dieci (10) giorni lavorativi perch\u00e9 le preferenze di posta elettronica diventino effettive.<\/p>\n<p>\u00c8 inoltre possibile visitare le pagine di opt-out per rinunciare a molte reti pubblicitarie di terze parti attraverso vari siti web di associazioni di categoria, come ad esempio: <\/p>\n<ul>\n<li class=\"translation-block\">Ufficio pubblicit\u00e0 su Internet (IAB): <a href=\"https:\/\/www.iab.com\/news\/interactive-advertising-bureau-iab\/\" target=\"_blank\" rel=\"noopener\">Interactive Advertising Bureau<\/a> (IAB)<\/li>\n<li class=\"translation-block\">Iniziativa per la pubblicit\u00e0 di rete (NAI): <a href=\"https:\/\/thenai.org\/\" target=\"_blank\" rel=\"noopener\">thenai.org<\/a><\/li>\n<li class=\"translation-block\">Alleanza per la pubblicit\u00e0 digitale (DAA): <a href=\"https:\/\/digitaladvertisingalliance.org\/\" target=\"_blank\" rel=\"noopener\">DigitalAdvertisingAlliance.org<\/a><\/li>\n<\/ul>\n<p>Tuttavia, l'utilizzo di queste pagine di opt-out non significa che non riceverete pi\u00f9 pubblicit\u00e0 attraverso i nostri siti web o servizi, o su altri siti web di terzi.<\/p>\n<h5>3.7 Reti pubblicitarie di terzi<\/h5>\n<p>Di tanto in tanto, possiamo fornire agli inserzionisti di rete non affiliati informazioni, compresi i dati personali dell'utente. Questi inserzionisti di rete forniscono pubblicit\u00e0 sui nostri siti web, sulle nostre applicazioni e su siti web e media di altre parti, come le piattaforme di social network. <\/p>\n<p>L'uso condiviso dei dati personali dell'utente con questi inserzionisti di rete ci consente di offrire i prodotti e i servizi che pi\u00f9 interessano all'utente. I fornitori di reti pubblicitarie non affiliate, gli inserzionisti di rete, gli sponsor e\/o i servizi di misurazione del traffico possono utilizzare cookie, JavaScript, web beacon, Flash LSO e altre tecnologie di tracciamento per misurare l'efficacia delle loro pubblicit\u00e0 e per personalizzare i contenuti pubblicitari. I cookie e le tecnologie di altre parti sono disciplinati dalle specifiche norme sulla privacy di ciascuna societ\u00e0 e non dalla presente Informativa sulla privacy.<\/p>\n<p>Quando collaboriamo con reti pubblicitarie di terzi, chiediamo loro di limitare il trattamento dei dati solo a quanto necessario per fornirci i servizi pubblicitari da noi richiesti.<\/p>\n<p>Gli utenti del sito web situati negli Stati Uniti possono avere maggiori informazioni sull'opting out e sull'esclusione di molte reti pubblicitarie di terzi attraverso vari siti web di associazioni di categoria come: <\/p>\n<ul>\n<li class=\"translation-block\">Ufficio pubblicit\u00e0 su Internet (IAB): <a href=\"https:\/\/www.iab.com\/news\/interactive-advertising-bureau-iab\/\" target=\"_blank\" rel=\"noopener\">Interactive Advertising Bureau<\/a> (IAB)<\/li>\n<li class=\"translation-block\">Iniziativa per la pubblicit\u00e0 di rete (NAI): <a href=\"https:\/\/thenai.org\/\" target=\"_blank\" rel=\"noopener\">thenai.org<\/a><\/li>\n<li class=\"translation-block\">Alleanza per la pubblicit\u00e0 digitale (DAA): <a href=\"https:\/\/digitaladvertisingalliance.org\/\" target=\"_blank\" rel=\"noopener\">DigitalAdvertisingAlliance.org<\/a><\/li>\n<\/ul>\n<p>Tuttavia, ci\u00f2 non significa che non riceverete pi\u00f9 pubblicit\u00e0 attraverso i nostri siti web, i nostri servizi o altri siti web di terzi.<\/p>\n<h5>3.8 Utilizzo di pi\u00f9 dispositivi<\/h5>\n<p>Noi e i nostri fornitori di servizi terzi, tra cui Google, possiamo utilizzare le informazioni che raccogliamo sull'utente, direttamente dal nostro sito web, dalle nostre applicazioni mobili, attraverso il dispositivo dell'utente o da terzi, per aiutare noi e i nostri fornitori di servizi terzi a identificare altri dispositivi utilizzati dall'utente, come un telefono cellulare, un tablet o un altro computer. <\/p>\n<p>Noi, e i nostri fornitori di servizi terzi, possiamo anche utilizzare le informazioni sull'uso incrociato dei dispositivi che apprendiamo sull'utente per proporre pubblicit\u00e0 mirata sui suoi dispositivi e per inviargli e-mail.<\/p>\n<p>Per rinunciare all'utilizzo di dispositivi incrociati, \u00e8 possibile rinunciare alla pubblicit\u00e0 di terzi (vedere la sezione 3.7). Tuttavia, se si rinuncia a questi cookie pubblicitari, la rinuncia sar\u00e0 specifica per il browser web, l'applicazione o il dispositivo da cui si accede alla rinuncia. Se si utilizzano pi\u00f9 dispositivi o browser web, \u00e8 necessario effettuare l'opt-out per ogni dispositivo e ogni browser su ogni dispositivo utilizzato.<\/p>\n<h5>3.9 Opzione Non tracciare<\/h5>\n<p>Alcuni browser internet offrono un'opzione \"Do Not Track\" che consente di comunicare ai siti web che non si desidera che le proprie attivit\u00e0 online vengano tracciate. Attualmente non esiste uno standard comune nel settore, pertanto riconosciamo questi segnali Do Not Track sui nostri siti web. Prendiamo sul serio la privacy e le vostre preferenze e continueremo a monitorare gli sviluppi del Do Not Track e l'adozione di uno standard.<\/p>\n<p class=\"translation-block\">Tuttavia, l'utente pu\u00f2 disabilitare alcuni tracciamenti facendo clic su \"Impostazioni sulla privacy\" nella parte inferiore del nostro sito web, all'indirizzo: <a href=\"http:\/\/www.rsa.com\/it\/\" target=\"_self\">RSA.com<\/a>, disabilitando i cookie sul proprio browser (si veda la Sezione 3.3), o scegliendo di non ricevere pubblicit\u00e0 (si vedano le Sezioni 3.6 e 3.7).<\/p>\n<h5>3.10 Media sociali<\/h5>\n<p>Siamo responsabili dei contenuti che pubblichiamo utilizzando le piattaforme di social media, ma non siamo responsabili della gestione delle piattaforme di social media o dei dati da esse raccolti ed elaborati. I nostri siti web dispongono di plugin per la condivisione dei social media. Questi widget possono consentirvi di pubblicare informazioni sulle vostre attivit\u00e0 sui nostri siti web su piattaforme esterne e social network. Potreste anche essere in grado di mettere \"mi piace\" o condividere le informazioni che abbiamo pubblicato sui nostri siti web o sulle nostre pagine di social media con marchio. Se le pagine dei social media sono ospitate dalle singole piattaforme e l'utente fa clic sul sito dai nostri siti web, la piattaforma pu\u00f2 ricevere informazioni che indicano che l'utente ha visitato i nostri siti web. Se l'utente ha effettuato l'accesso al sito di social media nel momento in cui fa clic, il sito di social media pu\u00f2 essere in grado di collegare la sua visita ai nostri siti web con il suo profilo di social media.<\/p>\n<h5>3.11 Informazioni sulla telefonia<\/h5>\n<p>Se l'utente utilizza le funzioni dei nostri servizi sul proprio dispositivo mobile, possiamo raccogliere informazioni di registro della telefonia, tra cui numeri di telefono, ora e data delle chiamate, durata della chiamata, informazioni di instradamento degli SMS. Possiamo raccogliere informazioni sugli eventi del dispositivo, come l'attivit\u00e0 del sistema, le impostazioni hardware e la lingua del browser. Possiamo anche raccogliere informazioni sulla posizione attraverso il GPS, l'indirizzo IP, i punti di accesso WiFi e le torri cellulari e altri sensori che ci forniscono informazioni sui dispositivi vicini.<\/p>\n<h4>4. Finalit\u00e0 e basi giuridiche del trattamento dei dati personali<\/h4>\n<p>Raccogliamo e trattiamo i vostri dati personali per le seguenti finalit\u00e0:<\/p>\n<ul>\n<li>Per fornire e promuovere i nostri siti web, prodotti e servizi. Tratteremo i vostri dati personali per adempiere agli obblighi previsti da qualsiasi contratto stipulato con voi o con il vostro datore di lavoro per l'utilizzo dei nostri siti web e servizi. <\/li>\n<ul>\n<li>Se non esiste un contratto, la base giuridica per il trattamento dei vostri dati personali \u00e8 la gestione e l'amministrazione dei nostri siti web e servizi per fornirvi l'accesso ai contenuti.<\/li>\n<\/ul>\n<li>Per fornire e promuovere la sicurezza dei nostri siti web. Tratteremo i vostri dati personali quando tracceremo il vostro utilizzo dei nostri siti web e servizi; quando creeremo dati aggregati, de-identificati e pseudonimizzati; quando verificheremo gli account e le attivit\u00e0; quando indagheremo su attivit\u00e0 sospette; quando faremo rispettare i nostri termini, condizioni e politiche. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 la promozione della sicurezza dei nostri siti web, servizi, sistemi e applicazioni e la protezione dei nostri diritti e dei diritti altrui.<\/li>\n<\/ul>\n<li>Gestione degli utenti. Tratteremo i dati personali dell'utente al momento della registrazione di un account presso di noi, per stabilire e gestire l'account utente e per consentirci di adempiere ai nostri obblighi nei confronti dell'utente in conformit\u00e0 al contratto o ai termini e alle condizioni applicabili. <\/li>\n<ul>\n<li>La base giuridica per il trattamento dei vostri dati personali \u00e8 quella di consentirci di confermare e autenticare la vostra identit\u00e0 e di impedire l'accesso non autorizzato alle aree riservate dei nostri siti web.<\/li>\n<\/ul>\n<li>Per fornire assistenza. Tratteremo i vostri dati personali quando richiedete un servizio di supporto tecnico o di assistenza clienti per esaminare i rapporti sugli errori, le informazioni sulle prestazioni dei prodotti e i problemi riscontrati, nonch\u00e9 per risolvere i problemi e fornire informazioni di aiuto. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 quella di consentirci di confermare il problema e di fornirvi l'assistenza necessaria per risolverlo.<\/li>\n<\/ul>\n<li>Per rispondere alle vostre richieste. Trattiamo i vostri dati personali quando compilate un modulo \"Contattaci\", richiedete una demo o ci contattate in qualsiasi altro modo, compresi chatbot, e-mail o telefono. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 l'adempimento dei nostri obblighi nei vostri confronti, l'adempimento delle vostre richieste e la comunicazione con voi.<\/li>\n<\/ul>\n<li>Per gestire i pagamenti. Trattiamo i vostri dati personali quando effettuate un acquisto e ci fornite informazioni finanziarie. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 la riscossione dei pagamenti necessari ai sensi dei contratti stipulati con voi.<\/li>\n<\/ul>\n<li>Per registrare conversazioni telefoniche e sessioni di chat. Trattiamo i vostri dati personali se ci chiamate e monitoriamo e registriamo la chiamata o se aprite una sessione di chat e monitoriamo e registriamo la conversazione. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 la formazione, il controllo qualit\u00e0 e l'amministrazione. Otterremo il vostro consenso preventivo o vi permetteremo di opporvi alla registrazione di una telefonata se richiesto dalla legge.<\/li>\n<\/ul>\n<li>Per inviare comunicazioni. Tratteremo i vostri dati personali per inviarvi informazioni di marketing, consigli sui prodotti e altre comunicazioni, come newsletter o notifiche push. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 la fornitura di informazioni su promozioni, novit\u00e0 o eventi a fini di marketing diretto.<\/li>\n<\/ul>\n<li>Per gestire la registrazione agli eventi. Tratteremo i vostri dati personali per pianificare e ospitare gli eventi a cui vi iscrivete o a cui partecipate, compreso l'invio di comunicazioni. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 l'adempimento dei nostri obblighi nei vostri confronti.<\/li>\n<\/ul>\n<li>Per sviluppare e migliorare i nostri siti web e servizi. Tratteremo i vostri dati personali per analizzare le tendenze e tracciare il vostro utilizzo e le vostre interazioni con i nostri siti web, se necessario. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 il nostro legittimo interesse a sviluppare e migliorare i nostri siti web e servizi e a fornire agli utenti contenuti e servizi pi\u00f9 pertinenti.<\/li>\n<\/ul>\n<li>Per valutare e migliorare l'esperienza dell'utente. Elaboriamo l'utilizzo del dispositivo e dei dati, che possono essere associati ai dati personali dell'utente, e le informazioni sul consumo di contenuti multimediali, quali televisione, app e giochi, a cui l'utente accede tramite i nostri prodotti. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 l'analisi delle tendenze, la valutazione e il miglioramento dell'esperienza dell'utente e il miglioramento dei nostri siti web e delle nostre offerte di servizi.<\/li>\n<\/ul>\n<li>Per valutare i requisiti di capacit\u00e0. Tratteremo i vostri dati personali per valutare i requisiti di capacit\u00e0 dei nostri servizi. <\/li>\n<ul>\n<li>La base giuridica per il trattamento dei vostri dati personali \u00e8 garantire la capacit\u00e0 necessaria per le nostre offerte di servizi.<\/li>\n<\/ul>\n<li>Per verificare il rispetto delle nostre condizioni d'uso. Tratteremo i dati personali dell'utente per convalidare che sia un utente autorizzato e per garantire il rispetto dei termini che ne garantiscono l'utilizzo. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 il rispetto dei termini previsti.<\/li>\n<\/ul>\n<li>Identificare le opportunit\u00e0 per i clienti. Tratteremo i vostri dati personali per valutare nuove opportunit\u00e0 per i nostri clienti. <\/li>\n<ul>\n<li>La base giuridica per il trattamento dei vostri dati personali \u00e8 quella di garantire la soddisfazione delle richieste dei nostri clienti e la loro esperienza d'uso.<\/li>\n<\/ul>\n<li>Per visualizzare pubblicit\u00e0 e contenuti personalizzati. Tratteremo i vostri dati personali per farvi pubblicit\u00e0 e fornirvi altri contenuti personalizzati in base ai vostri interessi e alle vostre attivit\u00e0. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 la possibilit\u00e0 di personalizzare la vostra esperienza con noi e di formulare raccomandazioni adeguate.<\/li>\n<\/ul>\n<li>Per gestire sondaggi e condurre ricerche. Tratteremo i vostri dati personali per condurre ricerche di mercato, ottenere recensioni di prodotti e raccogliere informazioni di feedback e valutazioni nell'ambito di un sondaggio tra i clienti. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 il miglioramento dei nostri prodotti e servizi e il raggiungimento degli obiettivi e delle finalit\u00e0 della ricerca. <\/li>\n<\/ul>\n<li>Per adempiere agli obblighi di legge. Tratteremo i dati personali dell'utente per collaborare con le autorit\u00e0 pubbliche e governative, i tribunali o le autorit\u00e0 di regolamentazione per adempiere ai nostri obblighi legali ai sensi delle leggi vigenti, per proteggere i nostri diritti, per proteggere dall'uso improprio o dall'abuso dei nostri siti web o servizi, per proteggere la propriet\u00e0 personale, per proteggere la sicurezza degli altri, per perseguire i rimedi a nostra disposizione, per limitare i nostri danni, per adempiere ai procedimenti giudiziari o alle ordinanze dei tribunali o ai procedimenti legali, per rispondere alle richieste legittime e per condurre audit. <\/li>\n<ul>\n<li>La base giuridica del trattamento dei vostri dati personali \u00e8 il rispetto delle leggi, delle norme e dei regolamenti applicabili.<\/li>\n<\/ul>\n<\/ul>\n<p>Laddove richiesto dalla legge, otterremo il vostro consenso preventivo all'utilizzo e al trattamento dei vostri dati personali, oppure ci baseremo su un'altra base giuridica autorizzata, come l'esecuzione di un contratto o un interesse legittimo. <\/p>\n<h4>5. Con chi condividiamo i vostri dati personali?<\/h4>\n<p>Possiamo condividere i vostri dati personali con i nostri partner commerciali, tra cui:<\/p>\n<ul>\n<li>Affiliati. Condivideremo i vostri dati personali con i nostri affiliati nella misura in cui ci\u00f2 sia necessario sulla base del contratto stipulato dall'affiliato con voi.<\/li>\n<li>Fornitori di servizi. Condivideremo i vostri dati personali con i nostri fornitori di servizi a contratto che forniscono servizi quali hosting, e-mail, gestione delle relazioni con i clienti (CRM), amministrazione informatica e di sistema, elaborazione di carte di credito e pagamenti, ricerca e analisi e assistenza clienti.<\/li>\n<li>Consulenti professionali. Condivideremo i vostri dati personali con i nostri consulenti professionali, come avvocati, banchieri, revisori dei conti e assicuratori, nella misura in cui siamo legalmente obbligati a condividerli o abbiamo un interesse legittimo a farlo.<\/li>\n<li>Reti e siti web di terzi. Condivideremo i dati personali dell'utente con reti di social media e siti web pubblicitari per poter commercializzare e pubblicizzare su piattaforme di terze parti.<\/li>\n<li>Account di terzi. Condivideremo i vostri dati personali se connettete i vostri account di terzi attraverso i nostri prodotti, al fine di autenticarvi e soddisfare le vostre richieste attraverso l'account di terzi.<\/li>\n<li>Terze parti in una transazione aziendale. Condivideremo i vostri dati personali se saremo coinvolti in una fusione, acquisizione, riorganizzazione, scioglimento o altra modifica aziendale.<\/li>\n<\/ul>\n<h4>6. Trasferimenti internazionali di dati personali<\/h4>\n<p>Possiamo raccogliere, trasferire e conservare i vostri dati personali negli Stati Uniti. Potremmo anche raccogliere, trasferire e conservare i vostri dati personali in altri paesi. Ci\u00f2 include paesi al di fuori dello Spazio Economico Europeo (SEE) e paesi con leggi che non sono state ritenute in grado di fornire un livello adeguato di protezione ai sensi delle leggi dell'Unione Europea (UE) o di altre giurisdizioni.<\/p>\n<p>Ci\u00f2 significa che i vostri dati personali potrebbero essere trattati al di fuori della vostra giurisdizione in paesi che non sono soggetti a una decisione di adeguatezza della Commissione europea sulla base dell'articolo 45 del Regolamento (UE) 2016\/679 (GDPR) o di un'autorit\u00e0 di regolamentazione. Tuttavia, garantiremo che i vostri dati personali siano soggetti a un livello adeguato di protezione e sicurezza stipulando accordi appropriati, comprese le clausole contrattuali standard del Regno Unito e le clausole contrattuali standard dell'UE, o un meccanismo alternativo per il trasferimento dei vostri dati personali. <\/p>\n<h4>7. Dati sui bambini<\/h4>\n<p class=\"translation-block\">I nostri siti web, prodotti e servizi non sono destinati ai bambini. Non raccogliamo ed elaboriamo consapevolmente dati personali di bambini di et\u00e0 inferiore ai sedici (16) anni. Se siete un genitore o un tutore e ritenete che vostro figlio ci abbia fornito dati personali senza il vostro consenso, contattateci all'indirizzo <a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a> e adotteremo le misure necessarie per cancellare i suoi dati personali dai nostri sistemi.<\/p>\n<h4>8. Conservazione dei dati<\/h4>\n<p>Conserveremo i vostri dati non pi\u00f9 a lungo di quanto sia necessario per gli scopi della RSA. Conserveremo i vostri dati personali per periodi di tempo diversi a seconda della categoria di dati personali per cui sono stati raccolti. Alcuni dati personali possono essere cancellati automaticamente, mentre altri saranno conservati pi\u00f9 a lungo, coerentemente con lo scopo originario della raccolta, per il tempo necessario ad adempiere ai nostri obblighi o come richiesto dalla legge. <\/p>\n<p>Alla scadenza del periodo di conservazione, cancelleremo i vostri dati personali. Se per motivi tecnici non \u00e8 possibile cancellare completamente i dati, adotteremo misure adeguate per impedirne l'ulteriore elaborazione.<\/p>\n<h4>9. I vostri diritti<\/h4>\n<p>L'utente pu\u00f2 godere di alcuni diritti relativi ai propri dati personali, nel rispetto delle leggi sulla protezione dei dati. Tali diritti possono includere:<\/p>\n<ul>\n<li>Accesso ai dati personali<\/li>\n<li>Informazioni sul trattamento dei vostri dati personali<\/li>\n<li>Rettifica di dati personali inesatti<\/li>\n<li>Cancellazione o eliminazione dei vostri dati personali<\/li>\n<li>Limitazioni al trattamento dei dati personali da parte nostra<\/li>\n<li>Obiezione al trattamento dei dati personali da parte nostra<\/li>\n<li>Rinuncia a determinate divulgazioni dei propri dati personali<\/li>\n<li>Nessuna ritorsione o discriminazione per l'esercizio dei propri diritti.<\/li>\n<li>Non essere soggetti a decisioni basate esclusivamente su un trattamento automatizzato<\/li>\n<li>Revoca del consenso per trattamenti futuri<\/li>\n<\/ul>\n<p>Attualmente non utilizziamo processi decisionali automatizzati sui nostri siti web o nei nostri servizi.<\/p>\n<h5>9.1 Come esercitare i propri diritti<\/h5>\n<p class=\"translation-block\">Per esercitare i vostri diritti, contattateci all'indirizzo <a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a>.<\/p>\n<p>I vostri dati personali possono essere trattati da noi quando rispondiamo a questi diritti. Cerchiamo di rispondere a tutte le richieste legittime entro trenta (30) giorni, a meno che non sia altrimenti richiesto dalla legge, e vi contatteremo se abbiamo bisogno di ulteriori informazioni per soddisfare la vostra richiesta o verificare la vostra identit\u00e0. A volte, in considerazione del numero e della complessit\u00e0 delle richieste che riceviamo, saranno necessari pi\u00f9 di trenta (30) giorni. Vi contatteremo se avremo bisogno di ulteriore tempo per soddisfare la vostra richiesta.<\/p>\n<p>Alcuni utenti autorizzati possono aggiornare le proprie impostazioni e i propri profili accedendo ai propri account.<\/p>\n<p>Si prega di notare che la richiesta non garantisce l'accesso completo o la rimozione totale, poich\u00e9 la legge potrebbe non consentire o richiedere la rimozione in determinate circostanze.<\/p>\n<h5>9.2 Diritti dell'utente sui dati del cliente<\/h5>\n<p>Possiamo trattare i vostri dati personali se inviati da o per un cliente dei nostri prodotti e servizi. Noi siamo l'incaricato del trattamento per conto del nostro cliente, che \u00e8 il responsabile del trattamento. Non siamo responsabili e non abbiamo alcun controllo sulle pratiche di privacy e sicurezza dei dati dei nostri clienti, che possono differire da quelle indicate nella nostra Informativa sulla privacy.<\/p>\n<p>Se i vostri dati ci sono stati inviati da o per conto di un cliente e desiderate esercitare qualsiasi diritto sui vostri dati personali ai sensi delle leggi sulla protezione dei dati applicabili, siete pregati di informarvi direttamente presso il nostro cliente. <\/p>\n<p>Possiamo accedere ai vostri dati personali solo in base alle istruzioni del nostro cliente. Se desiderate presentare una richiesta per esercitare i vostri diritti presso di noi, siete pregati di fornirci il nome del cliente che ci ha inviato i vostri dati. La richiesta verr\u00e0 inoltrata a tale cliente e gli forniremo tutto il supporto necessario per rispondere alla vostra richiesta entro un tempo ragionevole.<\/p>\n<h5>9.3 Preferenze per le comunicazioni via e-mail e SMS<\/h5>\n<p>Avete la possibilit\u00e0 di scegliere come raggiungervi con offerte di marketing e su altri usi delle vostre informazioni. Per aggiornare le vostre preferenze, potete:<\/p>\n<ul>\n<li class=\"translation-block\">Fare clic su \"Annulla iscrizione\" in tutte le comunicazioni di marketing via e-mail che vi inviamo o <a href=\"https:\/\/go.securid.com\/communication-preference-management\" rel=\"noopener\" target=\"_blank\">cliccare qui<\/a>.<\/li>\n<li class=\"translation-block\">Visitate il nostro <a href=\"https:\/\/go.securid.com\/communication-preference-management\" rel=\"noopener\" target=\"_blank\">Centro di gestione delle preferenze<\/a> per selezionare le vostre scelte.<\/li>\n<\/ul>\n<p>Si prega di notare che potrebbero essere necessari fino a 10 giorni lavorativi perch\u00e9 le preferenze di posta elettronica diventino effettive. <\/p>\n<p>La rinuncia alle comunicazioni di marketing non vi impedir\u00e0 di ricevere importanti comunicazioni commerciali relative al vostro attuale rapporto con noi, come ad esempio informazioni sui vostri prodotti o servizi, registrazioni di eventi, annunci di servizi o informazioni sulla sicurezza.<\/p>\n<h4>10. Come proteggiamo i vostri dati personali<\/h4>\n<p>Adottiamo adeguate misure organizzative, tecniche e fisiche per contribuire alla salvaguardia contro la distruzione accidentale o illegale, la perdita, l'alterazione e la divulgazione non autorizzata o l'accesso ai dati personali che raccogliamo ed elaboriamo. Il modo in cui facciamo questo include:<\/p>\n<ul>\n<li>Utilizzare la crittografia quando si raccolgono o si trasferiscono dati sensibili, come quelli delle carte di credito o delle banche.<\/li>\n<li>Progettare le nostre misure di sicurezza dei dati per garantire la sicurezza, l'integrit\u00e0, la disponibilit\u00e0 e la resilienza dei sistemi e dei servizi di elaborazione.<\/li>\n<li>Limitare l'accesso fisico ai nostri locali<\/li>\n<li>Limitare l'accesso ai dati personali che raccogliamo su di voi<\/li>\n<li>Garantire che i nostri partner commerciali dispongano di misure di sicurezza tecniche e organizzative adeguate per mantenere i vostri dati personali protetti.<\/li>\n<li>Distruggere, pseudonimizzare o de-identificare i dati personali come richiesto dagli obblighi contrattuali e dalla legge.<\/li>\n<\/ul>\n<p>Seguiamo gli standard generalmente accettati per proteggere i vostri dati personali. Tuttavia, nessun metodo di raccolta, archiviazione o trasmissione \u00e8 100% sicuro. L'utente \u00e8 l'unico responsabile della protezione della propria password, della limitazione dell'accesso ai propri dispositivi e della disconnessione dai siti web al termine delle sessioni. <\/p>\n<p>Vi invitiamo a mantenere riservate le password che utilizzate e a fare attenzione a evitare le truffe di \"phishing\", in cui qualcuno pu\u00f2 inviarvi un'e-mail che sembra provenire da RSA e che vi chiede informazioni personali. RSA non richieder\u00e0 il vostro ID o la vostra password tramite e-mail.<\/p>\n<h4>11. Siti collegati<\/h4>\n<p>Per comodit\u00e0, sui nostri siti web possono essere presenti collegamenti ipertestuali che rimandano ad altri siti web. Non siamo responsabili e la presente Informativa sulla privacy non si applica alle pratiche sulla privacy dei siti web collegati o delle societ\u00e0 che non possediamo o controlliamo. I siti web collegati possono raccogliere informazioni in aggiunta a quelle raccolte da noi.<\/p>\n<p>Non approviamo nessuno di questi siti web collegati, i loro prodotti, i loro servizi o qualsiasi contenuto dei loro siti web. Vi invitiamo a cercare e leggere l'Informativa sulla privacy di ogni sito web collegato che visitate per capire come vengono utilizzate e protette le informazioni raccolte su di voi.<\/p>\n<h4>12. Informazioni sulla legge sulla privacy dei consumatori della California<\/h4>\n<p>La legge sulla privacy dei consumatori della California (CCPA) impone alle aziende di dichiarare se vendono dati personali, che la CCPA chiama \"informazioni personali\".  Ai fini della presente Sezione 12, per \"dati personali\" si intendono tutte le \"informazioni personali\" come definite dal CCPA. <\/p>\n<p>In quanto azienda soggetta al CCPA, non vendiamo dati personali in cambio di un corrispettivo in denaro. Possiamo condividere i dati personali con altri o consentire loro di raccogliere dati personali dai nostri siti web o servizi se si tratta di affiliati, terze parti da noi autorizzate o partner commerciali che hanno accettato i nostri requisiti contrattuali in materia di conservazione, utilizzo e divulgazione dei dati personali, oppure se utilizzate i nostri prodotti o servizi per interagire con terze parti o ci dite di divulgare i vostri dati personali a terze parti. <\/p>\n<p>In caso di conflitto tra la presente Sezione 12 e il resto della nostra Informativa sulla privacy, i termini della Sezione 12 prevarranno per quanto riguarda i dati personali dei residenti in California soggetti al CCPA.<\/p>\n<h5>12.1 Categorie di dati personali divulgati<\/h5>\n<p>Il CCPA ci impone di specificare le categorie di dati personali che divulghiamo per determinati scopi commerciali. Nei dodici (12) mesi precedenti, potremmo aver raccolto le seguenti categorie di dati personali:<\/p>\n<ul>\n<li>Identificatori: nome, indirizzo postale, indirizzo e-mail, indirizzo IP e altri identificatori simili.<\/li>\n<li>Informazioni commerciali: registrazioni di prodotti e servizi acquistati e altre storie o tendenze dei consumatori.<\/li>\n<li>informazioni sull'attivit\u00e0 in Internet o in rete: cronologia di navigazione o di ricerca, interazione con i nostri siti web<\/li>\n<li>Dati di geolocalizzazione: posizione fisica di un dispositivo connesso a Internet.<\/li>\n<li>Informazioni finanziarie: numero di conto corrente, numero di carta di credito e altri dati finanziari simili.<\/li>\n<li>Informazioni professionali e relative all'occupazione: storia lavorativa, titoli di lavoro<\/li>\n<li>Inferenze tratte da una qualsiasi di queste categorie<\/li>\n<\/ul>\n<h5>12.2 Finalit\u00e0 commerciali<\/h5>\n<p>Nei dodici (12) mesi precedenti, potremmo aver raccolto ed elaborato i vostri dati personali per vari scopi commerciali, tra cui: <\/p>\n<ul>\n<li>Esecuzione di servizi professionali<\/li>\n<li>Vendere un prodotto<\/li>\n<li>Rilevare gli incidenti di sicurezza e proteggere da attivit\u00e0 dannose, ingannevoli, fraudolente o illegali.<\/li>\n<li>Debug per identificare e riparare gli errori che compromettono la funzionalit\u00e0.<\/li>\n<li>Intraprendere attivit\u00e0 per verificare o mantenere la qualit\u00e0 o la sicurezza dei nostri prodotti e servizi, e per migliorare, aggiornare o potenziare i nostri prodotti e servizi.<\/li>\n<\/ul>\n<p>Nei dodici (12) mesi precedenti, potremmo aver condiviso i dati personali dell'utente con le nostre affiliate, i venditori e i fornitori che forniscono servizi per nostro conto, e con altre terze parti quali partner commerciali, reti pubblicitarie, fornitori di servizi Internet, fornitori di analisi dei dati, sistemi e piattaforme operative, fornitori di servizi di verifica dell'identit\u00e0, enti normativi e autorit\u00e0 governative.<\/p>\n<h5>12.3 Diritti CCPA<\/h5>\n<p>Le leggi della California garantiscono ai residenti dello Stato alcuni diritti in determinate circostanze in relazione ai loro dati personali:<\/p>\n<ul>\n<li>Diritto all'Opt-Out della vendita: non vendiamo i vostri dati personali a titolo oneroso. Tuttavia, condividiamo i dati personali, il che potrebbe essere considerato una \"vendita\" secondo la definizione fornita dal CCPA. Avete il diritto di chiederci di non vendere i vostri dati personali comunicandolo a <a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a>. Possiamo comunque utilizzare dati personali aggregati, pseudonimizzati e de-identificati che non identificano l'utente o qualsiasi altra persona. Possiamo inoltre conservare i dati personali dell'utente se necessario per adempiere ai nostri obblighi legali, per far rispettare gli accordi e per risolvere le controversie.<\/li>\n<li>Diritto di accesso: l'utente pu\u00f2 richiedere informazioni sulla raccolta e sull'utilizzo da parte nostra dei suoi dati personali negli ultimi dodici (12) mesi. Ci\u00f2 include le categorie di dati personali che abbiamo venduto o divulgato per uno scopo commerciale su di voi e le categorie di terze parti a cui i dati personali sono stati venduti o divulgati. Questo include il diritto di richiedere la divulgazione di parti specifiche dei vostri dati personali, quali:\n<ul>\n<li>Le categorie di dati personali che abbiamo raccolto su di voi<\/li>\n<li>Le categorie o le fonti da cui abbiamo raccolto i dati personali<\/li>\n<li>Lo scopo aziendale o commerciale per la raccolta o la vendita dei dati personali<\/li>\n<li>Le categorie di terzi con cui condividiamo i dati personali<\/li>\n<li>I dati personali specifici che abbiamo raccolto su di lei<\/li>\n<li>Le categorie di dati personali che abbiamo divulgato su di voi per una finalit\u00e0 commerciale<\/li>\n<li>Le categorie di dati personali che abbiamo venduto su di lei<\/li>\n<li>Le categorie di terzi a cui abbiamo venduto i dati personali<\/li>\n<\/ul>\n<p>Le informazioni possono essere fornite per posta o per via elettronica. Se vengono fornite elettronicamente, saranno trasportabili e in un formato facilmente utilizzabile in modo da poterle trasmettere a un'altra entit\u00e0 o persona.<\/li>\n<li>Diritto di richiedere la cancellazione: l'utente pu\u00f2 richiedere la cancellazione dei dati personali raccolti. Non cancelleremo i dati personali se ci\u00f2 creer\u00e0 problemi con il completamento di una transazione o l'adempimento di un obbligo legale. Questo diritto di richiedere la cancellazione \u00e8 soggetto al nostro diritto di mantenere i vostri dati personali per scopi specifici consentiti dalla CCPA. <\/li>\n<li class=\"translation-block\"><strong>Diritto alla non discriminazione<\/strong>: non discrimineremo mai l'utente negandogli beni o servizi o fornendogli un livello o una qualit\u00e0 diversi se esercita uno dei diritti che gli sono stati riconosciuti.<\/li>\n<\/ul>\n<h5>12.4 Come gestiamo le vostre richieste<\/h5>\n<p>Nell'ambito dell'elaborazione della vostra richiesta, vi chiederemo di fornire alcuni dati personali che vi riguardano per verificare la vostra identit\u00e0 in conformit\u00e0 ai requisiti della CCPA. Tali informazioni possono includere nome e cognome, indirizzo e-mail, indirizzo fisico, numero di telefono, numero di conto e la natura del vostro rapporto con noi.<\/p>\n<p>L'utente pu\u00f2 anche designare un agente autorizzato ad effettuare una richiesta per suo conto. Per soddisfare tale richiesta, richiederemo i dati personali di cui sopra ai fini della verifica dell'identificazione, nonch\u00e9 il nome e il cognome, l'indirizzo e-mail e il numero di telefono dell'agente autorizzato.<\/p>\n<p>Una volta verificata la richiesta, faremo il possibile per rispondere entro quarantacinque (45) giorni. Se dovessimo avere bisogno di pi\u00f9 tempo, vi informeremo per iscritto del motivo e del periodo di proroga. Se non possiamo soddisfare la vostra richiesta, vi risponderemo per iscritto indicandone i motivi.<\/p>\n<p>Qualsiasi divulgazione riguarder\u00e0 solo il periodo di dodici (12) mesi precedente il ricevimento della richiesta. <\/p>\n<p>Non addebitiamo alcun costo per l'elaborazione o la risposta alle vostre richieste, a meno che non si tratti di richieste eccessive, ripetitive o manifestamente infondate. Se riteniamo che la vostra richiesta richieda il pagamento di una tariffa, ve ne comunicheremo il motivo per iscritto, insieme a un preventivo di spesa, prima di completare la vostra richiesta.<\/p>\n<p>\u00c8 possibile presentare una richiesta di accesso ai dati personali solo per due (2) volte in un periodo di dodici (12) mesi.<\/p>\n<h5>12,5 Residenti sotto i 18 anni<\/h5>\n<p>Se l'utente \u00e8 residente in California e ha meno di diciotto (18) anni e si \u00e8 registrato per un account con noi, pu\u00f2 richiedere la rimozione di contenuti o informazioni che ha pubblicato sui nostri siti web. Questa richiesta non garantisce la rimozione completa del contenuto o delle informazioni, poich\u00e9 alcuni dei vostri contenuti potrebbero essere stati ripubblicati da un altro utente.<\/p>\n<h4>13. Modifiche alla presente Informativa sulla privacy<\/h4>\n<p>Aggiorneremo periodicamente la presente Informativa sulla privacy per riflettere le modifiche apportate alle nostre pratiche, alle tecnologie e ai requisiti legali. Aggiorneremo la data di entrata in vigore alla fine di questo documento.<\/p>\n<p>Se effettuiamo un aggiornamento sostanziale, possiamo informarvi prima che l'aggiornamento entri in vigore pubblicando un avviso sui nostri siti web o contattandovi direttamente. Se possibile, chiederemo il consenso dell'utente a tali modifiche, ove richiesto dalla legge applicabile.<\/p>\n<p>Vi invitiamo a rivedere periodicamente la presente Informativa sulla privacy per rimanere informati sulla nostra raccolta, elaborazione e condivisione dei vostri dati personali. <\/p>\n<p>L'accesso o l'utilizzo del Sito, in qualsiasi modo, sar\u00e0 considerato come accettazione della presente Informativa sulla privacy.<\/p>\n<h4>14. Strumento di screening COVID-19 e telecamera di visione termica<\/h4>\n<p>Per contribuire a ridurre il rischio di infezioni da COVID-19 e mantenere sicure le nostre comunit\u00e0, tutti i dipendenti, i lavoratori temporanei e i visitatori della RSA devono completare un'indagine giornaliera sullo stato di salute e superare uno screening termico della temperatura corporea per poter accedere ai locali della RSA. La termocamera misura la temperatura corporea in modo anonimo e la RSA non conserva la temperatura corporea. Se la temperatura corporea \u00e8 pari o superiore a 100 gradi Fahrenheit, vi sar\u00e0 negato l'ingresso e\/o vi sar\u00e0 chiesto di lasciare i locali della RSA.<\/p>\n<p>Lo strumento di screening dell'indagine sulla salute, disponibile tramite un'app o un portale web, raccoglie il nome, l'indirizzo e-mail e alcuni dati sulla salute forniti volontariamente. Queste informazioni saranno conservate sul dispositivo dell'utente e non saranno condivise con la RSA, a meno che l'utente non dichiari di essere positivo al COVID-19. In tal caso, lo strumento informer\u00e0 il team competente e l'indirizzo e-mail dell'utente sar\u00e0 comunicato alla RSA. In tal caso, lo strumento informer\u00e0 il team RSA competente e l'indirizzo e-mail dell'utente sar\u00e0 conservato per un massimo di 30 giorni (in base alle leggi locali), in modo che RSA possa contattarlo quando intraprende azioni appropriate per proteggere la salute e la sicurezza degli individui presso le sedi fisiche di RSA. Il vostro stato di positivit\u00e0 al COVID-19 sar\u00e0 condiviso con il team della RSA e con le autorit\u00e0 sanitarie pubbliche applicabili (come richiesto dalla legge). Il vostro stato sar\u00e0 inoltre condiviso in forma anonima con persone potenzialmente infette per la ricerca di contatti.<\/p>\n<h4>15. Notifica di problemi di violazione di copyright<\/h4>\n<p>Se un Utente ritiene che il proprio lavoro protetto da copyright sia stato copiato e sia accessibile sui siti web della RSA in un modo che costituisce una violazione del copyright, \u00e8 pregato di inviare una comunicazione a:<\/p>\n<p>RSA Security LLC<br \/>\nAttenzione: RSA Legal<br \/>\n176 Middlesex Turnpike<br \/>\nBedford, MA 01730<br \/>\nE-mail: <a href=\"mailto:Legalnotices@rsa.com\" rel=\"noopener\" target=\"_blank\">Legalnotices@rsa.com <\/a><\/p>\n<p>Gli avvisi devono includere ciascuno dei seguenti elementi:<\/p>\n<ol>\n<li>La firma elettronica o fisica del titolare del diritto esclusivo che si presume violato, o la firma elettronica o fisica di una persona autorizzata ad agire per conto del titolare;<\/li>\n<li>Identificazione dell'opera protetta da copyright che si ritiene sia stata violata o, se pi\u00f9 opere protette da copyright in un singolo sito online sono coperte da un'unica notifica, un elenco rappresentativo di tali opere in quel sito;<\/li>\n<li>Identificazione del materiale, che si sostiene essere in violazione o oggetto di attivit\u00e0 di violazione, per il quale si richiede la disabilitazione dell'accesso o la rimozione, e informazioni ragionevolmente sufficienti a permetterci di individuare il materiale;<\/li>\n<li>Se la violazione contestata \u00e8 dovuta all'archiviazione intermedia e temporanea o alla memorizzazione nella cache del materiale, includere anche una dichiarazione che confermi che il materiale in violazione \u00e8 stato rimosso dal sito di origine o che l'accesso ad esso \u00e8 stato disabilitato o che un tribunale ha ordinato che il materiale sia rimosso o che l'accesso a tale materiale sia disabilitato;<\/li>\n<li>Se la violazione contestata \u00e8 dovuta al rinvio o al collegamento degli utenti a un sito online contenente materiale o attivit\u00e0 in violazione, utilizzando strumenti di localizzazione delle informazioni, invece dell'identificazione di cui ai paragrafi (3) o (4), fornire l'identificazione del riferimento o del collegamento al materiale o all'attivit\u00e0 contestata che deve essere rimossa o il cui accesso deve essere disabilitato, nonch\u00e9 informazioni ragionevolmente sufficienti a consentirci di individuare tale riferimento o collegamento;<\/li>\n<li>Informazioni ragionevolmente sufficienti per permetterci di contattarvi, come ad esempio un indirizzo, un numero di telefono e, se disponibile, un indirizzo di posta elettronica al quale potete essere contattati;<\/li>\n<li>Una dichiarazione in cui si afferma di ritenere in buona fede che l'uso del materiale nel modo contestato non \u00e8 autorizzato dal titolare del copyright, dal suo agente o dalla legge,<\/li>\n<li>Una dichiarazione che le informazioni contenute nella notifica sono accurate e, sotto pena di spergiuro, che siete autorizzati ad agire per conto del titolare di un diritto esclusivo che \u00e8 stato presumibilmente violato.<\/li>\n<\/ol>\n<h4>16. Politica di utilizzo accettabile<\/h4>\n<h5>16.1 In generale<\/h5>\n<p>La Politica di utilizzo accettabile (\"AUP\") di RSA e delle sue affiliate ha lo scopo di promuovere un utilizzo responsabile dell'infrastruttura, delle reti, delle offerte basate su cloud, dei sistemi, dei servizi, dei siti web, delle strutture e dei prodotti di RSA (collettivamente, l'\"Infrastruttura e i Servizi di RSA\") da parte dei nostri clienti e di altri utenti. Gli utenti acconsentono a essere vincolati dai termini della presente AUP. RSA si riserva il diritto di modificare la presente AUP a sua discrezione in qualsiasi momento. Le modifiche entreranno in vigore al momento della pubblicazione e gli utenti sono tenuti a controllare questa pagina di tanto in tanto per prendere atto di eventuali modifiche apportate, in quanto legalmente vincolanti per ciascun utente. L'utilizzo dei siti Web di RSA da parte degli utenti dopo le modifiche apportate costituisce l'accettazione delle nostre modifiche.<\/p>\n<h5>16.2 Sospensione; cessazione<\/h5>\n<p>Se RSA stabilisce che un Utente ha violato una qualsiasi parte della presente AUP, RSA pu\u00f2 interrompere l'utilizzo del sito web da parte dell'Utente. RSA sospender\u00e0 il servizio per violazione dell'AUP sulla base pi\u00f9 limitata possibile, come RSA ritiene sia ragionevolmente pratico, date le circostanze, per affrontare la violazione sottostante. RSA cercher\u00e0 di avvisare l'Utente prima di sospendere il servizio per violazione dell'AUP (tramite e-mail o qualsiasi altra notifica). Tuttavia, RSA pu\u00f2 sospendere il servizio senza preavviso nel caso in cui venga a conoscenza di una violazione della presente AUP o di qualsiasi legge o regolamento applicabile che esponga RSA a responsabilit\u00e0 penale o civile, o che esponga RSA o qualsiasi propriet\u00e0 di terzi a danni. Il danno pu\u00f2 includere, a titolo esemplificativo, il rischio di inserimento di uno o pi\u00f9 indirizzi IP in liste nere. RSA pu\u00f2 intraprendere qualsiasi altra azione ritenuta appropriata dalle circostanze per eliminare o impedire violazioni ripetute. RSA non \u00e8 responsabile per alcun tipo di danno che gli Utenti o i terzi possono subire derivante in tutto o in parte dall'esercizio da parte di RSA dei propri diritti ai sensi della presente AUP. Questa esclusione di responsabilit\u00e0 non include la responsabilit\u00e0 di RSA per morte o lesioni personali causate dalla sua negligenza, o qualsiasi altra responsabilit\u00e0 che RSA non pu\u00f2 escludere o limitare per legge.<\/p>\n<h4>17. App mobile RSA<\/h4>\n<p class=\"translation-block\">Per saperne di pi\u00f9 sulle informazioni che possiamo trattare durante l'utilizzo della nostra SecurID Mobile App, <a href=\"\/wp-content\/uploads\/securid-mobile-application-privacy.pdf\" target=\"_blank\" rel=\"noopener\">cliccare qui<\/a>.<\/p>\n<h4>18. Autenticazione tramite messaggio di testo (SMS) RSA<\/h4>\n<p class=\"translation-block\">Per saperne di pi\u00f9 sulle informazioni che possiamo trattare durante l'uso dell'autenticazione OTP (one-time passcode) basata su messaggi di testo, <a href=\"\/wp-content\/uploads\/securid-sms-authentication-privacy.pdf\" target=\"_blank\" rel=\"noopener\">cliccare qui<\/a>.<\/p>\n<h4>19. Varie<\/h4>\n<p class=\"translation-block\">Per conoscere ulteriori informazioni importanti sulle Condizioni d'uso di questo sito web, <a href=\"https:\/\/www.rsa.com\/it\/terms-of-use\/\" target=\"_self\">cliccare qui<\/a>.<br>\r\nQuesto sito web pu\u00f2 contenere link o frame di altri siti web, che possono o meno essere affiliati alla RSA. Questi link e frame sono disponibili al solo scopo di fornire ulteriori vantaggi agli utenti. L'inclusione di questi link e frame non significa che la RSA sia a conoscenza, concordi o sia responsabile per essi o per il loro contenuto. Pertanto, la RSA non pu\u00f2 essere ritenuta responsabile di eventuali perdite o danni subiti in seguito all'utilizzo di tali link o frame.<\/p>\n<h4>20. Contattarci<\/h4>\n<p class=\"translation-block\">Per esercitare i propri diritti in merito ai dati personali, o in caso di domande sulla presente Informativa sulla privacy o sulle nostre pratiche in materia di privacy, \u00e8 possibile inviare un'e-mail all'indirizzo <a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a> o scriverci all'indirizzo:<br>\r\nRSA Security LLC<br>\r\nAttenzione: Ufficio legale - Privacy<br>\r\n176 Middlesex Turnpike<br>\r\nBedford, MA 01730 USA<\/p>\n<p>Si prega di notare che la vostra richiesta pu\u00f2 avere delle limitazioni, in base alla legge applicabile.<\/p>\n<p><strong>Data di entrata in vigore: 27 luglio 2022.<\/strong><\/p>\n<p>Precedente Informativa sulla privacy:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-january-2022\/\">Gennaio 2022<\/a><\/li>\n<\/ul>\n<p><strong>\u00a92022 RSA Security LLC o le sue affiliate. Tutti i diritti riservati. Il logo della conferenza RSA, RSA e altri marchi sono marchi di RSA Security LLC o delle sue affiliate. Altri marchi possono essere marchi dei rispettivi proprietari.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Introduzione La vostra privacy \u00e8 importante per RSA Security LLC, pertanto abbiamo sviluppato questa Informativa sulla privacy che illustra le nostre prassi in materia di trattamento, raccolta, utilizzo e condivisione dei vostri dati personali, nonch\u00e9 i vostri diritti in materia di privacy ai sensi di alcune leggi sulla privacy. Possiamo fornire ulteriori informazioni sulla privacy dei dati utilizzando una o pi\u00f9 informative supplementari sulla privacy. ... <a href=\"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/\">Continua<\/a><\/p>","protected":false},"author":2,"featured_media":0,"parent":3,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-policy.blade.php","meta":{"_acf_changed":false,"_searchwp_excluded":"","inline_featured_image":false,"footnotes":""},"class_list":["post-24430","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - July 2022 - RSA<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - July 2022 - RSA\" \/>\n<meta property=\"og:description\" content=\"Introduction Your privacy is important to RSA Security LLC so we have developed this Privacy Policy that outlines our privacy practice on how we process, collect, use and share your personal data as well as your privacy rights under certain privacy laws. We may provide additional data privacy information by using a supplementary privacy notice(s). &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"RSA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-07T20:58:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/privacy\\\/privacy-policy-july-2022\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/privacy\\\/privacy-policy-july-2022\\\/\",\"name\":\"Privacy Policy - July 2022 - RSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\"},\"datePublished\":\"2023-01-12T20:33:49+00:00\",\"dateModified\":\"2025-02-07T20:58:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/privacy\\\/privacy-policy-july-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rsa.com\\\/it\\\/privacy\\\/privacy-policy-july-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/privacy\\\/privacy-policy-july-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/it\\\/privacy\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Privacy Policy &#8211; July 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"name\":\"RSA\",\"description\":\"Cybersecurity and Digital Risk Management Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rsa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\",\"name\":\"RSA\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"width\":2880,\"height\":1020,\"caption\":\"RSA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informativa sulla privacy - Luglio 2022 - RSA","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Privacy Policy - July 2022 - RSA","og_description":"Introduction Your privacy is important to RSA Security LLC so we have developed this Privacy Policy that outlines our privacy practice on how we process, collect, use and share your personal data as well as your privacy rights under certain privacy laws. We may provide additional data privacy information by using a supplementary privacy notice(s). &hellip; Continued","og_url":"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/","og_site_name":"RSA","article_modified_time":"2025-02-07T20:58:34+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/","url":"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/","name":"Informativa sulla privacy - Luglio 2022 - RSA","isPartOf":{"@id":"https:\/\/www.rsa.com\/#website"},"datePublished":"2023-01-12T20:33:49+00:00","dateModified":"2025-02-07T20:58:34+00:00","breadcrumb":{"@id":"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rsa.com\/it\/privacy\/privacy-policy-july-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rsa.com\/it\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy","item":"https:\/\/www.rsa.com\/it\/privacy\/"},{"@type":"ListItem","position":3,"name":"Privacy Policy &#8211; July 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.rsa.com\/#website","url":"https:\/\/www.rsa.com\/","name":"RSA","description":"Soluzioni di cybersecurity e di gestione del rischio digitale","publisher":{"@id":"https:\/\/www.rsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rsa.com\/#organization","name":"RSA","url":"https:\/\/www.rsa.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","width":2880,"height":1020,"caption":"RSA"},"image":{"@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages\/24430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/comments?post=24430"}],"version-history":[{"count":3,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages\/24430\/revisions"}],"predecessor-version":[{"id":24604,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages\/24430\/revisions\/24604"}],"up":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/pages\/3"}],"wp:attachment":[{"href":"https:\/\/www.rsa.com\/it\/wp-json\/wp\/v2\/media?parent=24430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}