{"id":24430,"date":"2023-01-12T15:33:49","date_gmt":"2023-01-12T20:33:49","guid":{"rendered":"https:\/\/www.rsa.com\/?page_id=24430"},"modified":"2025-02-07T15:58:34","modified_gmt":"2025-02-07T20:58:34","slug":"privacy-policy-july-2022","status":"publish","type":"page","link":"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/","title":{"rendered":"Politique de confidentialit\u00e9 - Juillet 2022"},"content":{"rendered":"<h4>Introduction<\/h4>\n<p>Votre vie priv\u00e9e est importante pour RSA Security LLC, c'est pourquoi nous avons \u00e9labor\u00e9 cette politique de confidentialit\u00e9 qui d\u00e9crit nos pratiques en mati\u00e8re de confidentialit\u00e9 sur la fa\u00e7on dont nous traitons, collectons, utilisons et partageons vos donn\u00e9es personnelles, ainsi que vos droits en mati\u00e8re de confidentialit\u00e9 en vertu de certaines lois sur la protection de la vie priv\u00e9e. Nous pouvons fournir des informations suppl\u00e9mentaires sur la confidentialit\u00e9 des donn\u00e9es en utilisant un ou plusieurs avis de confidentialit\u00e9 suppl\u00e9mentaires. <\/p>\n<p>Dans la pr\u00e9sente politique de confidentialit\u00e9, \"RSA\", \"notre\", \"nos\" ou \"nous\" d\u00e9signe RSA Security LLC et ses filiales concern\u00e9es par la collecte, l'utilisation, le partage ou le traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel. <\/p>\n<p>L'ASR s'engage \u00e0 prot\u00e9ger la confidentialit\u00e9 et la s\u00e9curit\u00e9 de toutes les donn\u00e9es personnelles que nous recueillons lorsque vous acc\u00e9dez, utilisez ou interagissez avec nous via nos sites web, nos communications marketing et les donn\u00e9es personnelles que nous traitons afin de fournir des services \u00e0 nos clients. Nous recevons peu de donn\u00e9es personnelles de la part de nos clients.<\/p>\n<p>La pr\u00e9sente politique de confidentialit\u00e9 ne s'applique pas<\/p>\n<ul>\n<li class=\"translation-block\">Nous avons mis en place un <a href=\"https:\/\/www.rsa.com\/fr_ca\/standard-form-agreements\/\" target=\"_self\">Data Processing Addendum (DPA)<\/a> qui d\u00e9crit la mani\u00e8re dont nous traitons les donn\u00e9es \u00e0 caract\u00e8re personnel de nos clients.<\/li>\n<li>les donn\u00e9es qui ne sont pas personnelles, y compris les donn\u00e9es anonymes et agr\u00e9g\u00e9es ; et,<\/li>\n<li>des informations relatives \u00e0 nos candidats \u00e0 l'emploi.<\/li>\n<\/ul>\n<p>La pr\u00e9sente politique de confidentialit\u00e9 est destin\u00e9e \u00e0 s'appliquer dans la mesure o\u00f9 RSA traite vos donn\u00e9es en tant que contr\u00f4leur de donn\u00e9es. Elle n'est pas destin\u00e9e \u00e0 s'appliquer lorsque RSA traite vos donn\u00e9es en tant que processeur de donn\u00e9es pour le compte de nos clients. Elle ne s'applique pas non plus aux informations qui ont \u00e9t\u00e9 agr\u00e9g\u00e9es, d\u00e9personnalis\u00e9es ou pseudonymis\u00e9es.<\/p>\n<h4>1. Les informations que nous collectons<\/h4>\n<p>Nous collectons des \"donn\u00e9es \u00e0 caract\u00e8re personnel\", c'est-\u00e0-dire des informations relatives \u00e0 une personne qui peut \u00eatre identifi\u00e9e, directement ou indirectement, par r\u00e9f\u00e9rence \u00e0 un identifiant, tel qu'un nom, un num\u00e9ro d'identification, des donn\u00e9es de localisation ou un identifiant en ligne.<\/p>\n<h5>1.1 Informations recueillies aupr\u00e8s de vous<\/h5>\n<p>Les types d'informations que nous recueillons \u00e0 votre sujet d\u00e9pendent de l'utilisation que vous faites de nos produits et services et de la mani\u00e8re dont vous interagissez avec nous, ainsi que des informations que nous obtenons de tiers. Il peut s'agir d'informations concernant<\/p>\n<ul>\n<li>Les informations de contact, telles que votre nom, votre pays, votre adresse \u00e9lectronique, votre num\u00e9ro de t\u00e9l\u00e9phone, votre fuseau horaire et votre adresse postale.<\/li>\n<li>Des informations professionnelles telles que votre titre de poste, votre niveau de poste, votre r\u00f4le\/fonction et d'autres informations relatives \u00e0 l'entreprise ou \u00e0 la soci\u00e9t\u00e9.<\/li>\n<li>Informations sur les int\u00e9r\u00eats, telles que les produits ou services que vous achetez, les activit\u00e9s associ\u00e9es \u00e0 votre compte et vos pr\u00e9f\u00e9rences.<\/li>\n<li>Les informations que vous fournissez dans nos formulaires web (les formulaires que vous choisissez de remplir indiqueront si les informations demand\u00e9es sont obligatoires ou volontaires).<\/li>\n<li>Les cookies et les informations de suivi lorsque vous interagissez avec nos sites web comprennent votre type de navigateur, votre adresse IP, Pixel ID, le num\u00e9ro d'identification unique de votre appareil, le syst\u00e8me d'exploitation, le type d'appareil et la version, les param\u00e8tres linguistiques, les pages web que vous consultez, le temps que vous passez sur les pages, l'URL du site web qui vous a renvoy\u00e9 sur nos pages, vos informations g\u00e9ographiques d\u00e9riv\u00e9es de votre adresse IP, d'autres informations techniques et tous les liens hypertextes ou publicit\u00e9s que vous s\u00e9lectionnez.<\/li>\n<li>Les informations de r\u00e9f\u00e9rence du navigateur sur les sites web qui vous ont amen\u00e9 \u00e0 nous rendre visite.<\/li>\n<li>Rapports d'erreur et informations sur les performances des produits et les probl\u00e8mes que vous rencontrez, y compris les rapports d'erreur.<\/li>\n<li>Informations sur la consommation de contenu concernant le contenu m\u00e9diatique (par ex. t\u00e9l\u00e9vision, applications et jeux) auquel vous acc\u00e9dez par le biais de nos offres.<\/li>\n<li>Les informations que vous nous fournissez, telles que les r\u00e9ponses aux enqu\u00eates aupr\u00e8s des clients et les \u00e9valuations de produits que vous r\u00e9digez, \u00e0 moins qu'elles ne soient anonymes.<\/li>\n<li>Les informations provenant de sources tierces peuvent inclure des donn\u00e9es personnelles pour compl\u00e9ter les informations que nous avons collect\u00e9es \u00e0 votre sujet.<\/li>\n<li>Sites web et liens de tiers. Nous pouvons fournir des liens vers d'autres sites web qui, si vous cliquez dessus, peuvent collecter des informations vous concernant et vous diriger vers ces sites web. Les pratiques en mati\u00e8re d'information de ces sites web tiers li\u00e9s \u00e0 notre site web sont couvertes par les propres politiques\/d\u00e9clarations de confidentialit\u00e9 de ces tiers et nous vous encourageons \u00e0 les lire.<\/li>\n<li>Les informations d'identification telles que les indices de mot de passe et les informations de s\u00e9curit\u00e9 similaires utilis\u00e9es pour l'authentification et l'acc\u00e8s \u00e0 MyAccount.<\/li>\n<li>Des informations d\u00e9mographiques telles que votre \u00e2ge, votre sexe, votre pays, vos int\u00e9r\u00eats et vos pr\u00e9f\u00e9rences.<\/li>\n<li>Les informations de paiement pour traiter les paiements, telles que votre num\u00e9ro d'instrument de paiement (comme un num\u00e9ro de carte de cr\u00e9dit) et le code de s\u00e9curit\u00e9 associ\u00e9 \u00e0 votre instrument de paiement.<\/li>\n<li>Informations de d\u00e9pannage et d'aide lorsque vous contactez RSA pour une assistance technique ou des services d'assistance \u00e0 la client\u00e8le, les conversations t\u00e9l\u00e9phoniques ou les sessions de chat avec nos repr\u00e9sentants peuvent \u00eatre surveill\u00e9es et enregistr\u00e9es.<\/li>\n<li>Les informations n\u00e9cessaires pour que nous puissions vous fournir des services.<\/li>\n<li>Toute autre donn\u00e9e personnelle que vous choisissez de partager avec nous.<\/li>\n<\/ul>\n<h5>1.2 Cat\u00e9gories sp\u00e9ciales de donn\u00e9es \u00e0 caract\u00e8re personnel<\/h5>\n<p>Nous ne collectons pas intentionnellement des cat\u00e9gories particuli\u00e8res de donn\u00e9es \u00e0 caract\u00e8re personnel, qui comprennent des informations sensibles telles que :<\/p>\n<ul>\n<li>Origine raciale ou ethnique<\/li>\n<li>Opinions politiques<\/li>\n<li>Croyances religieuses ou philosophiques<\/li>\n<li>Adh\u00e9sion \u00e0 un syndicat<\/li>\n<li>Donn\u00e9es g\u00e9n\u00e9tiques<\/li>\n<li>Donn\u00e9es biom\u00e9triques<\/li>\n<li>Sant\u00e9 ou \u00e9tat physique ou mental<\/li>\n<li>Vie sexuelle ou orientation sexuelle<\/li>\n<\/ul>\n<p>Vous n'\u00eates pas tenu de fournir ces informations et vous ne devriez pas les divulguer, car nous n'avons pas l'intention de traiter des informations sensibles. Toutefois, si vous les divulguez, vous reconnaissez que vous consentez \u00e0 ce que nous collections et traitions ces cat\u00e9gories sp\u00e9ciales de donn\u00e9es.<\/p>\n<h4>2. Comment nous collectons vos donn\u00e9es personnelles<\/h4>\n<p>Les types de donn\u00e9es personnelles que nous recueillons \u00e0 votre sujet d\u00e9pendent de votre utilisation de nos produits et services et de la mani\u00e8re dont vous interagissez avec nous.<\/p>\n<h5>2.1 Donn\u00e9es personnelles collect\u00e9es directement aupr\u00e8s de vous<\/h5>\n<p>Nous vous demandons et collectons des donn\u00e9es \u00e0 caract\u00e8re personnel dans les cas suivants :<\/p>\n<ul>\n<li>Lorsque vous manifestez de l'int\u00e9r\u00eat pour nos produits et services et que vous demandez des informations compl\u00e9mentaires ; lorsque vous demandez une d\u00e9monstration ; lorsque vous demandez une assistance \u00e0 la client\u00e8le ; lorsque vous utilisez notre page Contactez-nous ; lorsque vous vous inscrivez pour recevoir des communications de notre part ; lorsque vous participez \u00e0 un programme ou \u00e0 une enqu\u00eate ; lorsque vous t\u00e9l\u00e9chargez du contenu \u00e0 partir de nos sites web ; lorsque vous \u00eates un utilisateur autoris\u00e9 de nos produits et services.<\/li>\n<ul>\n<li>Nous pouvons recueillir votre nom, votre fonction, le nom de votre entreprise, votre adresse, votre pays, votre num\u00e9ro de t\u00e9l\u00e9phone, votre adresse \u00e9lectronique, votre nom d'utilisateur et votre mot de passe.<\/li>\n<\/ul>\n<li>Lorsque vous effectuez un achat sur nos sites web.<\/li>\n<ul>\n<li>Nous pouvons recueillir votre nom, votre fonction, le nom de votre entreprise, votre adresse, votre pays, votre num\u00e9ro de t\u00e9l\u00e9phone, votre adresse \u00e9lectronique et des informations financi\u00e8res pour la facturation et le paiement, telles que le nom et l'adresse de facturation, l'instrument de paiement tel que le num\u00e9ro de carte de cr\u00e9dit et le code de s\u00e9curit\u00e9 associ\u00e9 \u00e0 votre instrument de paiement, ou les informations relatives \u00e0 votre compte bancaire. <\/li>\n<\/ul>\n<li>Lorsque vous vous inscrivez \u00e0 l'un de nos \u00e9v\u00e9nements.<\/li>\n<ul>\n<li>Nous pouvons recueillir votre nom, votre fonction, le nom de votre entreprise, votre adresse, votre pays, votre num\u00e9ro de t\u00e9l\u00e9phone, votre adresse \u00e9lectronique et des informations financi\u00e8res pour la facturation et le paiement, telles que le nom et l'adresse de facturation, l'instrument de paiement tel que le num\u00e9ro de carte de cr\u00e9dit et le code de s\u00e9curit\u00e9 associ\u00e9 \u00e0 votre instrument de paiement, ou les informations relatives \u00e0 votre compte bancaire. Si vous assistez \u00e0 un \u00e9v\u00e9nement en personne et que vous recevez un badge, nous pouvons scanner le badge et acc\u00e9der \u00e0 vos informations, telles que le nom, la fonction, le nom de l'entreprise, l'adresse, le pays, le num\u00e9ro de t\u00e9l\u00e9phone et l'adresse \u00e9lectronique. Nous pouvons \u00e9galement collecter votre image.<\/li>\n<\/ul>\n<li>Lorsque vous communiquez avec nous par t\u00e9l\u00e9phone.<\/li>\n<ul>\n<li>Nous pouvons recueillir des informations pour v\u00e9rifier votre identit\u00e9 et enregistrer l'appel \u00e0 des fins de formation, conform\u00e9ment aux lois applicables.<\/li>\n<\/ul>\n<li>Lorsque vous visitez nos bureaux.<\/li>\n<ul>\n<li>Nous pouvons recueillir votre nom, votre fonction, le nom de votre entreprise, votre adresse, votre pays, votre num\u00e9ro de t\u00e9l\u00e9phone, votre adresse \u00e9lectronique, ainsi que l'heure et la date de votre arriv\u00e9e. Nous pouvons \u00e9galement collecter votre image. <\/li>\n<\/ul>\n<li>Lorsque vous interagissez avec nos sites web ou nos courriels.<\/li>\n<ul>\n<li>Nous pouvons collecter des informations sur votre appareil, votre utilisation de nos sites web et\/ou de nos courriels en utilisant des cookies, des balises web ou d'autres technologies similaires.<\/li>\n<\/ul>\n<li>Lorsque vous interagissez avec nos produits et services.<\/li>\n<ul>\n<li>Nous pouvons collecter des informations sur l'historique de votre compte et les activit\u00e9s associ\u00e9es \u00e0 votre compte, telles que des informations sur votre appareil et votre utilisation de nos produits et services par le biais de fichiers journaux et d'autres technologies.<\/li>\n<\/ul>\n<li>Lorsque vous remplissez volontairement un formulaire en ligne, participez \u00e0 une enqu\u00eate, r\u00e9pondez \u00e0 un questionnaire ou partagez des donn\u00e9es avec nous dans le cadre d'une autre forme de recherche.<\/li>\n<ul>\n<li>Nous pouvons recueillir des informations que vous choisissez volontairement de fournir et toute information obligatoire que nous demandons.<\/li>\n<\/ul>\n<\/ul>\n<p> Si vous fournissez des donn\u00e9es \u00e0 caract\u00e8re personnel concernant une autre personne, vous d\u00e9clarez que vous \u00eates habilit\u00e9 \u00e0 le faire et, le cas \u00e9ch\u00e9ant, que vous avez obtenu le consentement n\u00e9cessaire pour partager ces donn\u00e9es. Vous reconnaissez que les donn\u00e9es personnelles de l'autre personne peuvent \u00eatre utilis\u00e9es conform\u00e9ment \u00e0 la pr\u00e9sente politique de confidentialit\u00e9.<\/p>\n<p class=\"translation-block\">Si vous pensez que vos donn\u00e9es personnelles nous ont \u00e9t\u00e9 fournies de mani\u00e8re inappropri\u00e9e, ou si vous souhaitez exercer vos droits relatifs \u00e0 vos donn\u00e9es personnelles, veuillez nous contacter \u00e0 l'adresse <a href=\"mailto:privacy@rsa.com\" target=\"_self\">privacy@rsa.com<\/a>.<\/p>\n<h5>2.2 Donn\u00e9es personnelles collect\u00e9es aupr\u00e8s d'autres personnes<\/h5>\n<p>Nous pouvons collecter vos donn\u00e9es personnelles \u00e0 partir d'autres sources telles que des informations accessibles au public et des sources tierces aupr\u00e8s desquelles nous achetons des donn\u00e9es personnelles. Les sources tierces peuvent changer au fil du temps et peuvent inclure :<\/p>\n<ul>\n<li>les courtiers en donn\u00e9es aupr\u00e8s desquels nous achetons des donn\u00e9es d\u00e9mographiques pour compl\u00e9ter les donn\u00e9es \u00e0 caract\u00e8re personnel que nous avons collect\u00e9es \u00e0 votre sujet<\/li>\n<li>les services de communication, y compris les fournisseurs de courrier \u00e9lectronique et les r\u00e9seaux sociaux, lorsque vous nous autorisez \u00e0 acc\u00e9der \u00e0 vos informations \u00e0 partir de ces services ou r\u00e9seaux tiers<\/li>\n<li>Les partenaires avec lesquels nous proposons des produits et services co-marqu\u00e9s, ou avec lesquels nous nous engageons dans des activit\u00e9s de marketing conjointes. <\/li>\n<\/ul>\n<p>Les donn\u00e9es personnelles peuvent inclure des identifiants, des informations professionnelles ou li\u00e9es \u00e0 l'emploi, des informations sur l'\u00e9ducation, des informations commerciales, des informations visuelles, des informations sur l'activit\u00e9 Internet, des profils de m\u00e9dias sociaux et des d\u00e9ductions sur les pr\u00e9f\u00e9rences et les comportements. Nous pouvons combiner des informations provenant d'autres sources avec les donn\u00e9es personnelles que vous nous avez fournies.<\/p>\n<p>Ces donn\u00e9es nous permettent de mettre \u00e0 jour nos dossiers, d'identifier de nouveaux clients et de cr\u00e9er des publicit\u00e9s personnalis\u00e9es pour des produits et services susceptibles de vous int\u00e9resser.<\/p>\n<h4>3. Donn\u00e9es relatives \u00e0 l'appareil et \u00e0 l'utilisation que nous traitons<\/h4>\n<p>Nous utilisons des outils de collecte d'informations tels que des cookies, des balises web, des pixels et des technologies similaires pour collecter automatiquement des informations susceptibles de contenir vos donn\u00e9es personnelles lorsque vous utilisez nos sites web et nos services ou lorsque vous interagissez avec les courriers \u00e9lectroniques que nous vous envoyons.<\/p>\n<h5>3.1 Collecte automatique<\/h5>\n<p>La plupart des sites web collectent automatiquement des donn\u00e9es vous concernant lorsque vous les visitez. Ces informations peuvent comprendre<\/p>\n<ul>\n<li>Identifiants<\/li>\n<li>Informations commerciales<\/li>\n<li>Adresse IP<\/li>\n<li>Informations sur le serveur proxy<\/li>\n<li>Informations sur l'appareil et l'application<\/li>\n<li>Num\u00e9ros d'identification<\/li>\n<li>Localisation<\/li>\n<li>Type de navigateur<\/li>\n<li>Plug-ins<\/li>\n<li>Int\u00e9grations<\/li>\n<li>Fournisseur d'acc\u00e8s \u00e0 Internet<\/li>\n<li>Op\u00e9rateur de t\u00e9l\u00e9phonie mobile<\/li>\n<li>Pages et fichiers consult\u00e9s<\/li>\n<li>Recherches<\/li>\n<li>Site web, application ou publicit\u00e9 de r\u00e9f\u00e9rence<\/li>\n<li>Informations sur la configuration du syst\u00e8me<\/li>\n<li>Pr\u00e9f\u00e9rences publicitaires<\/li>\n<li>Pr\u00e9f\u00e9rences linguistiques<\/li>\n<li>Date et heure de votre utilisation<\/li>\n<li>Fr\u00e9quence des visites sur les sites web<\/li>\n<\/ul>\n<p>Nous utilisons ces informations pour analyser les tendances g\u00e9n\u00e9rales, nous aider \u00e0 am\u00e9liorer nos sites web, offrir une exp\u00e9rience personnalis\u00e9e aux utilisateurs des sites web, et s\u00e9curiser et maintenir nos sites web.<\/p>\n<p>Nous recueillons aussi automatiquement des informations dans le cadre de votre utilisation de nos produits et services. Ces informations peuvent comprendre<\/p>\n<ul>\n<li>Identifiants<\/li>\n<li>Informations commerciales<\/li>\n<li>Adresse IP<\/li>\n<li>Informations sur le serveur proxy<\/li>\n<li>Num\u00e9ro de l'appareil mobile<\/li>\n<li>Num\u00e9ro d'identification de l'appareil<\/li>\n<li>Num\u00e9ro d'identification de la demande<\/li>\n<li>Localisation<\/li>\n<li>Type de navigateur<\/li>\n<li>Fournisseur d'acc\u00e8s \u00e0 Internet<\/li>\n<li>Op\u00e9rateur de t\u00e9l\u00e9phonie mobile<\/li>\n<li>Pages et fichiers consult\u00e9s<\/li>\n<li>Site web et interactions avec les pages web<\/li>\n<li>Recherche d'informations<\/li>\n<li>Type et version du syst\u00e8me d'exploitation<\/li>\n<li>Informations sur la configuration du syst\u00e8me<\/li>\n<li>Donn\u00e9es et horodatage de votre utilisation<\/li>\n<li>D\u00e9tails des produits et des versions de produits que vous utilisez<\/li>\n<\/ul>\n<p>Nous utilisons ces informations pour maintenir la s\u00e9curit\u00e9 de nos sites web et de nos produits et services, fournir les fonctionnalit\u00e9s n\u00e9cessaires, am\u00e9liorer la performance des services, \u00e9valuer et am\u00e9liorer l'exp\u00e9rience du client et de l'utilisateur, v\u00e9rifier que vous \u00eates un utilisateur autoris\u00e9, contr\u00f4ler le respect des conditions d'utilisation, identifier les possibilit\u00e9s futures de d\u00e9veloppement des services, \u00e9valuer les besoins et les exigences en mati\u00e8re de capacit\u00e9, et identifier les opportunit\u00e9s pour les clients.<\/p>\n<p>Les donn\u00e9es relatives aux appareils et \u00e0 l'utilisation sont principalement utilis\u00e9es pour identifier les utilisations uniques de nos sites web et non pour identifier des individus sp\u00e9cifiques, sauf si l'identit\u00e9 est requise \u00e0 des fins de s\u00e9curit\u00e9 ou pour fournir des services \u00e0 l'individu.<\/p>\n<h5>3.2 Technologies de suivi<\/h5>\n<p>Nos sites web, services en ligne, applications interactives, messages \u00e9lectroniques et publicit\u00e9s peuvent utiliser des technologies de suivi telles que des balises web, des pixels, des tags et des cookies pour nous aider \u00e0 personnaliser votre exp\u00e9rience, mieux comprendre vos pr\u00e9f\u00e9rences, nous indiquer les parties de nos sites web que vous avez visit\u00e9es, faciliter et mesurer l'efficacit\u00e9 de nos publicit\u00e9s et services web bas\u00e9s sur les centres d'int\u00e9r\u00eat, et recueillir des informations sur l'utilisation de nos sites web et les interactions avec nos messages \u00e9lectroniques.<\/p>\n<p>Les balises web et les pixels sont utilis\u00e9s sur nos sites web et dans nos courriels pour aider \u00e0 d\u00e9livrer des cookies, collecter des donn\u00e9es d'utilisation et de performance, et exploiter et am\u00e9liorer nos sites web et nos courriels de marketing.<\/p>\n<p>Les cookies sont des identifiants alphanum\u00e9riques qui sont stock\u00e9s sur la m\u00e9moire locale de votre appareil par l'interm\u00e9diaire de votre navigateur web \u00e0 des fins d'archivage. Certains cookies nous permettent de faciliter votre navigation sur nos sites web et nos services, d'am\u00e9liorer et de personnaliser votre exp\u00e9rience de navigation et de d\u00e9duire vos pr\u00e9f\u00e9rences de navigation, tandis que d'autres sont utilis\u00e9s pour acc\u00e9l\u00e9rer le processus de connexion ou pour nous permettre de suivre vos activit\u00e9s en ligne dans le temps et sur nos pages web. <\/p>\n<p>Nous utilisons \u00e0 la fois des cookies de session et des cookies persistants. <\/p>\n<ul>\n<li>Les cookies de session n'existent que pendant une seule session et disparaissent de votre appareil lorsque vous fermez votre navigateur ou \u00e9teignez votre appareil. Nous utilisons des cookies de session pour permettre \u00e0 nos syst\u00e8mes de vous identifier de mani\u00e8re unique au cours d'une session ou lorsque vous \u00eates connect\u00e9 aux sites web ou \u00e0 nos services. Cela nous permet de traiter vos transactions et demandes en ligne et de v\u00e9rifier votre identit\u00e9 une fois que vous \u00eates connect\u00e9, lorsque vous naviguez sur nos pages web et nos services.<\/li>\n<li>Les cookies persistants resteront sur votre appareil m\u00eame apr\u00e8s que vous ayez ferm\u00e9 votre navigateur ou \u00e9teint votre appareil. Nous utilisons des cookies persistants pour obtenir des informations globales et statistiques sur l'activit\u00e9 des utilisateurs sur nos sites web.<\/li>\n<\/ul>\n<p>Il existe trois cat\u00e9gories de cookies : les cookies n\u00e9cessaires et fonctionnels, les cookies d'analyse et de personnalisation, et les cookies publicitaires :<\/p>\n<ul>\n<li>Les cookies obligatoires et fonctionnels sont n\u00e9cessaires au fonctionnement de nos sites web, tels que les cookies de session qui transmettent les sites web, les cookies d'authentification et les cookies de s\u00e9curit\u00e9. Lorsque vous choisissez de nous communiquer vos donn\u00e9es personnelles, nous pouvons placer un cookie sur votre navigateur pour nous permettre de vous identifier lorsque vous vous connectez aux sites web et de traiter toutes les transactions et demandes que vous effectuez. Vous ne pouvez pas refuser les cookies obligatoires et fonctionnels, car ils sont n\u00e9cessaires au fonctionnement de nos sites web.<\/li>\n<li>Les cookies d'analyse et de personnalisation sont utilis\u00e9s pour am\u00e9liorer les performances, les fonctions et les services de nos sites web et pour vous fournir des communications plus pertinentes. Il peut s'agir de cookies qui analysent le trafic sur le site, qui sont utilis\u00e9s pour des \u00e9tudes de march\u00e9 et qui affichent des publicit\u00e9s g\u00e9n\u00e9riques ne s'adressant pas \u00e0 une personne en particulier. Nous utilisons ces cookies pour collecter des informations sur la mani\u00e8re dont nos sites web sont utilis\u00e9s, d\u00e9terminer quelles pages sont les plus consult\u00e9es, fournir des interactions am\u00e9lior\u00e9es et des communications pertinentes, et suivre les performances de nos publicit\u00e9s. Vous pouvez choisir de ne pas utiliser nos cookies d'analyse et de personnalisation en cliquant sur \"Param\u00e8tres de confidentialit\u00e9\" au bas de notre site web. <\/li>\n<li>Les cookies publicitaires suivent votre activit\u00e9 sur nos sites web afin de comprendre vos centres d'int\u00e9r\u00eat et de vous adresser des messages publicitaires. Vous pouvez choisir de refuser les cookies publicitaires en cliquant sur \"Param\u00e8tres de confidentialit\u00e9\" au bas de notre site web.<\/li>\n<\/ul>\n<h5>3.3 D\u00e9sactivation des cookies sur votre navigateur<\/h5>\n<p>Outre l'utilisation de nos param\u00e8tres de confidentialit\u00e9, vous pouvez vous opposer \u00e0 la collecte de donn\u00e9es non essentielles relatives \u00e0 l'appareil et \u00e0 l'utilisation dans votre navigateur web. Selon vos pr\u00e9f\u00e9rences personnelles, vous pouvez modifier les options de votre navigateur en utilisant la fonction \"Aide\" de la barre d'outils de votre navigateur. Vous pouvez emp\u00eacher votre ordinateur d'accepter de nouveaux cookies, demander au navigateur de vous avertir lorsque vous recevez un nouveau cookie ou d\u00e9sactiver tous les cookies. Toutefois, il est important de noter que si vous bloquez ou supprimez les cookies que nous utilisons sur nos sites web, vous pourrez toujours naviguer dans certaines parties des sites web, mais certaines fonctions risquent de ne pas fonctionner correctement.<\/p>\n<h5>3.4 Objets de stockage local Flash<\/h5>\n<p>Nous pouvons utiliser des objets de stockage local Flash (Flash LSO) pour enregistrer vos pr\u00e9f\u00e9rences sur le site web et personnaliser votre visite. Les Flash LSO sont diff\u00e9rents des cookies du navigateur en raison de la quantit\u00e9 et du type de donn\u00e9es stock\u00e9es. En r\u00e8gle g\u00e9n\u00e9rale, vous ne pouvez pas contr\u00f4ler, supprimer ou d\u00e9sactiver l'acceptation de tous les Flash LSO par le biais de votre navigateur web.<br \/>\nPour plus d'informations sur les LSO Flash et pour savoir comment g\u00e9rer vos param\u00e8tres pour les LSO Flash, consultez la page d'aide d'Adobe Flash Player. <\/p>\n<h5>3.5 Images invisibles<\/h5>\n<p>Les images invisibles sont de minuscules graphiques dot\u00e9s d'un identifiant unique, dont la fonction est similaire \u00e0 celle des cookies. Contrairement aux cookies, qui sont stock\u00e9s dans la m\u00e9moire locale de votre appareil, ces images sont int\u00e9gr\u00e9es de mani\u00e8re invisible dans les pages web et les applications. <\/p>\n<p>Nous pouvons utiliser des images invisibles, \u00e9galement connues sous le nom de balises web, web bugs ou pixel tags, en relation avec nos sites web et nos offres de services pour, entre autres, suivre les activit\u00e9s des visiteurs du site web et des utilisateurs d'applications, nous aider \u00e0 g\u00e9rer le contenu et compiler des statistiques sur l'utilisation du site web. <\/p>\n<p>Nous, et nos fournisseurs de services tiers, utilisons \u00e9galement des images invisibles dans les courriels HTML adress\u00e9s \u00e0 nos clients pour nous aider \u00e0 suivre les taux de r\u00e9ponse aux courriels, \u00e0 identifier le moment o\u00f9 nos courriels sont consult\u00e9s et \u00e0 savoir si nos courriels sont transf\u00e9r\u00e9s.<\/p>\n<h5>3.6 Publicit\u00e9 comportementale ou bas\u00e9e sur les centres d'int\u00e9r\u00eat<\/h5>\n<p>Nous, et nos fournisseurs de services tiers, pouvons utiliser des informations concernant votre visite sur nos sites web, telles que les pages que vous visitez, les \u00e9l\u00e9ments que vous visualisez et vos r\u00e9ponses \u00e0 nos publicit\u00e9s et \u00e0 nos courriels. Ces informations nous permettent de rendre les publicit\u00e9s que vous voyez plus pertinentes pour vous. Pour mettre \u00e0 jour vos pr\u00e9f\u00e9rences, vous pouvez cliquer sur \"se d\u00e9sabonner\" dans toute communication marketing par courrier \u00e9lectronique qui vous est envoy\u00e9e.<\/p>\n<p>Il peut s'\u00e9couler jusqu'\u00e0 dix (10) jours ouvrables avant que vos pr\u00e9f\u00e9rences en mati\u00e8re de courrier \u00e9lectronique ne soient prises en compte.<\/p>\n<p>Vous pouvez \u00e9galement consulter les pages de d\u00e9sengagement pour vous d\u00e9sengager de nombreux r\u00e9seaux publicitaires tiers par l'interm\u00e9diaire de divers sites web d'associations professionnelles tels que : <\/p>\n<ul>\n<li class=\"translation-block\">Internet Advertising Bureau (IAB) : <a href=\"https:\/\/www.iab.com\/news\/interactive-advertising-bureau-iab\/\" target=\"_blank\" rel=\"noopener\">Interactive Advertising Bureau<\/a> (IAB)<\/li>\n<li class=\"translation-block\">Initiative pour la publicit\u00e9 en r\u00e9seau (NAI) : <a href=\"https:\/\/thenai.org\/\" target=\"_blank\" rel=\"noopener\">thenai.org<\/a><\/li>\n<li class=\"translation-block\">Alliance pour la publicit\u00e9 num\u00e9rique (DAA) : <a href=\"https:\/\/digitaladvertisingalliance.org\/\" target=\"_blank\" rel=\"noopener\">DigitalAdvertisingAlliance.org<\/a><\/li>\n<\/ul>\n<p>Toutefois, l'utilisation de ces pages de d\u00e9sactivation ne signifie pas que vous ne recevrez plus de publicit\u00e9 sur nos sites web ou nos services, ou sur les sites web de tiers.<\/p>\n<h5>3.7 R\u00e9seaux publicitaires de tiers<\/h5>\n<p>De temps \u00e0 autre, nous pouvons communiquer \u00e0 des annonceurs de r\u00e9seau non affili\u00e9s des informations, y compris vos donn\u00e9es personnelles. Ces annonceurs de r\u00e9seau fournissent des publicit\u00e9s sur nos sites web, nos applications et sur les sites web et m\u00e9dias d'autres parties, tels que les plateformes de r\u00e9seaux sociaux. <\/p>\n<p>L'utilisation partag\u00e9e de vos donn\u00e9es personnelles avec ces annonceurs de r\u00e9seau nous permet d'offrir les produits et services qui vous int\u00e9ressent le plus. Les fournisseurs de r\u00e9seaux publicitaires non affili\u00e9s, les annonceurs en r\u00e9seau, les sponsors et\/ou les services de mesure du trafic peuvent utiliser des cookies, JavaScript, des balises web, des LSO Flash et d'autres technologies de suivi pour mesurer l'efficacit\u00e9 de leurs publicit\u00e9s et pour personnaliser le contenu publicitaire qui vous est destin\u00e9. Les cookies et technologies d'autres parties sont r\u00e9gis par la politique de confidentialit\u00e9 sp\u00e9cifique de chaque soci\u00e9t\u00e9, et non par la pr\u00e9sente politique de confidentialit\u00e9.<\/p>\n<p>Lorsque nous travaillons avec des r\u00e9seaux publicitaires tiers, nous leur demandons de limiter le traitement des donn\u00e9es \u00e0 ce qui est n\u00e9cessaire pour nous fournir les services publicitaires que nous demandons.<\/p>\n<p>Les utilisateurs de sites web situ\u00e9s aux \u00c9tats-Unis peuvent en savoir plus sur le retrait et l'exclusion de nombreux r\u00e9seaux publicitaires tiers par le biais de divers sites web d'associations professionnelles tels que : <\/p>\n<ul>\n<li class=\"translation-block\">Internet Advertising Bureau (IAB) : <a href=\"https:\/\/www.iab.com\/news\/interactive-advertising-bureau-iab\/\" target=\"_blank\" rel=\"noopener\">Interactive Advertising Bureau<\/a> (IAB)<\/li>\n<li class=\"translation-block\">Initiative pour la publicit\u00e9 en r\u00e9seau (NAI) : <a href=\"https:\/\/thenai.org\/\" target=\"_blank\" rel=\"noopener\">thenai.org<\/a><\/li>\n<li class=\"translation-block\">Alliance pour la publicit\u00e9 num\u00e9rique (DAA) : <a href=\"https:\/\/digitaladvertisingalliance.org\/\" target=\"_blank\" rel=\"noopener\">DigitalAdvertisingAlliance.org<\/a><\/li>\n<\/ul>\n<p>Toutefois, cela ne signifie pas que vous ne recevrez plus de publicit\u00e9 sur nos sites web, nos services ou sur les sites web de tiers.<\/p>\n<h5>3.8 Utilisation crois\u00e9e des appareils<\/h5>\n<p>Nous et nos fournisseurs de services tiers, y compris Google, pouvons utiliser les informations que nous recueillons \u00e0 votre sujet, que ce soit directement sur notre site Web, \u00e0 partir de nos applications mobiles, par l'interm\u00e9diaire de votre appareil ou d'un tiers, pour nous aider et aider nos fournisseurs de services tiers \u00e0 identifier d'autres appareils que vous utilisez, tels qu'un t\u00e9l\u00e9phone mobile, une tablette ou un autre ordinateur. <\/p>\n<p>Nous, et nos fournisseurs de services tiers, pouvons \u00e9galement utiliser les informations d'utilisation crois\u00e9e des appareils que nous apprenons sur vous pour diffuser des publicit\u00e9s cibl\u00e9es sur vos appareils et pour vous envoyer des courriels.<\/p>\n<p>Pour refuser l'utilisation crois\u00e9e des dispositifs, vous pouvez refuser la publicit\u00e9 de tiers (voir la section 3.7). Toutefois, si vous refusez ces cookies publicitaires, votre refus sera sp\u00e9cifique au navigateur web, \u00e0 l'application ou \u00e0 l'appareil \u00e0 partir duquel vous avez acc\u00e9d\u00e9 au refus. Si vous utilisez plusieurs appareils ou navigateurs web, vous devrez vous d\u00e9sinscrire pour chaque appareil et chaque navigateur sur chaque appareil que vous utilisez.<\/p>\n<h5>3.9 Option \"Ne pas suivre\" (Do Not Track)<\/h5>\n<p>Certains navigateurs Internet proposent une option \"Do Not Track\" qui vous permet d'indiquer aux sites web que vous ne souhaitez pas que vos activit\u00e9s en ligne soient suivies. Il n'existe actuellement aucune norme commune dans le secteur, c'est pourquoi nous reconnaissons ces signaux \"Do Not Track\" sur nos sites web. Nous prenons au s\u00e9rieux la protection de la vie priv\u00e9e et vos pr\u00e9f\u00e9rences et nous continuerons \u00e0 suivre l'\u00e9volution de l'option \"Do Not Track\" et l'adoption d'une norme.<\/p>\n<p class=\"translation-block\">Toutefois, vous pouvez d\u00e9sactiver certains suivis en cliquant sur \"Param\u00e8tres de confidentialit\u00e9\" au bas de notre site web, \u00e0 l'adresse suivante : <a href=\"\" target=\"_self\">RSA.com<\/a> : <a href=\"http:\/\/www.rsa.com\/fr_ca\/\" target=\"_self\">RSA.com<\/a> en d\u00e9sactivant les cookies sur votre navigateur (voir section 3.3), ou en refusant la publicit\u00e9 (voir sections 3.6 et 3.7).<\/p>\n<h5>3.10 M\u00e9dias sociaux<\/h5>\n<p>Nous sommes responsables du contenu que nous publions sur les plateformes de m\u00e9dias sociaux, mais nous ne sommes pas responsables de la gestion des plateformes de m\u00e9dias sociaux ou des donn\u00e9es qu'elles collectent et traitent. Nos sites web sont dot\u00e9s de plugins de partage de m\u00e9dias sociaux. Ces widgets peuvent vous permettre de publier des informations sur vos activit\u00e9s sur nos sites web sur des plateformes externes et des r\u00e9seaux sociaux. Vous pouvez \u00e9galement \u00eatre en mesure d'aimer ou de partager des informations que nous avons publi\u00e9es sur nos sites web ou sur les pages de m\u00e9dias sociaux de notre marque. Si les pages de m\u00e9dias sociaux sont h\u00e9berg\u00e9es par les plateformes individuelles et que vous cliquez sur le site \u00e0 partir de nos sites web, la plateforme peut recevoir des informations montrant que vous avez visit\u00e9 nos sites web. Si vous \u00eates connect\u00e9 au site de m\u00e9dias sociaux au moment o\u00f9 vous cliquez, le site de m\u00e9dias sociaux peut \u00eatre en mesure d'\u00e9tablir un lien entre votre visite sur nos sites web et votre profil de m\u00e9dias sociaux.<\/p>\n<h5>3.11 Informations sur la t\u00e9l\u00e9phonie<\/h5>\n<p>Si vous utilisez des fonctions de nos services sur votre appareil mobile, nous pouvons collecter des informations de journal t\u00e9l\u00e9phonique, y compris les num\u00e9ros de t\u00e9l\u00e9phone, l'heure et la date des appels, la dur\u00e9e de l'appel, les informations d'acheminement des SMS. Nous pouvons collecter des informations sur les \u00e9v\u00e9nements li\u00e9s \u00e0 l'appareil, telles que l'activit\u00e9 du syst\u00e8me, les param\u00e8tres du mat\u00e9riel et la langue du navigateur. Nous pouvons \u00e9galement collecter des informations de localisation par le biais du GPS, de l'adresse IP, des points d'acc\u00e8s WiFi et des tours de t\u00e9l\u00e9phonie mobile, ainsi que d'autres capteurs qui nous fournissent des informations sur les appareils situ\u00e9s \u00e0 proximit\u00e9.<\/p>\n<h4>4. Finalit\u00e9s et bases juridiques du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel<\/h4>\n<p>Nous collectons et traitons vos donn\u00e9es personnelles aux fins suivantes :<\/p>\n<ul>\n<li>Fournir et promouvoir nos sites web, nos produits et nos services. Nous traiterons vos donn\u00e9es \u00e0 caract\u00e8re personnel pour nous acquitter des obligations qui nous incombent en vertu de tout contrat conclu avec vous ou votre employeur pour l'utilisation de nos sites web et de nos services. <\/li>\n<ul>\n<li>En l'absence de contrat, la base juridique du traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel est l'exploitation et l'administration de nos sites web et de nos services afin de vous permettre d'acc\u00e9der au contenu.<\/li>\n<\/ul>\n<li>Assurer et promouvoir la s\u00e9curit\u00e9 de nos sites web. Nous traiterons vos donn\u00e9es personnelles lorsque nous suivrons votre utilisation de nos sites web et de nos services, lorsque nous cr\u00e9erons des donn\u00e9es agr\u00e9g\u00e9es, d\u00e9personnalis\u00e9es et pseudonymis\u00e9es, lorsque nous v\u00e9rifierons des comptes et des activit\u00e9s, lorsque nous enqu\u00eaterons sur des activit\u00e9s suspectes, lorsque nous ferons respecter nos conditions et nos politiques. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est la promotion de la s\u00fbret\u00e9 et de la s\u00e9curit\u00e9 de nos sites web, services, syst\u00e8mes et applications et la protection de nos droits et des droits d'autrui.<\/li>\n<\/ul>\n<li>Pour g\u00e9rer les utilisateurs. Nous traiterons vos donn\u00e9es \u00e0 caract\u00e8re personnel lorsque vous vous inscrivez pour ouvrir un compte chez nous, afin d'\u00e9tablir et de g\u00e9rer le compte d'utilisateur et de nous permettre d'ex\u00e9cuter nos obligations envers vous conform\u00e9ment au contrat ou aux conditions g\u00e9n\u00e9rales applicables. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est de nous permettre de confirmer et d'authentifier votre identit\u00e9 et d'emp\u00eacher l'acc\u00e8s non autoris\u00e9 \u00e0 des zones restreintes de nos sites web.<\/li>\n<\/ul>\n<li>Pour fournir une assistance. Nous traiterons vos donn\u00e9es \u00e0 caract\u00e8re personnel lorsque vous demanderez une assistance technique ou des services d'assistance \u00e0 la client\u00e8le afin d'examiner les rapports d'erreur, les informations sur les performances des produits et les probl\u00e8mes que vous rencontrez, ainsi que pour r\u00e9soudre les probl\u00e8mes et fournir des informations d'aide. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est de nous permettre de confirmer le probl\u00e8me et de vous fournir l'assistance dont vous avez besoin pour le r\u00e9soudre.<\/li>\n<\/ul>\n<li>Pour r\u00e9pondre \u00e0 vos demandes. Nous traiterons vos donn\u00e9es personnelles lorsque vous remplissez un formulaire \"Contactez-nous\", demandez une d\u00e9mo ou nous contactez de toute autre mani\u00e8re, y compris par chatbot, email ou t\u00e9l\u00e9phone. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est l'ex\u00e9cution de nos obligations envers vous, la satisfaction de vos demandes et la communication avec vous.<\/li>\n<\/ul>\n<li>Pour g\u00e9rer les paiements. Nous traitons vos donn\u00e9es personnelles lorsque vous effectuez un achat et que vous nous fournissez des informations financi\u00e8res. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est la collecte des paiements n\u00e9cessaires en vertu des contrats que nous avons conclus avec vous.<\/li>\n<\/ul>\n<li>Pour enregistrer les conversations t\u00e9l\u00e9phoniques et les sessions de chat. Nous traiterons vos donn\u00e9es \u00e0 caract\u00e8re personnel si vous nous appelez et que nous surveillons et enregistrons l'appel ou si vous ouvrez une session de chat et que nous surveillons et enregistrons la conversation. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est la formation, l'assurance qualit\u00e9 et l'administration. Nous obtiendrons votre consentement pr\u00e9alable ou nous vous permettrons de vous opposer \u00e0 l'enregistrement d'un appel t\u00e9l\u00e9phonique si la loi applicable l'exige.<\/li>\n<\/ul>\n<li>Pour envoyer des communications. Nous traiterons vos donn\u00e9es personnelles pour vous envoyer des informations marketing, des recommandations de produits et d'autres communications, telles que des bulletins d'information ou des notifications push. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est la fourniture d'informations sur les promotions, les nouvelles ou les \u00e9v\u00e9nements \u00e0 des fins de marketing direct.<\/li>\n<\/ul>\n<li>G\u00e9rer l'inscription aux \u00e9v\u00e9nements. Nous traiterons vos donn\u00e9es \u00e0 caract\u00e8re personnel pour planifier et organiser les \u00e9v\u00e9nements auxquels vous vous inscrivez ou auxquels vous participez, y compris pour vous envoyer des communications. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est l'ex\u00e9cution de nos obligations envers vous.<\/li>\n<\/ul>\n<li>d\u00e9velopper et am\u00e9liorer nos sites web et nos services. Nous traiterons vos donn\u00e9es personnelles pour analyser les tendances et suivre votre utilisation et vos interactions avec nos sites web, si n\u00e9cessaire. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est notre int\u00e9r\u00eat l\u00e9gitime \u00e0 d\u00e9velopper et \u00e0 am\u00e9liorer nos sites web et nos services et \u00e0 fournir aux utilisateurs un contenu et des offres de services plus pertinents.<\/li>\n<\/ul>\n<li>Pour \u00e9valuer et am\u00e9liorer l'exp\u00e9rience de l'utilisateur. Nous traiterons l'utilisation de votre appareil et des donn\u00e9es, qui peuvent \u00eatre associ\u00e9es \u00e0 vos donn\u00e9es personnelles, ainsi que les informations de consommation de contenu sur les contenus m\u00e9diatiques tels que la t\u00e9l\u00e9vision, les applications et les jeux auxquels vous acc\u00e9dez par l'interm\u00e9diaire de nos produits. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est l'analyse des tendances, l'\u00e9valuation et l'am\u00e9lioration de l'exp\u00e9rience de l'utilisateur, ainsi que l'am\u00e9lioration de nos sites web et de nos offres de services.<\/li>\n<\/ul>\n<li>Pour \u00e9valuer les besoins en capacit\u00e9. Nous traiterons vos donn\u00e9es \u00e0 caract\u00e8re personnel pour \u00e9valuer les besoins en capacit\u00e9 de nos services. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est de s'assurer que nous disposons de la capacit\u00e9 n\u00e9cessaire pour nos offres de services.<\/li>\n<\/ul>\n<li>V\u00e9rifier le respect de nos conditions d'utilisation. Nous traiterons vos donn\u00e9es personnelles pour v\u00e9rifier que vous \u00eates un utilisateur autoris\u00e9 et pour nous assurer que vous respectez les conditions d'utilisation. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est la garantie du respect des conditions applicables.<\/li>\n<\/ul>\n<li>Identifier les opportunit\u00e9s pour les clients. Nous traiterons vos donn\u00e9es personnelles afin d'\u00e9valuer les nouvelles opportunit\u00e9s pour nos clients. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est de s'assurer que nous r\u00e9pondons aux demandes de nos clients et \u00e0 leur exp\u00e9rience d'utilisateur.<\/li>\n<\/ul>\n<li>Pour afficher des publicit\u00e9s et du contenu personnalis\u00e9s. Nous traiterons vos donn\u00e9es personnelles pour vous faire de la publicit\u00e9 et vous fournir d'autres contenus personnalis\u00e9s en fonction de vos centres d'int\u00e9r\u00eat et de vos activit\u00e9s. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est de personnaliser votre exp\u00e9rience avec nous et de faire des recommandations appropri\u00e9es.<\/li>\n<\/ul>\n<li>Pour administrer des enqu\u00eates et mener des recherches. Nous traiterons vos donn\u00e9es personnelles pour mener des \u00e9tudes de march\u00e9, obtenir des avis sur les produits et recueillir des informations sur les r\u00e9actions et les \u00e9valuations dans le cadre d'une enqu\u00eate aupr\u00e8s des clients. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est l'am\u00e9lioration de nos produits et services et la r\u00e9alisation des objectifs de la recherche. <\/li>\n<\/ul>\n<li>Respecter les obligations l\u00e9gales. Nous traiterons vos donn\u00e9es \u00e0 caract\u00e8re personnel pour coop\u00e9rer avec les autorit\u00e9s publiques et gouvernementales, les tribunaux ou les autorit\u00e9s de r\u00e9gulation afin de respecter nos obligations l\u00e9gales en vertu des lois applicables, de prot\u00e9ger nos droits, de nous prot\u00e9ger contre les utilisations abusives de nos sites web ou de nos services, de prot\u00e9ger la propri\u00e9t\u00e9 personnelle, de prot\u00e9ger la s\u00e9curit\u00e9 d'autrui, d'exercer les recours dont nous disposons, de limiter nos dommages, de nous conformer aux proc\u00e9dures judiciaires, aux ordonnances des tribunaux ou aux processus l\u00e9gaux, de r\u00e9pondre aux demandes l\u00e9gales et de r\u00e9aliser des audits. <\/li>\n<ul>\n<li>La base juridique du traitement de vos donn\u00e9es personnelles est le respect des lois, r\u00e8gles et r\u00e8glements applicables.<\/li>\n<\/ul>\n<\/ul>\n<p>Lorsque la loi l'exige, nous obtiendrons votre consentement pr\u00e9alable pour utiliser et traiter vos donn\u00e9es \u00e0 caract\u00e8re personnel, ou nous nous appuierons sur une autre base juridique autoris\u00e9e, telle que l'ex\u00e9cution d'un contrat ou un int\u00e9r\u00eat l\u00e9gitime. <\/p>\n<h4>5. Avec qui partageons-nous vos donn\u00e9es personnelles ?<\/h4>\n<p>Nous pouvons partager vos donn\u00e9es personnelles avec nos partenaires commerciaux, qui incluent :<\/p>\n<ul>\n<li>Affili\u00e9s. Nous partagerons vos donn\u00e9es personnelles avec nos affili\u00e9s dans la mesure o\u00f9 cela est n\u00e9cessaire sur la base du contrat de l'affili\u00e9 avec vous.<\/li>\n<li>Prestataires de services. Nous partagerons vos donn\u00e9es personnelles avec nos prestataires de services sous contrat qui fournissent des services tels que l'h\u00e9bergement, le courrier \u00e9lectronique, la gestion de la relation client (CRM), l'administration des TI et des syst\u00e8mes, le traitement des cartes de cr\u00e9dit et des paiements, la recherche et l'analyse, ainsi que l'assistance \u00e0 la client\u00e8le.<\/li>\n<li>Conseillers professionnels. Nous partagerons vos donn\u00e9es personnelles avec nos conseillers professionnels, tels que les avocats, les banquiers, les auditeurs et les assureurs, dans la mesure o\u00f9 nous sommes l\u00e9galement oblig\u00e9s de partager vos donn\u00e9es personnelles ou que nous avons un int\u00e9r\u00eat l\u00e9gitime \u00e0 le faire.<\/li>\n<li>R\u00e9seaux et sites web tiers. Nous partagerons vos donn\u00e9es personnelles avec des r\u00e9seaux de m\u00e9dias sociaux et des sites web de publicit\u00e9 afin de pouvoir faire du marketing et de la publicit\u00e9 sur des plateformes tierces.<\/li>\n<li>Comptes de tiers. Nous partagerons vos donn\u00e9es personnelles si vous connectez vos comptes de tiers \u00e0 nos produits afin de vous authentifier et de r\u00e9pondre \u00e0 toutes les demandes que vous avez formul\u00e9es par l'interm\u00e9diaire du compte de tiers.<\/li>\n<li>Tiers dans le cadre d'une transaction d'entreprise. Nous partagerons vos donn\u00e9es personnelles si nous sommes impliqu\u00e9s dans une fusion, une acquisition, une r\u00e9organisation, une dissolution ou tout autre changement de soci\u00e9t\u00e9.<\/li>\n<\/ul>\n<h4>6. Transferts internationaux de donn\u00e9es \u00e0 caract\u00e8re personnel<\/h4>\n<p>Nous pouvons collecter, transf\u00e9rer et stocker vos donn\u00e9es \u00e0 caract\u00e8re personnel aux \u00c9tats-Unis. Nous pouvons \u00e9galement collecter, transf\u00e9rer et stocker vos donn\u00e9es \u00e0 caract\u00e8re personnel dans d'autres pays. Il s'agit notamment de pays situ\u00e9s en dehors de l'Espace \u00e9conomique europ\u00e9en (EEE) et de pays dont les lois n'ont pas \u00e9t\u00e9 jug\u00e9es suffisantes pour assurer un niveau de protection ad\u00e9quat en vertu des lois de l'Union europ\u00e9enne (UE) ou d'autres juridictions.<\/p>\n<p>Cela signifie que vos donn\u00e9es personnelles peuvent \u00eatre trait\u00e9es en dehors de votre juridiction dans des pays qui ne font pas l'objet d'une d\u00e9cision d'ad\u00e9quation de la Commission europ\u00e9enne sur la base de l'article 45 du r\u00e8glement (UE) 2016\/679 (GDPR) ou d'une autorit\u00e9 r\u00e9glementaire. Toutefois, nous veillerons \u00e0 ce que vos donn\u00e9es \u00e0 caract\u00e8re personnel fassent l'objet d'un niveau de protection et de s\u00e9curit\u00e9 ad\u00e9quat en concluant des accords appropri\u00e9s, y compris les clauses contractuelles types du Royaume-Uni et les clauses contractuelles types de l'UE, ou un m\u00e9canisme alternatif pour le transfert de vos donn\u00e9es \u00e0 caract\u00e8re personnel. <\/p>\n<h4>7. Donn\u00e9es sur les enfants<\/h4>\n<p class=\"translation-block\">Nos sites web, produits et services ne sont pas destin\u00e9s aux enfants. Nous ne collectons ni ne traitons sciemment les donn\u00e9es personnelles d'enfants de moins de seize (16) ans. Si vous \u00eates un parent ou un tuteur et que vous pensez que votre enfant nous a fourni des donn\u00e9es personnelles sans votre consentement, veuillez nous contacter \u00e0 l'adresse <a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a> et nous prendrons les mesures n\u00e9cessaires pour supprimer ses donn\u00e9es personnelles de nos syst\u00e8mes.<\/p>\n<h4>8. Conservation des donn\u00e9es<\/h4>\n<p>Nous ne conserverons pas vos informations plus longtemps que n\u00e9cessaire pour les besoins de l'ASR. Nous conserverons vos donn\u00e9es personnelles pendant des p\u00e9riodes diff\u00e9rentes en fonction de la cat\u00e9gorie de donn\u00e9es personnelles pour laquelle elles sont collect\u00e9es. Certaines donn\u00e9es personnelles peuvent \u00eatre supprim\u00e9es automatiquement, tandis que d'autres seront conserv\u00e9es plus longtemps, conform\u00e9ment \u00e0 l'objectif initial de leur collecte, aussi longtemps que n\u00e9cessaire pour remplir nos obligations, ou comme l'exige la loi. <\/p>\n<p>\u00c0 l'expiration de la p\u00e9riode de conservation, nous effacerons vos donn\u00e9es \u00e0 caract\u00e8re personnel. Si des donn\u00e9es ne peuvent \u00eatre compl\u00e8tement effac\u00e9es pour des raisons techniques, nous mettrons en \u0153uvre des mesures appropri\u00e9es pour emp\u00eacher tout traitement ult\u00e9rieur de ces donn\u00e9es.<\/p>\n<h4>9. Vos droits<\/h4>\n<p>Vous pouvez avoir certains droits relatifs \u00e0 vos donn\u00e9es personnelles, sous r\u00e9serve des lois sur la protection des donn\u00e9es. Ces droits peuvent inclure<\/p>\n<ul>\n<li>Acc\u00e8s \u00e0 vos donn\u00e9es personnelles<\/li>\n<li>Informations concernant le traitement de vos donn\u00e9es personnelles<\/li>\n<li>Rectification des donn\u00e9es personnelles inexactes<\/li>\n<li>Effacement ou suppression de vos donn\u00e9es personnelles<\/li>\n<li>Restrictions au traitement de vos donn\u00e9es personnelles<\/li>\n<li>Objection au traitement de vos donn\u00e9es personnelles<\/li>\n<li>Refus de certaines divulgations de vos donn\u00e9es \u00e0 caract\u00e8re personnel<\/li>\n<li>Pas de repr\u00e9sailles ni de discrimination pour avoir exerc\u00e9 vos droits<\/li>\n<li>Ne pas faire l'objet de d\u00e9cisions fond\u00e9es uniquement sur un traitement automatis\u00e9<\/li>\n<li>Retrait du consentement pour un traitement futur<\/li>\n<\/ul>\n<p>Nous n'utilisons pas actuellement la prise de d\u00e9cision automatis\u00e9e sur nos sites web ou dans nos services.<\/p>\n<h5>9.1 Comment exercer vos droits<\/h5>\n<p class=\"translation-block\">Pour exercer vos droits, veuillez nous contacter \u00e0 <a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a>.<\/p>\n<p>Nous pouvons traiter vos donn\u00e9es \u00e0 caract\u00e8re personnel lorsque nous r\u00e9pondons \u00e0 ces droits. Nous nous effor\u00e7ons de r\u00e9pondre \u00e0 toutes les demandes l\u00e9gitimes dans un d\u00e9lai de trente (30) jours, sauf disposition l\u00e9gale contraire, et nous vous contacterons si nous avons besoin d'informations suppl\u00e9mentaires pour r\u00e9pondre \u00e0 votre demande ou v\u00e9rifier votre identit\u00e9. Il arrive que ce d\u00e9lai soit plus long que trente (30) jours, compte tenu du nombre et de la complexit\u00e9 des demandes que nous recevons. Nous vous contacterons si nous avons besoin d'un d\u00e9lai suppl\u00e9mentaire pour r\u00e9pondre \u00e0 votre demande.<\/p>\n<p>Certains utilisateurs autoris\u00e9s peuvent mettre \u00e0 jour leurs param\u00e8tres et leurs profils en se connectant \u00e0 leur compte.<\/p>\n<p>Sachez que votre demande ne garantit pas un acc\u00e8s complet ou une suppression totale, car la loi peut ne pas autoriser ou exiger la suppression dans certaines circonstances.<\/p>\n<h5>9.2 Vos droits sur les donn\u00e9es des clients<\/h5>\n<p>Nous pouvons traiter vos donn\u00e9es personnelles si elles sont soumises par ou pour un client de nos produits et services. Nous sommes le sous-traitant pour le compte de notre client, qui est le responsable du traitement. Nous ne sommes pas responsables et n'avons aucun contr\u00f4le sur les pratiques de nos clients en mati\u00e8re de confidentialit\u00e9 et de s\u00e9curit\u00e9 des donn\u00e9es, qui peuvent diff\u00e9rer de celles d\u00e9crites dans notre politique de confidentialit\u00e9.<\/p>\n<p>Si vos donn\u00e9es nous ont \u00e9t\u00e9 transmises par ou au nom d'un client et que vous souhaitez exercer les droits dont vous disposez sur vos donn\u00e9es personnelles en vertu des lois applicables en mati\u00e8re de protection des donn\u00e9es, veuillez vous adresser directement \u00e0 notre client. <\/p>\n<p>Nous ne pouvons acc\u00e9der \u00e0 vos donn\u00e9es personnelles que sur la base des instructions de nos clients. Si vous souhaitez faire votre demande d'exercice de vos droits aupr\u00e8s de nous, veuillez nous fournir le nom du client qui nous a soumis vos donn\u00e9es. Nous transmettrons la demande \u00e0 ce client et lui fournirons toute l'aide n\u00e9cessaire pour r\u00e9pondre \u00e0 votre demande dans un d\u00e9lai raisonnable.<\/p>\n<h5>9.3 Vos pr\u00e9f\u00e9rences en mati\u00e8re de communications par courrier \u00e9lectronique et par SMS<\/h5>\n<p>Vous avez le choix quant \u00e0 la mani\u00e8re dont nous vous contactons avec des offres marketing et quant \u00e0 d'autres utilisations de vos informations. Pour mettre \u00e0 jour vos pr\u00e9f\u00e9rences, vous pouvez<\/p>\n<ul>\n<li class=\"translation-block\">Cliquez sur \"unsubscribe\" dans les communications marketing par courriel que nous vous envoyons ou <a href=\"https:\/\/go.securid.com\/communication-preference-management\" rel=\"noopener\" target=\"_blank\">cliquez ici<\/a>.<\/li>\n<li class=\"translation-block\">Visitez notre <a href=\"https:\/\/go.securid.com\/communication-preference-management\" rel=\"noopener\" target=\"_blank\">Centre de gestion des pr\u00e9f\u00e9rences<\/a> pour s\u00e9lectionner vos choix.<\/li>\n<\/ul>\n<p>Veuillez noter qu'il peut s'\u00e9couler jusqu'\u00e0 10 jours ouvrables avant que vos pr\u00e9f\u00e9rences en mati\u00e8re de courrier \u00e9lectronique ne soient prises en compte. <\/p>\n<p>Le fait de refuser les communications marketing ne vous emp\u00eachera pas de recevoir des communications commerciales importantes li\u00e9es \u00e0 votre relation actuelle avec nous, telles que des informations sur vos produits ou services, des inscriptions \u00e0 des \u00e9v\u00e9nements, des annonces de services ou des informations sur la s\u00e9curit\u00e9.<\/p>\n<h4>10. Comment nous s\u00e9curisons vos donn\u00e9es personnelles<\/h4>\n<p>Nous prenons les mesures organisationnelles, techniques et physiques appropri\u00e9es pour nous prot\u00e9ger contre la destruction, la perte, l'alt\u00e9ration et la divulgation non autoris\u00e9e des donn\u00e9es \u00e0 caract\u00e8re personnel que nous collectons et traitons, ou contre l'acc\u00e8s \u00e0 ces donn\u00e9es, de mani\u00e8re accidentelle ou ill\u00e9gale. Nous proc\u00e9dons notamment de la mani\u00e8re suivante :<\/p>\n<ul>\n<li>Utilisation du cryptage lors de la collecte ou du transfert de donn\u00e9es sensibles, telles que les cartes de cr\u00e9dit ou les informations bancaires.<\/li>\n<li>concevoir nos garanties de s\u00e9curit\u00e9 des donn\u00e9es pour assurer la s\u00e9curit\u00e9, l'int\u00e9grit\u00e9, la disponibilit\u00e9 et la r\u00e9silience des syst\u00e8mes et des services de traitement<\/li>\n<li>Limiter l'acc\u00e8s physique \u00e0 nos locaux<\/li>\n<li>Limiter l'acc\u00e8s aux donn\u00e9es personnelles que nous collectons \u00e0 votre sujet<\/li>\n<li>s'assurer que nos partenaires commerciaux ont mis en place des mesures de s\u00e9curit\u00e9 techniques et organisationnelles appropri\u00e9es pour prot\u00e9ger vos donn\u00e9es \u00e0 caract\u00e8re personnel<\/li>\n<li>d\u00e9truire, pseudonymiser ou d\u00e9personnaliser les donn\u00e9es \u00e0 caract\u00e8re personnel conform\u00e9ment aux obligations contractuelles et \u00e0 la loi<\/li>\n<\/ul>\n<p>Nous suivons les normes g\u00e9n\u00e9ralement accept\u00e9es pour prot\u00e9ger vos donn\u00e9es personnelles. Toutefois, aucune m\u00e9thode de collecte, de stockage ou de transmission n'est 100% s\u00fbre. Vous \u00eates seul responsable de la protection de votre mot de passe, de la limitation de l'acc\u00e8s \u00e0 vos appareils et de la d\u00e9connexion des sites web apr\u00e8s vos sessions. <\/p>\n<p>Nous vous encourageons \u00e0 garder confidentiels les mots de passe que vous utilisez et \u00e0 \u00e9viter les escroqueries de type \"phishing\", o\u00f9 quelqu'un peut vous envoyer un courrier \u00e9lectronique semblant provenir de l'ASR et vous demandant vos informations personnelles. L'ASR ne vous demandera pas votre identifiant ou votre mot de passe par courrier \u00e9lectronique.<\/p>\n<h4>11. Sites li\u00e9s<\/h4>\n<p>Pour votre commodit\u00e9, nos sites web peuvent contenir des hyperliens vers d'autres sites web. Nous ne sommes pas responsables des pratiques en mati\u00e8re de protection de la vie priv\u00e9e des sites web li\u00e9s ou des soci\u00e9t\u00e9s que nous ne poss\u00e9dons pas ou que nous ne contr\u00f4lons pas, et la pr\u00e9sente politique de protection de la vie priv\u00e9e ne s'applique pas \u00e0 ces pratiques. Les liens vers d'autres sites web peuvent collecter des informations en plus de celles que nous collectons.<\/p>\n<p>Nous ne cautionnons aucun de ces sites, ni leurs produits ou services, ni aucun de leurs contenus. Nous vous encourageons \u00e0 rechercher et \u00e0 lire la politique de confidentialit\u00e9 de chaque site web li\u00e9 que vous visitez afin de comprendre comment les informations collect\u00e9es \u00e0 votre sujet sont utilis\u00e9es et prot\u00e9g\u00e9es.<\/p>\n<h4>12. Divulgations au titre de la loi californienne sur la protection de la vie priv\u00e9e des consommateurs<\/h4>\n<p>La loi californienne sur la protection de la vie priv\u00e9e des consommateurs (California Consumer Privacy Act, CCPA) oblige les entreprises \u00e0 indiquer si elles vendent des donn\u00e9es personnelles, que la CCPA appelle \"informations personnelles\".  Aux fins de la pr\u00e9sente section 12, les \"donn\u00e9es \u00e0 caract\u00e8re personnel\" comprennent toutes les \"informations \u00e0 caract\u00e8re personnel\" d\u00e9finies par la CCPA. <\/p>\n<p>En tant qu'entreprise relevant de la CCPA, nous ne vendons pas de donn\u00e9es \u00e0 caract\u00e8re personnel pour une contrepartie mon\u00e9taire. Nous pouvons partager des donn\u00e9es \u00e0 caract\u00e8re personnel avec des tiers ou leur permettre de collecter des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 partir de nos sites web ou de nos services s'il s'agit de soci\u00e9t\u00e9s affili\u00e9es, de tiers autoris\u00e9s par nous ou de partenaires commerciaux qui ont accept\u00e9 nos exigences contractuelles en mati\u00e8re de conservation, d'utilisation et de divulgation des donn\u00e9es \u00e0 caract\u00e8re personnel, ou si vous utilisez nos produits ou services pour interagir avec des tiers ou si vous nous demandez de divulguer vos donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 des tiers. <\/p>\n<p>En cas de conflit entre la pr\u00e9sente section 12 et le reste de notre politique de protection de la vie priv\u00e9e, les termes de la section 12 pr\u00e9vaudront en ce qui concerne les donn\u00e9es personnelles des r\u00e9sidents de Californie qui sont soumises \u00e0 la CCPA.<\/p>\n<h5>12.1 Cat\u00e9gories de donn\u00e9es personnelles divulgu\u00e9es<\/h5>\n<p>La CCPA nous oblige \u00e0 d\u00e9tailler les cat\u00e9gories de donn\u00e9es \u00e0 caract\u00e8re personnel que nous divulguons \u00e0 certaines fins commerciales. Au cours des douze (12) derniers mois, il se peut que nous ayons collect\u00e9 les cat\u00e9gories de donn\u00e9es \u00e0 caract\u00e8re personnel suivantes :<\/p>\n<ul>\n<li>Identifiants : nom, adresse postale, adresse \u00e9lectronique, adresse IP et autres identifiants similaires.<\/li>\n<li>Informations commerciales : registres des produits et services achet\u00e9s et autres ant\u00e9c\u00e9dents ou tendances des consommateurs.<\/li>\n<li>Informations sur l'activit\u00e9 Internet ou r\u00e9seau : historique de navigation ou de recherche, interaction avec nos sites web<\/li>\n<li>Donn\u00e9es de g\u00e9olocalisation : emplacement physique d'un appareil connect\u00e9 \u00e0 l'internet<\/li>\n<li>Informations financi\u00e8res : num\u00e9ro de compte bancaire, num\u00e9ro de carte de cr\u00e9dit et autres donn\u00e9es financi\u00e8res similaires.<\/li>\n<li>Informations professionnelles et li\u00e9es \u00e0 l'emploi : historique de l'emploi, titres des postes occup\u00e9s<\/li>\n<li>D\u00e9ductions tir\u00e9es de l'une ou l'autre de ces cat\u00e9gories<\/li>\n<\/ul>\n<h5>12.2 Objectifs commerciaux<\/h5>\n<p>Au cours des douze (12) mois pr\u00e9c\u00e9dents, il se peut que nous ayons collect\u00e9 et trait\u00e9 vos donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 diverses fins commerciales, notamment : <\/p>\n<ul>\n<li>Fournir des services professionnels<\/li>\n<li>Vendre un produit<\/li>\n<li>D\u00e9tection des incidents de s\u00e9curit\u00e9 et protection contre les activit\u00e9s malveillantes, trompeuses, frauduleuses ou ill\u00e9gales<\/li>\n<li>D\u00e9bogage pour identifier et r\u00e9parer les erreurs qui nuisent \u00e0 la fonctionnalit\u00e9<\/li>\n<li>entreprendre des activit\u00e9s visant \u00e0 v\u00e9rifier ou \u00e0 maintenir la qualit\u00e9 ou la s\u00e9curit\u00e9 de nos produits et services, et \u00e0 am\u00e9liorer, mettre \u00e0 niveau ou perfectionner nos produits et services<\/li>\n<\/ul>\n<p>Au cours des douze (12) mois pr\u00e9c\u00e9dents, nous pouvons avoir partag\u00e9 vos donn\u00e9es personnelles avec nos affili\u00e9s, vendeurs et fournisseurs qui fournissent des services en notre nom, et d'autres tiers tels que des partenaires commerciaux, des r\u00e9seaux publicitaires, des fournisseurs de services Internet, des fournisseurs d'analyse de donn\u00e9es, des syst\u00e8mes d'exploitation et des plateformes, des fournisseurs de services de v\u00e9rification d'identit\u00e9, des organismes de r\u00e9glementation et des autorit\u00e9s gouvernementales.<\/p>\n<h5>12.3 Droits de l'ACCP<\/h5>\n<p>Les lois californiennes accordent aux r\u00e9sidents de l'\u00c9tat certains droits dans certaines circonstances en ce qui concerne leurs donn\u00e9es personnelles :<\/p>\n<ul>\n<li>Droit de refuser la vente : nous ne vendons pas vos donn\u00e9es \u00e0 caract\u00e8re personnel pour une contrepartie mon\u00e9taire. Toutefois, nous partageons des donn\u00e9es \u00e0 caract\u00e8re personnel, ce qui pourrait \u00eatre consid\u00e9r\u00e9 comme une \"vente\" au sens de la d\u00e9finition donn\u00e9e par la CCPA. Vous avez le droit de nous demander de ne pas vendre vos donn\u00e9es personnelles en nous informant \u00e0 l'adresse suivante <a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a>. Nous pouvons encore utiliser des donn\u00e9es personnelles agr\u00e9g\u00e9es, pseudonymis\u00e9es et d\u00e9personnalis\u00e9es qui ne permettent pas de vous identifier ou d'identifier une personne. Nous pouvons \u00e9galement conserver vos donn\u00e9es personnelles si cela s'av\u00e8re n\u00e9cessaire pour nous conformer \u00e0 nos obligations l\u00e9gales, pour faire appliquer les accords et pour r\u00e9soudre les litiges.<\/li>\n<li>Droit d'acc\u00e8s : vous pouvez demander \u00e0 \u00eatre inform\u00e9 de la collecte et de l'utilisation de vos donn\u00e9es \u00e0 caract\u00e8re personnel au cours des douze (12) derniers mois. Cela inclut les cat\u00e9gories de donn\u00e9es \u00e0 caract\u00e8re personnel que nous avons vendues ou divulgu\u00e9es \u00e0 des fins commerciales vous concernant, ainsi que les cat\u00e9gories de tiers auxquels les donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 vendues ou divulgu\u00e9es. Cela inclut votre droit de demander la divulgation d'\u00e9l\u00e9ments sp\u00e9cifiques de vos donn\u00e9es \u00e0 caract\u00e8re personnel, tels que\n<ul>\n<li>Les cat\u00e9gories de donn\u00e9es personnelles que nous avons collect\u00e9es \u00e0 votre sujet<\/li>\n<li>Les cat\u00e9gories ou sources \u00e0 partir desquelles nous avons collect\u00e9 les donn\u00e9es \u00e0 caract\u00e8re personnel<\/li>\n<li>L'objectif professionnel ou commercial de la collecte ou de la vente des donn\u00e9es \u00e0 caract\u00e8re personnel<\/li>\n<li>Les cat\u00e9gories de tiers avec lesquels nous partageons des donn\u00e9es \u00e0 caract\u00e8re personnel<\/li>\n<li>Les donn\u00e9es personnelles sp\u00e9cifiques que nous avons collect\u00e9es \u00e0 votre sujet<\/li>\n<li>Les cat\u00e9gories de donn\u00e9es \u00e0 caract\u00e8re personnel que nous avons divulgu\u00e9es \u00e0 votre sujet \u00e0 des fins professionnelles<\/li>\n<li>Les cat\u00e9gories de donn\u00e9es personnelles que nous avons vendues \u00e0 votre sujet<\/li>\n<li>Les cat\u00e9gories de tiers auxquels nous avons vendu les donn\u00e9es \u00e0 caract\u00e8re personnel<\/li>\n<\/ul>\n<p>Les informations peuvent \u00eatre fournies par courrier ou par voie \u00e9lectronique. Si elles sont fournies par voie \u00e9lectronique, elles seront portables et dans un format facilement utilisable afin que vous puissiez les transmettre \u00e0 une autre entit\u00e9 ou personne.<\/li>\n<li>Droit de demander la suppression : vous pouvez nous demander de supprimer toutes les donn\u00e9es \u00e0 caract\u00e8re personnel que nous avons recueillies aupr\u00e8s de vous. Nous ne supprimerons pas les donn\u00e9es \u00e0 caract\u00e8re personnel si cela pose des probl\u00e8mes pour la r\u00e9alisation d'une transaction ou le respect d'une obligation l\u00e9gale. Ce droit de demander la suppression est soumis \u00e0 notre droit de conserver vos donn\u00e9es personnelles \u00e0 des fins sp\u00e9cifiques autoris\u00e9es par la CCPA. <\/li>\n<li class=\"translation-block\"><strong>Droit \u00e0 la non-discrimination<\/strong> : nous ne ferons jamais de discrimination \u00e0 votre \u00e9gard en vous refusant des biens ou des services ou en vous fournissant un niveau ou une qualit\u00e9 de biens ou de services diff\u00e9rents si vous exercez l'un des droits qui vous ont \u00e9t\u00e9 accord\u00e9s.<\/li>\n<\/ul>\n<h5>12.4 Comment nous traitons vos demandes<\/h5>\n<p>Dans le cadre du traitement de votre demande, nous vous demanderons de fournir certaines donn\u00e9es \u00e0 caract\u00e8re personnel vous concernant afin de v\u00e9rifier votre identit\u00e9 conform\u00e9ment aux exigences de la CCPA. Ces informations peuvent inclure vos nom et pr\u00e9nom, votre adresse \u00e9lectronique, votre adresse physique, votre num\u00e9ro de t\u00e9l\u00e9phone, votre num\u00e9ro de compte et la nature de votre relation avec nous.<\/p>\n<p>Vous pouvez \u00e9galement d\u00e9signer un agent autoris\u00e9 pour effectuer une demande en votre nom. Pour r\u00e9pondre \u00e0 une telle demande, nous aurons besoin des donn\u00e9es \u00e0 caract\u00e8re personnel mentionn\u00e9es ci-dessus \u00e0 des fins de v\u00e9rification de l'identit\u00e9, ainsi que du nom et du pr\u00e9nom, de l'adresse \u00e9lectronique et du num\u00e9ro de t\u00e9l\u00e9phone de votre agent autoris\u00e9.<\/p>\n<p>Une fois que nous avons v\u00e9rifi\u00e9 votre demande, nous nous effor\u00e7ons d'y r\u00e9pondre dans un d\u00e9lai de quarante-cinq (45) jours. Si nous avons besoin de plus de temps, nous vous informerons par \u00e9crit de la raison et de la p\u00e9riode de prolongation. Si nous ne pouvons pas donner suite \u00e0 votre demande, nous vous r\u00e9pondrons par \u00e9crit en vous indiquant les raisons de cette impossibilit\u00e9.<\/p>\n<p>Toute divulgation ne couvrira que la p\u00e9riode de douze (12) mois pr\u00e9c\u00e9dant la r\u00e9ception de la demande. <\/p>\n<p>Nous ne facturons pas de frais pour traiter ou r\u00e9pondre \u00e0 votre demande, \u00e0 moins qu'il ne s'agisse de demandes excessives, r\u00e9p\u00e9titives ou manifestement infond\u00e9es. Si nous estimons que votre demande justifie le paiement d'une redevance, nous vous en donnerons la raison, par \u00e9crit, et nous vous fournirons une estimation des co\u00fbts avant de donner suite \u00e0 votre demande.<\/p>\n<p>Vous ne pouvez pr\u00e9senter une demande d'acc\u00e8s aux donn\u00e9es \u00e0 caract\u00e8re personnel que deux (2) fois au maximum au cours d'une p\u00e9riode de douze (12) mois.<\/p>\n<h5>12.5 R\u00e9sidents de moins de 18 ans<\/h5>\n<p>Si vous \u00eates un r\u00e9sident californien \u00e2g\u00e9 de moins de dix-huit (18) ans et que vous avez ouvert un compte chez nous, vous pouvez nous demander de supprimer le contenu ou les informations que vous avez publi\u00e9s sur nos sites web. Cette demande ne garantit pas que nous supprimerons compl\u00e8tement le contenu ou les informations, car une partie de votre contenu peut avoir \u00e9t\u00e9 r\u00e9affich\u00e9e par un autre utilisateur.<\/p>\n<h4>13. Modifications de la pr\u00e9sente politique de protection de la vie priv\u00e9e<\/h4>\n<p>Nous mettrons \u00e0 jour la pr\u00e9sente politique de confidentialit\u00e9 de temps \u00e0 autre afin de refl\u00e9ter les changements dans nos pratiques, nos technologies et nos exigences l\u00e9gales. Nous mettrons \u00e0 jour la date d'entr\u00e9e en vigueur \u00e0 la fin du pr\u00e9sent document.<\/p>\n<p>Si nous proc\u00e9dons \u00e0 une mise \u00e0 jour importante, nous pouvons vous en avertir avant qu'elle n'entre en vigueur en publiant un avis sur nos sites web ou en vous contactant directement. Dans la mesure du possible, nous vous demanderons votre consentement pour ces modifications lorsque la loi applicable l'exige.<\/p>\n<p>Nous vous encourageons \u00e0 consulter r\u00e9guli\u00e8rement la pr\u00e9sente politique de protection de la vie priv\u00e9e afin de rester inform\u00e9 de la collecte, du traitement et du partage de vos donn\u00e9es \u00e0 caract\u00e8re personnel. <\/p>\n<p>Le fait d'acc\u00e9der au site ou de l'utiliser de quelque mani\u00e8re que ce soit vaut acceptation de la pr\u00e9sente politique de protection de la vie priv\u00e9e.<\/p>\n<h4>14. Outil de d\u00e9pistage COVID-19 et cam\u00e9ra de vision thermique<\/h4>\n<p>Afin de r\u00e9duire le risque d'infections par le COVID-19 et d'assurer la s\u00e9curit\u00e9 de nos communaut\u00e9s, tous les employ\u00e9s de l'ASR, les travailleurs occasionnels et les visiteurs doivent remplir un questionnaire de sant\u00e9 quotidien et passer un test de temp\u00e9rature corporelle thermique pour avoir acc\u00e8s aux locaux de l'ASR. La cam\u00e9ra de vision thermique mesure votre temp\u00e9rature corporelle de mani\u00e8re anonyme et la RSA ne conserve pas votre temp\u00e9rature corporelle. Si votre temp\u00e9rature corporelle est \u00e9gale ou sup\u00e9rieure \u00e0 100 degr\u00e9s Fahrenheit, l'entr\u00e9e vous sera refus\u00e9e et\/ou il vous sera demand\u00e9 de quitter les locaux de l'ASR.<\/p>\n<p>L'outil de d\u00e9pistage de l'enqu\u00eate de sant\u00e9, disponible via une application ou un portail web, recueille votre nom, votre adresse \u00e9lectronique et certaines donn\u00e9es de sant\u00e9 que vous fournissez volontairement. Ces informations seront conserv\u00e9es sur votre appareil et ne seront pas partag\u00e9es avec l'ASR, sauf si vous d\u00e9clarez vous-m\u00eame que vous \u00eates positif au COVID-19. Dans ce cas, l'outil informera l'\u00e9quipe RSA appropri\u00e9e, et votre adresse \u00e9lectronique sera conserv\u00e9e pendant 30 jours maximum (sous r\u00e9serve des lois locales) afin que la RSA puisse vous contacter lorsqu'elle prend des mesures appropri\u00e9es pour prot\u00e9ger la sant\u00e9 et la s\u00e9curit\u00e9 des personnes sur les sites physiques de la RSA. Votre statut positif au COVID-19 sera communiqu\u00e9 \u00e0 l'\u00e9quipe de l'ASR et aux autorit\u00e9s de sant\u00e9 publique comp\u00e9tentes (conform\u00e9ment \u00e0 la loi). Votre statut sera \u00e9galement communiqu\u00e9 de mani\u00e8re anonyme aux personnes potentiellement infect\u00e9es \u00e0 des fins de recherche de contacts.<\/p>\n<h4>15. Notification des probl\u00e8mes de violation des droits d'auteur<\/h4>\n<p>Si un utilisateur estime que son travail prot\u00e9g\u00e9 par le droit d'auteur a \u00e9t\u00e9 copi\u00e9 et est accessible sur les sites web de l'ASR d'une mani\u00e8re qui constitue une violation du droit d'auteur, veuillez envoyer un avis \u00e0 :<\/p>\n<p>RSA Security LLC<br \/>\nA l'attention de : RSA Legal<br \/>\n176 Middlesex Turnpike<br \/>\nBedford, MA 01730<br \/>\nCourriel : <a href=\"mailto:Legalnotices@rsa.com\" rel=\"noopener\" target=\"_blank\">Legalnotices@rsa.com <\/a><\/p>\n<p>Les avis doivent comprendre chacun des \u00e9l\u00e9ments suivants :<\/p>\n<ol>\n<li>La signature \u00e9lectronique ou physique du titulaire du droit exclusif pr\u00e9tendument viol\u00e9, ou la signature \u00e9lectronique ou physique d'une personne autoris\u00e9e \u00e0 agir au nom du titulaire ;<\/li>\n<li>L'identification de l'\u0153uvre prot\u00e9g\u00e9e par des droits d'auteur qui aurait \u00e9t\u00e9 viol\u00e9e ou, si plusieurs \u0153uvres prot\u00e9g\u00e9es par des droits d'auteur sur un seul site en ligne sont couvertes par une seule notification, une liste repr\u00e9sentative de ces \u0153uvres sur ce site ;<\/li>\n<li>L'identification du mat\u00e9riel d\u00e9clar\u00e9 en infraction ou faisant l'objet d'une activit\u00e9 en infraction, pour lequel la d\u00e9sactivation de l'acc\u00e8s ou la suppression est demand\u00e9e, et des informations raisonnablement suffisantes pour nous permettre de localiser le mat\u00e9riel ;<\/li>\n<li>Si l'infraction invoqu\u00e9e est due au stockage interm\u00e9diaire et temporaire, ou \u00e0 la mise en cache, du mat\u00e9riel, inclure \u00e9galement une d\u00e9claration confirmant que le mat\u00e9riel en infraction a \u00e9t\u00e9 retir\u00e9 du site d'origine ou que l'acc\u00e8s \u00e0 ce mat\u00e9riel a \u00e9t\u00e9 d\u00e9sactiv\u00e9, ou qu'un tribunal a ordonn\u00e9 que le mat\u00e9riel soit ainsi retir\u00e9 ou que l'acc\u00e8s \u00e0 ce mat\u00e9riel soit d\u00e9sactiv\u00e9 ;<\/li>\n<li>Si l'infraction invoqu\u00e9e consiste \u00e0 renvoyer ou \u00e0 relier des utilisateurs \u00e0 un site en ligne contenant du mat\u00e9riel ou des activit\u00e9s illicites, en utilisant des outils de localisation d'informations, alors, au lieu de l'identification pr\u00e9vue aux paragraphes (3) ou (4), fournissez l'identification de la r\u00e9f\u00e9rence ou du lien vers le mat\u00e9riel ou l'activit\u00e9 en question, qui doit \u00eatre supprim\u00e9 ou dont l'acc\u00e8s doit \u00eatre d\u00e9sactiv\u00e9, ainsi que des informations raisonnablement suffisantes pour nous permettre de localiser cette r\u00e9f\u00e9rence ou ce lien ;<\/li>\n<li>Des informations raisonnablement suffisantes pour nous permettre de vous contacter, telles qu'une adresse, un num\u00e9ro de t\u00e9l\u00e9phone et, le cas \u00e9ch\u00e9ant, une adresse \u00e9lectronique \u00e0 laquelle vous pouvez \u00eatre contact\u00e9 ;<\/li>\n<li>Une d\u00e9claration selon laquelle vous pensez de bonne foi que l'utilisation du mat\u00e9riel de la mani\u00e8re faisant l'objet de la plainte n'est pas autoris\u00e9e par le d\u00e9tenteur des droits d'auteur, son agent ou la loi ; et,<\/li>\n<li>Une d\u00e9claration selon laquelle les informations contenues dans la notification sont exactes et, sous peine de parjure, que vous \u00eates autoris\u00e9 \u00e0 agir au nom du titulaire d'un droit exclusif pr\u00e9tendument enfreint.<\/li>\n<\/ol>\n<h4>16. Politique d'utilisation acceptable<\/h4>\n<h5>16.1 G\u00e9n\u00e9ralement<\/h5>\n<p>La politique d'utilisation acceptable de RSA et de ses soci\u00e9t\u00e9s affili\u00e9es (\"AUP\") est destin\u00e9e \u00e0 encourager une utilisation responsable de l'infrastructure, des r\u00e9seaux, des offres bas\u00e9es sur le cloud, des syst\u00e8mes, des services, des sites Web, des installations et des produits de RSA (collectivement, l'\"infrastructure et les services de RSA\") par nos clients et d'autres utilisateurs. Les utilisateurs acceptent d'\u00eatre li\u00e9s par les conditions de la pr\u00e9sente PUA. RSA se r\u00e9serve le droit de modifier cette PUA \u00e0 sa discr\u00e9tion et \u00e0 tout moment. Les modifications entreront en vigueur au moment de leur publication et les utilisateurs sont cens\u00e9s consulter cette page de temps \u00e0 autre pour prendre connaissance des changements que nous apportons, car ils sont juridiquement contraignants pour chaque utilisateur. L'utilisation par les utilisateurs des sites web de l'ASR apr\u00e8s que nous ayons apport\u00e9 des modifications constitue une acceptation de nos modifications.<\/p>\n<h5>16.2 Suspension ; r\u00e9siliation<\/h5>\n<p>Si la RSA d\u00e9termine qu'un utilisateur a viol\u00e9 une partie de la pr\u00e9sente PUA, la RSA peut mettre fin \u00e0 l'utilisation du site Web par l'utilisateur. L'ASR suspendra le service pour violation de la PUA sur la base la plus limit\u00e9e que l'ASR juge raisonnablement pratique dans les circonstances pour traiter la violation sous-jacente. La RSA tentera d'aviser l'utilisateur avant de suspendre le service en cas de violation de la PUA (par courriel ou par tout autre moyen de notification). Toutefois, la RSA peut suspendre le service sans pr\u00e9avis si elle prend connaissance d'une violation de la pr\u00e9sente PUA ou d'une loi ou d'un r\u00e8glement applicable qui expose la RSA \u00e0 une responsabilit\u00e9 criminelle ou civile, ou qui expose la RSA ou la propri\u00e9t\u00e9 d'un tiers \u00e0 un pr\u00e9judice. Le pr\u00e9judice peut inclure, sans s'y limiter, le risque de voir une ou plusieurs adresses IP plac\u00e9es sur des listes noires. La RSA peut prendre toute autre mesure qu'elle juge appropri\u00e9e dans les circonstances afin d'\u00e9liminer ou d'emp\u00eacher les violations r\u00e9p\u00e9t\u00e9es. La RSA n'est pas responsable de tout type de dommages que les utilisateurs ou les tiers pourraient subir et qui r\u00e9sulteraient en tout ou en partie de l'exercice par la RSA de ses droits en vertu de la pr\u00e9sente PUA. Cette exclusion de responsabilit\u00e9 ne comprend pas la responsabilit\u00e9 de l'ASR en cas de d\u00e9c\u00e8s ou de pr\u00e9judice corporel caus\u00e9 par sa n\u00e9gligence, ou toute autre responsabilit\u00e9 que l'ASR ne peut pas exclure ou limiter en vertu de la loi.<\/p>\n<h4>17. RSA Mobile App<\/h4>\n<p class=\"translation-block\">Pour en savoir plus sur les informations que nous pouvons traiter lors de l'utilisation de notre SecurID Mobile App, <a href=\"\/wp-content\/uploads\/securid-mobile-application-privacy.pdf\" target=\"_blank\" rel=\"noopener\">cliquez ici<\/a>.<\/p>\n<h4>18. Authentification par message texte RSA (SMS)<\/h4>\n<p class=\"translation-block\">Pour en savoir plus sur les informations que nous pouvons traiter lors de l'utilisation de l'authentification par code d'acc\u00e8s unique (OTP) bas\u00e9e sur un message texte, <a href=\"\/wp-content\/uploads\/securid-sms-authentication-privacy.pdf\" target=\"_blank\" rel=\"noopener\">cliquez ici<\/a>.<\/p>\n<h4>19. Divers<\/h4>\n<p class=\"translation-block\">Pour obtenir des informations plus importantes sur les conditions d'utilisation de ce site web, <a href=\"https:\/\/www.rsa.com\/fr_ca\/terms-of-use\/\" target=\"_self\">click here<\/a>.<br>\r\nCe site web peut contenir des liens ou des cadres d'autres sites web, qui peuvent ou non \u00eatre affili\u00e9s \u00e0 l'ASR. Ces liens et cadres sont disponibles dans le seul but de fournir des avantages suppl\u00e9mentaires aux utilisateurs. L'inclusion de ces liens et cadres ne signifie pas que l'ASR a connaissance de ces sites, qu'elle les approuve ou qu'elle est responsable de leur contenu. Par cons\u00e9quent, l'ASR ne peut \u00eatre tenue responsable de toute perte ou de tout dommage subi \u00e0 la suite de l'utilisation de ces liens ou cadres.<\/p>\n<h4>20. Nous contacter<\/h4>\n<p class=\"translation-block\">Pour exercer vos droits concernant vos donn\u00e9es personnelles, ou si vous avez des questions sur cette politique de confidentialit\u00e9 ou sur nos pratiques en mati\u00e8re de confidentialit\u00e9, veuillez nous envoyer un courriel \u00e0 <a href=\"mailto:privacy@rsa.com\" rel=\"noopener\" target=\"_blank\">privacy@rsa.com<\/a> ou \u00e9crivez-nous \u00e0:<br>\r\nRSA Security LLC<br>\r\nAttention : D\u00e9partement juridique - Protection de la vie priv\u00e9e<br>\r\n176 Middlesex Turnpike<br>\r\nBedford, MA 01730 USA<\/p>\n<p>Sachez que votre demande peut \u00eatre soumise \u00e0 des restrictions, conform\u00e9ment \u00e0 la l\u00e9gislation applicable.<\/p>\n<p><strong>Date d'entr\u00e9e en vigueur : 27 juillet 2022.<\/strong><\/p>\n<p>Politiques de confidentialit\u00e9 pr\u00e9c\u00e9dentes :<\/p>\n<ul>\n<li><a href=\"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-january-2022\/\">Janvier 2022<\/a><\/li>\n<\/ul>\n<p><strong>\u00a92022 RSA Security LLC ou ses filiales. Tous droits r\u00e9serv\u00e9s. Le logo RSA Conference, RSA et d'autres marques sont des marques commerciales de RSA Security LLC ou de ses filiales. D'autres marques peuvent \u00eatre des marques de leurs propri\u00e9taires respectifs.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Introduction La protection de votre vie priv\u00e9e est importante pour RSA Security LLC. C'est pourquoi nous avons \u00e9labor\u00e9 cette politique de confidentialit\u00e9 qui d\u00e9crit nos pratiques en mati\u00e8re de traitement, de collecte, d'utilisation et de partage de vos donn\u00e9es personnelles, ainsi que vos droits en mati\u00e8re de confidentialit\u00e9 en vertu de certaines lois sur la protection de la vie priv\u00e9e. Nous pouvons fournir des informations suppl\u00e9mentaires sur la confidentialit\u00e9 des donn\u00e9es en utilisant un ou des avis de confidentialit\u00e9 suppl\u00e9mentaires. ... <a href=\"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/\">Suite<\/a><\/p>","protected":false},"author":2,"featured_media":0,"parent":3,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-policy.blade.php","meta":{"_acf_changed":false,"_searchwp_excluded":"","inline_featured_image":false,"footnotes":""},"class_list":["post-24430","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - July 2022 - RSA<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - July 2022 - RSA\" \/>\n<meta property=\"og:description\" content=\"Introduction Your privacy is important to RSA Security LLC so we have developed this Privacy Policy that outlines our privacy practice on how we process, collect, use and share your personal data as well as your privacy rights under certain privacy laws. We may provide additional data privacy information by using a supplementary privacy notice(s). &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"RSA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-07T20:58:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/fr_ca\\\/privacy\\\/privacy-policy-july-2022\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/fr_ca\\\/privacy\\\/privacy-policy-july-2022\\\/\",\"name\":\"Privacy Policy - July 2022 - RSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\"},\"datePublished\":\"2023-01-12T20:33:49+00:00\",\"dateModified\":\"2025-02-07T20:58:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/fr_ca\\\/privacy\\\/privacy-policy-july-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rsa.com\\\/fr_ca\\\/privacy\\\/privacy-policy-july-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/fr_ca\\\/privacy\\\/privacy-policy-july-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/fr_ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/fr_ca\\\/privacy\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Privacy Policy &#8211; July 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"name\":\"RSA\",\"description\":\"Cybersecurity and Digital Risk Management Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rsa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\",\"name\":\"RSA\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"width\":2880,\"height\":1020,\"caption\":\"RSA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - Juillet 2022 - RSA","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_CA","og_type":"article","og_title":"Privacy Policy - July 2022 - RSA","og_description":"Introduction Your privacy is important to RSA Security LLC so we have developed this Privacy Policy that outlines our privacy practice on how we process, collect, use and share your personal data as well as your privacy rights under certain privacy laws. We may provide additional data privacy information by using a supplementary privacy notice(s). &hellip; Continued","og_url":"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/","og_site_name":"RSA","article_modified_time":"2025-02-07T20:58:34+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/","url":"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/","name":"Politique de confidentialit\u00e9 - Juillet 2022 - RSA","isPartOf":{"@id":"https:\/\/www.rsa.com\/#website"},"datePublished":"2023-01-12T20:33:49+00:00","dateModified":"2025-02-07T20:58:34+00:00","breadcrumb":{"@id":"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rsa.com\/fr_ca\/privacy\/privacy-policy-july-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rsa.com\/fr_ca\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy","item":"https:\/\/www.rsa.com\/fr_ca\/privacy\/"},{"@type":"ListItem","position":3,"name":"Privacy Policy &#8211; July 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.rsa.com\/#website","url":"https:\/\/www.rsa.com\/","name":"RSA","description":"Solutions de cybers\u00e9curit\u00e9 et de gestion des risques num\u00e9riques","publisher":{"@id":"https:\/\/www.rsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.rsa.com\/#organization","name":"RSA","url":"https:\/\/www.rsa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","width":2880,"height":1020,"caption":"RSA"},"image":{"@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/pages\/24430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/comments?post=24430"}],"version-history":[{"count":3,"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/pages\/24430\/revisions"}],"predecessor-version":[{"id":24604,"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/pages\/24430\/revisions\/24604"}],"up":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/pages\/3"}],"wp:attachment":[{"href":"https:\/\/www.rsa.com\/fr_ca\/wp-json\/wp\/v2\/media?parent=24430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}