{"id":2249,"date":"2021-09-13T12:58:58","date_gmt":"2021-09-13T19:58:58","guid":{"rendered":"https:\/\/live-rsa-hub.pantheonsite.io\/resources\/\/"},"modified":"2025-11-17T11:59:44","modified_gmt":"2025-11-17T16:59:44","slug":"mfa-for-vmware-workspace-one","status":"publish","type":"resources_post_type","link":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/","title":{"rendered":"Autenticaci\u00f3n multifactor moderna para VMware Workspace ONE"},"content":{"rendered":"","protected":false},"featured_media":17721,"template":"","class_list":["post-2249","resources_post_type","type-resources_post_type","status-publish","has-post-thumbnail","hentry","resource_type-datasheets"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modern Multi-Factor Authentication for VMware Workspace ONE - RSA<\/title>\n<meta name=\"description\" content=\"RSA SecurID\u00ae Access secures the VMware Workspace ONE digital workspace to ensure the right users access the right information across the entire application catalog from any device.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modern Multi-Factor Authentication for VMware Workspace ONE\" \/>\n<meta property=\"og:description\" content=\"RSA SecurID\u00ae Access secures the VMware Workspace ONE digital workspace to ensure the right users access the right information across the entire application catalog from any device.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/\" \/>\n<meta property=\"og:site_name\" content=\"RSA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T16:59:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Modern Multi-Factor Authentication for VMware Workspace ONE\" \/>\n<meta name=\"twitter:description\" content=\"RSA SecurID\u00ae Access secures the VMware Workspace ONE digital workspace to ensure the right users access the right information across the entire application catalog from any device.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/resources\\\/datasheets\\\/mfa-for-vmware-workspace-one\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/resources\\\/datasheets\\\/mfa-for-vmware-workspace-one\\\/\",\"name\":\"Modern Multi-Factor Authentication for VMware Workspace ONE - RSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/id\\\/resources\\\/datasheets\\\/mfa-for-vmware-workspace-one\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/id\\\/resources\\\/datasheets\\\/mfa-for-vmware-workspace-one\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/RSA_Data_sheet_Thumbnail.jpg\",\"datePublished\":\"2021-09-13T19:58:58+00:00\",\"dateModified\":\"2025-11-17T16:59:44+00:00\",\"description\":\"RSA SecurID\u00ae Access secures the VMware Workspace ONE digital workspace to ensure the right users access the right information across the entire application catalog from any device.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/resources\\\/datasheets\\\/mfa-for-vmware-workspace-one\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rsa.com\\\/es\\\/resources\\\/datasheets\\\/mfa-for-vmware-workspace-one\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/id\\\/resources\\\/datasheets\\\/mfa-for-vmware-workspace-one\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/RSA_Data_sheet_Thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/RSA_Data_sheet_Thumbnail.jpg\",\"width\":830,\"height\":644},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/resources\\\/datasheets\\\/mfa-for-vmware-workspace-one\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modern Multi-Factor Authentication for VMware Workspace ONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"name\":\"RSA\",\"description\":\"Cybersecurity and Digital Risk Management Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rsa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\",\"name\":\"RSA\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"width\":2880,\"height\":1020,\"caption\":\"RSA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"knowsAbout\":[\"multi-factor authentication\",\"passwordless authentication\",\"identity and access management\",\"identity governance and administration\",\"zero trust\",\"threat detection and response\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autenticaci\u00f3n multifactor moderna para VMware Workspace ONE - RSA","description":"RSA SecurID\u00ae Access protege el espacio de trabajo digital VMware Workspace ONE para garantizar que los usuarios adecuados accedan a la informaci\u00f3n correcta en todo el cat\u00e1logo de aplicaciones desde cualquier dispositivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/","og_locale":"es_ES","og_type":"article","og_title":"Modern Multi-Factor Authentication for VMware Workspace ONE","og_description":"RSA SecurID\u00ae Access secures the VMware Workspace ONE digital workspace to ensure the right users access the right information across the entire application catalog from any device.","og_url":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/","og_site_name":"RSA","article_modified_time":"2025-11-17T16:59:44+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Modern Multi-Factor Authentication for VMware Workspace ONE","twitter_description":"RSA SecurID\u00ae Access secures the VMware Workspace ONE digital workspace to ensure the right users access the right information across the entire application catalog from any device.","twitter_image":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/","url":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/","name":"Autenticaci\u00f3n multifactor moderna para VMware Workspace ONE - RSA","isPartOf":{"@id":"https:\/\/www.rsa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rsa.com\/id\/resources\/datasheets\/mfa-for-vmware-workspace-one\/#primaryimage"},"image":{"@id":"https:\/\/www.rsa.com\/id\/resources\/datasheets\/mfa-for-vmware-workspace-one\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/RSA_Data_sheet_Thumbnail.jpg","datePublished":"2021-09-13T19:58:58+00:00","dateModified":"2025-11-17T16:59:44+00:00","description":"RSA SecurID\u00ae Access protege el espacio de trabajo digital VMware Workspace ONE para garantizar que los usuarios adecuados accedan a la informaci\u00f3n correcta en todo el cat\u00e1logo de aplicaciones desde cualquier dispositivo.","breadcrumb":{"@id":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.rsa.com\/id\/resources\/datasheets\/mfa-for-vmware-workspace-one\/#primaryimage","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/RSA_Data_sheet_Thumbnail.jpg","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/RSA_Data_sheet_Thumbnail.jpg","width":830,"height":644},{"@type":"BreadcrumbList","@id":"https:\/\/www.rsa.com\/es\/resources\/datasheets\/mfa-for-vmware-workspace-one\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rsa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Modern Multi-Factor Authentication for VMware Workspace ONE"}]},{"@type":"WebSite","@id":"https:\/\/www.rsa.com\/#website","url":"https:\/\/www.rsa.com\/","name":"RSA","description":"Soluciones de ciberseguridad y gesti\u00f3n de riesgos digitales","publisher":{"@id":"https:\/\/www.rsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.rsa.com\/#organization","name":"RSA","url":"https:\/\/www.rsa.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","width":2880,"height":1020,"caption":"RSA"},"image":{"@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/"},"knowsAbout":["multi-factor authentication","passwordless authentication","identity and access management","identity governance and administration","zero trust","threat detection and response"]}]}},"_links":{"self":[{"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/resources_post_type\/2249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/resources_post_type"}],"about":[{"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/types\/resources_post_type"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/media\/17721"}],"wp:attachment":[{"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/media?parent=2249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}