{"id":3615,"date":"2022-08-08T15:37:49","date_gmt":"2022-08-08T19:37:49","guid":{"rendered":"https:\/\/www.rsa.com\/?page_id=3615"},"modified":"2026-03-24T15:50:54","modified_gmt":"2026-03-24T19:50:54","slug":"privacy-policy-january-2022","status":"publish","type":"page","link":"https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/","title":{"rendered":"Pol\u00edtica de privacidad - Enero de 2022"},"content":{"rendered":"<p>Su privacidad es importante para nosotros, por lo que hemos desarrollado esta Declaraci\u00f3n de Privacidad que describe nuestra pr\u00e1ctica de privacidad sobre c\u00f3mo procesamos, recopilamos, utilizamos y compartimos su informaci\u00f3n personal, as\u00ed como sus derechos de privacidad bajo ciertas leyes de privacidad.<\/p>\n<p>Esta Declaraci\u00f3n de Privacidad (\"Declaraci\u00f3n de Privacidad\") se aplica a RSA Security LLC (\"RSA\" \"nosotros\" o \"nuestro\").<\/p>\n<h2><strong>Visi\u00f3n general de nuestras pr\u00e1cticas de privacidad<\/strong><\/h2>\n<h3>Informaci\u00f3n que recopilamos sobre usted<\/h3>\n<p>Recopilamos su informaci\u00f3n personal directamente de usted a trav\u00e9s de sus interacciones, uso y experiencias con nuestro sitio web, productos y servicios. Tambi\u00e9n obtenemos su informaci\u00f3n indirectamente de nuestros socios comerciales y de terceras fuentes. Para m\u00e1s informaci\u00f3n sobre los tipos y fuentes de informaci\u00f3n que recopilamos sobre usted, consulte: Informaci\u00f3n que recopilamos sobre usted<\/p>\n<h3>Aplicaci\u00f3n m\u00f3vil SecurID<\/h3>\n<p class=\"translation-block\">Para obtener m\u00e1s informaci\u00f3n sobre la informaci\u00f3n que podemos procesar durante el uso de nuestra aplicaci\u00f3n m\u00f3vil SecurID, <a href=\"\/wp-content\/uploads\/securid-mobile-application-privacy.pdf\" target=\"_blank\" rel=\"noopener\">haga clic aqu\u00ed<\/a>.<\/p>\n<h3>Autenticaci\u00f3n por mensaje de texto (SMS) SecurID<\/h3>\n<p class=\"translation-block\">Para obtener m\u00e1s informaci\u00f3n sobre la informaci\u00f3n que podemos procesar durante el uso de la autenticaci\u00f3n con c\u00f3digo de un solo uso (OTP) basada en mensajes de texto, <a href=\"\/wp-content\/uploads\/securid-sms-authentication-privacy.pdf\" target=\"_blank\" rel=\"noopener\">haga clic aqu\u00ed<\/a>.<\/p>\n<h3>C\u00f3mo utilizamos y compartimos su informaci\u00f3n<\/h3>\n<p>Utilizamos su informaci\u00f3n personal para proporcionarle nuestros productos y servicios, mejorar nuestros productos y servicios, adaptar su experiencia como cliente de RSA, personalizar nuestros productos y servicios y hacerle recomendaciones, publicitarnos y comercializar con usted, y para cumplir con la legislaci\u00f3n aplicable. Adem\u00e1s, utilizamos su informaci\u00f3n para ayudar a mejorar la seguridad de nuestro sitio web, productos y servicios, lo que incluye detectar, prevenir y responder al fraude y a los riesgos de seguridad que podr\u00edan perjudicarle a usted o a RSA. Podemos compartir su informaci\u00f3n personal con nuestras empresas afiliadas y socios comerciales para que realicen trabajos para nosotros, como completar cualquier transacci\u00f3n, proporcionarle la informaci\u00f3n m\u00e1s reciente sobre nuestros productos y servicios y ofrecerle nuestras \u00faltimas promociones. Para m\u00e1s informaci\u00f3n, consulte C\u00f3mo utilizamos y compartimos su informaci\u00f3n.<\/p>\n<h3>Nuestro uso de cookies y otras tecnolog\u00edas<\/h3>\n<p>Los sitios web, servicios en l\u00ednea, aplicaciones interactivas, mensajes de correo electr\u00f3nico y anuncios publicitarios de RSA pueden utilizar cookies y tecnolog\u00edas similares para ayudarnos a adaptar su experiencia, comprender mejor sus preferencias, indicarnos qu\u00e9 partes de nuestros sitios web ha visitado, facilitar y medir la eficacia de nuestros anuncios basados en intereses y b\u00fasquedas en la web. Tambi\u00e9n utilizamos balizas web para ayudar a entregar cookies y recopilar datos de uso y rendimiento. Usted tiene opciones sobre c\u00f3mo RSA y nuestros Socios Comerciales llegan a usted haciendo referencia a los Anuncios y Correos Electr\u00f3nicos. Para obtener m\u00e1s informaci\u00f3n, consulte Nuestro uso de cookies y otras tecnolog\u00edas.<\/p>\n<h3>Acceso, supresi\u00f3n y actualizaci\u00f3n de sus datos<\/h3>\n<h5 class=\"translation-block\">Puede ejercer sus Derechos de Privacidad del Consumidor en relaci\u00f3n con su informaci\u00f3n personal enviando un correo electr\u00f3nico a <a href=\"mailto:privacy@rsa.com\" target=\"_self\">privacy@rsa.com<\/a>.<\/h5>\n<p>&nbsp;<\/p>\n<h3>Contacte con nosotros<\/h3>\n<p>Para m\u00e1s informaci\u00f3n, consulte Sus derechos de privacidad como consumidor. Si tiene alguna pregunta, duda o queja sobre privacidad, p\u00f3ngase en contacto con nosotros en privacy@rsa.com o escr\u00edbanos a:<\/p>\n<ul>\n<li>RSA Security LLC<br \/>\nAtenci\u00f3n Departamento Jur\u00eddico - Privacidad<br \/>\n176 Middlesex Turnpike<br \/>\nBedford, MA 01730 EE.UU.<\/li>\n<\/ul>\n<h3>Consideraciones especiales para los residentes en California<\/h3>\n<p>Como residente de California, usted tiene ciertos derechos de privacidad del consumidor que puede conocer y ejercer como se describe aqu\u00ed. Si desea obtener m\u00e1s informaci\u00f3n sobre las categor\u00edas de datos personales que recopilamos sobre usted y sobre c\u00f3mo compartimos sus datos personales con nuestros socios comerciales, haga clic aqu\u00ed. No \"vendemos\" su informaci\u00f3n personal a ning\u00fan socio comercial, tal y como se define actualmente en la Ley de Protecci\u00f3n del Consumidor de California.<\/p>\n<h3>Sus opciones de marketing<\/h3>\n<p>Usted tiene opciones sobre la forma en que RSA se pone en contacto con usted con ofertas de marketing y sobre otros usos de su informaci\u00f3n. Para obtener m\u00e1s informaci\u00f3n sobre sus opciones, consulte Sus opciones de marketing y Nuestro uso de cookies y otras tecnolog\u00edas.<\/p>\n<h3>Socio comercial<\/h3>\n<p>Se refiere a cualquier contratista, proveedor, prestador de servicios, procesador de tarjetas de d\u00e9bito o cr\u00e9dito con el que tengamos una relaci\u00f3n comercial para ofrecerle nuestras ofertas, productos, servicios, procesar su pago, predecir mejor y ofrecerle contenidos y ofertas de marketing que puedan interesarle.<\/p>\n<h3>Cambios en esta declaraci\u00f3n de confidencialidad<\/h3>\n<p>Es posible que modifiquemos esta Declaraci\u00f3n de Privacidad cuando sea necesario para ofrecer una mayor transparencia o en respuesta a:<\/p>\n<ul>\n<li>Comentarios de nuestros clientes, reguladores, industria u otras partes interesadas.<\/li>\n<li>Cambios en nuestras pr\u00e1cticas de privacidad, productos o servicios. Cambios en la legislaci\u00f3n aplicable en materia de privacidad.<\/li>\n<li>Si se producen cambios sustanciales en la Declaraci\u00f3n de Privacidad, revisaremos la fecha de \"\u00faltima actualizaci\u00f3n\" que figura al pie de la declaraci\u00f3n.<\/li>\n<\/ul>\n<p>Le recomendamos que revise peri\u00f3dicamente esta Declaraci\u00f3n de Privacidad para saber c\u00f3mo RSA protege su informaci\u00f3n.<\/p>\n<h2>Contenido de esta declaraci\u00f3n de confidencialidad<\/h2>\n<p>Esta declaraci\u00f3n de privacidad se aplica a la informaci\u00f3n personal, que definimos como cualquier informaci\u00f3n relativa a una persona identificada o identificable que puede ser identificada, directa o indirectamente, en particular por referencia a un n\u00famero de identificaci\u00f3n o a uno o m\u00e1s factores espec\u00edficos de su identidad f\u00edsica, fisiol\u00f3gica, mental, econ\u00f3mica, cultural o social.<\/p>\n<p>Esta declaraci\u00f3n de privacidad se aplica a toda la informaci\u00f3n personal que recopilamos cuando usted accede o utiliza nuestros sitios web, productos, servicios o interact\u00faa de cualquier otro modo con nosotros o nuestros representantes. Esta declaraci\u00f3n no se aplica a los datos que no sean informaci\u00f3n personal, incluidos los datos an\u00f3nimos, desidentificados o agregados.<\/p>\n<h3 id=\"information-we-collect-about-you\">Informaci\u00f3n que recopilamos<\/h3>\n<p>El tipo de informaci\u00f3n que recopilamos sobre usted depende del uso que haga de nuestros productos y servicios y de la forma en que interact\u00fae con nosotros. Puede incluir informaci\u00f3n sobre:<\/p>\n<ul>\n<li>C\u00f3mo utiliza o visita nuestros sitios web, cuentas con RSA o aplicaciones.<\/li>\n<li>C\u00f3mo utiliza nuestros servicios y productos e interact\u00faa con nosotros.<\/li>\n<li>Informaci\u00f3n de contacto, facturaci\u00f3n y otros datos que nos facilite.<\/li>\n<li>Mejorar y desarrollar nuestros productos y servicios.<\/li>\n<li>Personalizar nuestros productos y servicios y hacer recomendaciones.<\/li>\n<li>Publicitarnos y comercializar con usted, lo que incluye el env\u00edo de comunicaciones promocionales, publicidad dirigida y presentarle ofertas relevantes.<\/li>\n<\/ul>\n<p>Tambi\u00e9n obtenemos informaci\u00f3n de terceros. Protegemos la informaci\u00f3n obtenida de terceros de acuerdo con las pr\u00e1cticas de privacidad descritas en esta Declaraci\u00f3n de Privacidad. Estas fuentes de terceros var\u00edan con el tiempo y pueden incluir:<\/p>\n<ul>\n<li>Corredores de datos a los que compramos datos demogr\u00e1ficos para complementar la informaci\u00f3n que<\/li>\n<li>sobre usted.<\/li>\n<li>Servicios de comunicaci\u00f3n, incluidos proveedores de correo electr\u00f3nico y redes sociales, cuando usted autorice el acceso a su informaci\u00f3n en dichos servicios o redes de terceros.<\/li>\n<li>Socios con los que ofrecemos productos o servicios de marca compartida o participamos en actividades de marketing conjuntas.<\/li>\n<li>Fuentes de acceso p\u00fablico, como las bases de datos gubernamentales abiertas.<\/li>\n<\/ul>\n<p>La informaci\u00f3n personal que recopilamos puede incluir lo siguiente:<\/p>\n<ul>\n<li><i>Datos de contacto <\/i>como su nombre, direcci\u00f3n de correo electr\u00f3nico, direcci\u00f3n postal y n\u00fameros de tel\u00e9fono de contacto.<\/li>\n<li><i>Informaci\u00f3n sobre empleo <\/i>como su cargo y otra informaci\u00f3n comercial o empresarial.<\/li>\n<li><i>Credenciales <\/i>como sus contrase\u00f1as, sugerencias de contrase\u00f1as e informaci\u00f3n de seguridad similar utilizada para la autenticaci\u00f3n y el acceso a MiCuenta.<\/li>\n<li><i>Informaci\u00f3n demogr\u00e1fica <\/i>como su edad, sexo, pa\u00eds, intereses y preferencias;<\/li>\n<li><i>Informaci\u00f3n del formulario web <\/i>que usted facilite en nuestros formularios web (en los formularios que usted decida cumplimentar se indicar\u00e1 si la informaci\u00f3n solicitada es obligatoria o voluntaria);<\/li>\n<li><i>Informaci\u00f3n de pago <\/i>para procesar los pagos, como el n\u00famero de su instrumento de pago (por ejemplo, el n\u00famero de una tarjeta de cr\u00e9dito) y el c\u00f3digo de seguridad asociado a su instrumento de pago.<\/li>\n<li><i>Informaci\u00f3n sobre el historial de la cuenta <\/i>relacionadas con los productos o servicios que adquiere y las actividades asociadas a su cuenta.<\/li>\n<li><i>Cookies e informaci\u00f3n de seguimiento <\/i>como la direcci\u00f3n IP, el identificador del dispositivo, los datos de localizaci\u00f3n, el tipo e idioma del navegador, las horas de acceso, el Localizador Uniforme de Recursos (URL), otros identificadores \u00fanicos y otros datos t\u00e9cnicos que puedan identificar de forma exclusiva su dispositivo, sistema o navegador.<\/li>\n<li><i>Buscar informaci\u00f3n hist\u00f3rica <\/i>sobre los sitios web que visita.<\/li>\n<li><i>Informes de errores e informaci\u00f3n sobre el rendimiento <\/i>de los productos y cualquier problema que experimente, incluidos los informes de errores.<\/li>\n<li><i>Soluci\u00f3n de problemas y ayuda <\/i>informaci\u00f3n cuando se pone en contacto con RSA para obtener asistencia t\u00e9cnica o servicios de atenci\u00f3n al cliente, las conversaciones telef\u00f3nicas o sesiones de chat con nuestros representantes pueden ser controladas y grabadas<i>.<\/i><\/li>\n<li><i>Informaci\u00f3n sobre el consumo de contenidos <\/i>sobre contenidos multimedia (por ejemplo, televisi\u00f3n, aplicaciones y juegos) a los que acceda a trav\u00e9s de nuestros productos.<\/li>\n<li><i>Informaci\u00f3n sobre opiniones y valoraciones <\/i>que nos proporcione, como los comentarios de las encuestas a clientes y las rese\u00f1as de productos que escriba.<\/li>\n<\/ul>\n<h3 id=\"how-we-use-and-share-your-information\">C\u00f3mo utilizamos y compartimos su informaci\u00f3n<\/h3>\n<p>Utilizamos y compartimos su informaci\u00f3n para<\/p>\n<ul>\n<li>Suministrar y mantener nuestros productos y servicios.<\/li>\n<li>Establezca y mantenga su cuenta.<\/li>\n<li>Medir el riesgo de cr\u00e9dito y de pago.<\/li>\n<li>Proporcionar servicios e informaci\u00f3n relacionados con las cuentas.<\/li>\n<li>Ayudarle con cuestiones o preguntas de atenci\u00f3n al cliente y soporte t\u00e9cnico.<\/li>\n<li>Ayudarnos a mejorar y personalizar nuestros productos y servicios.<\/li>\n<li>Predecir mejor el contenido y las ofertas de marketing que puedan interesarle, lo que incluye enviar comunicaciones promocionales, orientar la publicidad y presentarle ofertas relevantes.<\/li>\n<li>Autentificarte.<\/li>\n<li>Detectar y prevenir el fraude.<\/li>\n<li>Gestionar y proteger nuestras redes, servicios y clientes.<\/li>\n<li>Cumplir nuestras obligaciones legales e investigar.<\/li>\n<\/ul>\n<h3 id=\"our-use-of-cookies\">Nuestro uso de cookies y otras tecnolog\u00edas<\/h3>\n<ul>\n<li><b>Galletas. <\/b>Las cookies son identificadores alfanum\u00e9ricos que transferimos al disco duro de su dispositivo a trav\u00e9s de su navegador web con fines de registro. Algunas cookies nos permiten facilitarle la navegaci\u00f3n por nuestro sitio web y nuestros servicios, mientras que otras se utilizan para agilizar el proceso de inicio de sesi\u00f3n o para permitirnos hacer un seguimiento de sus actividades en nuestro sitio web y nuestros servicios. Existen dos tipos de cookies: de sesi\u00f3n y permanentes.\n<ul>\n<li><i>Cookies de sesi\u00f3n. <\/i>Las cookies de sesi\u00f3n s\u00f3lo existen durante una sesi\u00f3n en l\u00ednea. Desaparecen de su dispositivo cuando cierra el navegador o apaga el dispositivo. Utilizamos cookies de sesi\u00f3n para permitir que nuestros sistemas le identifiquen de forma exclusiva durante una sesi\u00f3n o mientras est\u00e1 conectado al sitio web y a los servicios. Esto nos permite procesar sus transacciones y solicitudes en l\u00ednea y verificar su identidad, una vez que haya iniciado sesi\u00f3n, a medida que se desplaza por nuestro sitio web y nuestros servicios.<\/li>\n<li><i>Cookies persistentes. <\/i>Las cookies persistentes permanecen en su dispositivo despu\u00e9s de que haya cerrado el navegador o apagado el dispositivo. Utilizamos cookies persistentes para rastrear informaci\u00f3n agregada y estad\u00edstica sobre la actividad del usuario.<\/li>\n<\/ul>\n<\/li>\n<li><b>Desactivaci\u00f3n de cookies. <\/b>La mayor\u00eda de los navegadores le avisan autom\u00e1ticamente del uso de cookies. Dependiendo de sus preferencias, puede modificar las opciones de su navegador para bloquearlas en el futuro. La secci\u00f3n de Ayuda de la barra de herramientas de la mayor\u00eda de los navegadores le indicar\u00e1 c\u00f3mo impedir que su ordenador acepte nuevas cookies, c\u00f3mo hacer que el navegador le avise cuando reciba una nueva cookie o c\u00f3mo desactivar las cookies por completo. Los visitantes de nuestro sitio web y servicios que deshabiliten las cookies podr\u00e1n navegar por determinadas \u00e1reas del sitio web, pero es posible que algunas funciones no funcionen correctamente.<\/li>\n<li><b>Objetos de almacenamiento local Flash. <\/b>Podemos utilizar objetos de almacenamiento local Flash (\"Flash LSO\") para almacenar sus preferencias en el sitio web y personalizar su visita. Los Flash LSO se diferencian de las cookies del navegador por la cantidad y el tipo de datos almacenados. Normalmente, usted no puede controlar, eliminar o desactivar la aceptaci\u00f3n de Flash LSO a trav\u00e9s de su navegador web. Para m\u00e1s informaci\u00f3n sobre Flash LSOs, o para aprender a gestionar su configuraci\u00f3n para Flash LSOs, vaya a la p\u00e1gina de ayuda de Adobe Flash Player, elija \"Panel de configuraci\u00f3n de almacenamiento global\" y siga las instrucciones. Para ver los Flash LSOs actualmente en su ordenador, elija \"Panel de configuraci\u00f3n de almacenamiento del sitio web\" y siga las instrucciones para revisar y, si lo desea, eliminar cualquier Flash LSO espec\u00edfico.<\/li>\n<li><b>GIF transparentes, etiquetas de p\u00edxeles y otras tecnolog\u00edas<\/b>. Los GIF transparentes son gr\u00e1ficos diminutos con un identificador \u00fanico, cuya funci\u00f3n es similar a la de las cookies. A diferencia de las cookies, que se almacenan en el disco duro de su ordenador, los GIF transparentes se incrustan de forma invisible en p\u00e1ginas web y aplicaciones. Podemos utilizar GIF transparentes (tambi\u00e9n conocidos como balizas web, web bugs o etiquetas de p\u00edxel) en relaci\u00f3n con nuestro sitio web y nuestros servicios para, entre otras cosas, realizar un seguimiento de las actividades de los visitantes del sitio web y de los usuarios de las aplicaciones, ayudarnos a gestionar los contenidos y recopilar estad\u00edsticas sobre el uso del sitio web. Nosotros y nuestros proveedores de servicios externos tambi\u00e9n utilizamos GIF transparentes en los mensajes de correo electr\u00f3nico HTML que enviamos a nuestros clientes, para ayudarnos a realizar un seguimiento de los \u00edndices de respuesta a los mensajes de correo electr\u00f3nico, identificar cu\u00e1ndo se visualizan nuestros mensajes de correo electr\u00f3nico y realizar un seguimiento de si se reenv\u00edan nuestros mensajes de correo electr\u00f3nico.<\/li>\n<li><b>Uso entre dispositivos<\/b>. Nosotros y nuestros proveedores de servicios externos, incluido Google, podemos utilizar la informaci\u00f3n que recopilamos sobre usted (ya sea directamente desde nuestro sitio web, desde nuestras aplicaciones m\u00f3viles, a trav\u00e9s de su(s) dispositivo(s) o de un tercero) para ayudarnos a nosotros y a nuestros proveedores de servicios externos a identificar otros dispositivos que usted utilice (por ejemplo, un tel\u00e9fono m\u00f3vil, una tableta, otro ordenador, etc.). Nosotros, y nuestros proveedores de servicios externos, tambi\u00e9n podemos utilizar el uso cruzado de dispositivos y otra informaci\u00f3n que obtengamos sobre usted para ofrecer publicidad dirigida a sus dispositivos y enviarle correos electr\u00f3nicos. Para excluirse de la publicidad cruzada entre dispositivos, puede seguir las instrucciones indicadas en la secci\u00f3n Redes publicitarias de terceros que figura m\u00e1s adelante. Tenga en cuenta lo siguiente: si opta por excluirse de estas cookies de publicidad dirigida, su exclusi\u00f3n ser\u00e1 espec\u00edfica para el navegador web, la aplicaci\u00f3n o el dispositivo desde el que accedi\u00f3 a la exclusi\u00f3n. Si utiliza varios dispositivos o navegadores web, tendr\u00e1 que inhabilitar cada navegador o dispositivo que utilice.<\/li>\n<\/ul>\n<ul>\n<li><b>No Seguir<\/b>. Actualmente, nuestros sistemas no reconocen las solicitudes de \"no seguimiento\" de los navegadores. No obstante, puede desactivar determinados seguimientos, como se indica en esta secci\u00f3n (por ejemplo, desactivando las cookies); tambi\u00e9n puede optar por no recibir publicidad dirigida siguiendo las instrucciones de la secci\u00f3n Redes publicitarias de terceros.\n<ul>\n<li><i><u>Redes publicitarias de terceros.<\/u> <\/i>De vez en cuando, podemos proporcionar a estos anunciantes no afiliados informaci\u00f3n, incluida informaci\u00f3n personal, sobre usted. Utilizamos estas redes de anunciantes para ofrecer anuncios en nuestro sitio web, en nuestra aplicaci\u00f3n y en sitios web u otros medios de terceros (por ejemplo, plataformas de redes sociales). El uso compartido de su informaci\u00f3n con estos anunciantes nos permite dirigirnos a los productos y servicios que m\u00e1s pueden interesarle. Los proveedores de redes publicitarias, anunciantes, patrocinadores y\/o servicios de medici\u00f3n de tr\u00e1fico no afiliados pueden utilizar cookies, JavaScript, balizas web (incluidos GIF transparentes), Flash LSO y otras tecnolog\u00edas de seguimiento para medir la eficacia de sus anuncios y personalizar el contenido publicitario para usted. Las cookies y tecnolog\u00edas de terceros se rigen por la pol\u00edtica de privacidad espec\u00edfica de cada empresa, no por la presente.<\/li>\n<li>Nuestros usuarios en Estados Unidos pueden optar por no participar en muchas redes publicitarias de terceros mediante el uso de varios sitios web de asociaciones comerciales. Para m\u00e1s informaci\u00f3n, consulte Anuncios y correos electr\u00f3nicos. Tambi\u00e9n puede dirigirse a la Digital Advertising Alliance (\"DAA\") <a href=\"http:\/\/optout.aboutads.info\/?c=2&amp;lang=EN\" target=\"_blank\" rel=\"noopener\">P\u00e1gina de elecci\u00f3n del consumidor<\/a> para obtener informaci\u00f3n sobre la exclusi\u00f3n voluntaria de la publicidad basada en intereses y sobre sus opciones en relaci\u00f3n con el uso de la informaci\u00f3n por parte de los proveedores de servicios de Internet. <a href=\"https:\/\/blog.hubspot.com\/marketing\/email-unsubscribe-pages\" target=\"_blank\" rel=\"noopener\">Empresas de la DAA.<\/a> Tambi\u00e9n puede dirigirse a la Network Advertising Initiative (\"NAI\") <a href=\"http:\/\/optout.networkadvertising.org\/?c=1\" target=\"_blank\" rel=\"noopener\">P\u00e1gina de exclusi\u00f3n del consumidor<\/a> para obtener informaci\u00f3n sobre la exclusi\u00f3n voluntaria de la publicidad basada en intereses y sobre sus opciones en relaci\u00f3n con el uso de la informaci\u00f3n por parte de los proveedores de servicios de Internet. <a href=\"https:\/\/www.networkadvertising.org\/participating-networks\" target=\"_blank\" rel=\"noopener\">Miembros de la NAI.<\/a><\/li>\n<li>Exclusi\u00f3n voluntaria de una o varias empresas de la DAA <a href=\"http:\/\/optout.aboutads.info\/?c=2&amp;lang=EN\" target=\"_blank\" rel=\"noopener\">P\u00e1gina de elecci\u00f3n del consumidor<\/a> o la NAI <a href=\"http:\/\/optout.networkadvertising.org\/?c=1\" target=\"_blank\" rel=\"noopener\">P\u00e1gina de exclusi\u00f3n del consumidor<\/a> le impedir\u00e1 que esas empresas le env\u00eden contenidos o anuncios basados en sus intereses, pero eso no significa que deje de recibir publicidad a trav\u00e9s de nuestro sitio web, nuestros servicios o en otros sitios web. Es posible que siga recibiendo anuncios, por ejemplo, basados en el sitio web concreto que est\u00e9 viendo (es decir, anuncios basados en el contexto). Adem\u00e1s, si su navegador est\u00e1 configurado para rechazar las cookies cuando intente ejercer su derecho de exclusi\u00f3n en los sitios web de la DAA o la NAI, es posible que su exclusi\u00f3n no sea efectiva. Encontrar\u00e1 m\u00e1s informaci\u00f3n en el sitio web de la DAA <a href=\"http:\/\/www.aboutads.info\/\" target=\"_blank\" rel=\"noopener\">www.aboutads.info<\/a> o en el sitio web de la NAI <a href=\"https:\/\/www.networkadvertising.org\/\" target=\"_blank\" rel=\"noopener\">www.networkadvertising.org.<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3 id=\"ads-and-emails\">Anuncios y correos electr\u00f3nicos<\/h3>\n<p>RSA y nuestros socios pueden utilizar informaci\u00f3n sobre su visita a este y otros sitios web. La informaci\u00f3n puede incluir las p\u00e1ginas que visita, los elementos que ve o sus respuestas a nuestros anuncios y correos electr\u00f3nicos. Esta informaci\u00f3n nos permite hacer que los anuncios de RSA que ve sean m\u00e1s relevantes para usted. Esto se denomina publicidad basada en intereses. Con este fin, RSA ha seleccionado socios que son miembros de asociaciones autorreguladoras como Internet Advertising Bureau (IAB), Network Advertising Initiative (NAI) o Digital Advertising Alliance (DAA).<\/p>\n<p>Para que pueda darse de baja de la publicidad basada en intereses que ofrecen los socios que trabajan con RSA, o para personalizar su experiencia en los sitios web de RSA, visite <i>P\u00e1gina web de gesti\u00f3n de cookies alojada en Evidon <\/i>para darse de baja. Si opta por no participar, es posible que siga viendo anuncios de RSA en los sitios web de RSA y en otros sitios web, pero esos anuncios no ser\u00e1n personalizados para usted por RSA o nuestros socios.<\/p>\n<p>RSA continuar\u00e1 personalizando su experiencia en los sitios web de RSA mediante el uso de cookies. Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo RSA utiliza las cookies y c\u00f3mo gestionar su configuraci\u00f3n de cookies a trav\u00e9s de su navegador, consulte <a href=\"#your-consumer-privacy-rights\">Nuestro uso de cookies y otras tecnolog\u00edas<\/a>, arriba<\/p>\n<p>Tenga en cuenta que si borra las cookies, o si utiliza un navegador o dispositivo diferente, es posible que tenga que restablecer sus selecciones de exclusi\u00f3n.<\/p>\n<p>Puede obtener m\u00e1s informaci\u00f3n sobre la publicidad basada en intereses visitando estos enlaces:<\/p>\n<p>Alianza de Publicidad Digital (DAA) - <a href=\"http:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.aboutads.info\/choices\/<\/a><br \/>\nAlianza de Publicidad Digital de Canad\u00e1 (DAAC) - <a href=\"http:\/\/youradchoices.ca\/choices\" target=\"_blank\" rel=\"noopener\">http:\/\/youradchoices.ca\/choices<\/a><\/p>\n<h3>Herramienta de detecci\u00f3n COVID-19 y c\u00e1mara de visi\u00f3n t\u00e9rmica<\/h3>\n<p>Para ayudar a reducir el riesgo de infecciones por COVID-19 y mantener la seguridad de nuestras comunidades, todos los empleados de RSA, trabajadores eventuales y visitantes deben completar una encuesta de salud diaria y pasar un control de temperatura corporal t\u00e9rmica para poder acceder a las instalaciones de RSA. La c\u00e1mara de visi\u00f3n t\u00e9rmica mide su temperatura corporal de forma an\u00f3nima y RSA no retiene su temperatura corporal. Si su temperatura corporal es igual o superior a 100 grados Fahrenheit, se le denegar\u00e1 la entrada y\/o se le pedir\u00e1 que abandone las instalaciones de RSA.<\/p>\n<p>La herramienta de cribado de la encuesta de salud, disponible a trav\u00e9s de una aplicaci\u00f3n o un portal web, recopila su nombre, direcci\u00f3n de correo electr\u00f3nico y determinados datos de salud que usted proporciona voluntariamente. Esta informaci\u00f3n se conservar\u00e1 en su dispositivo y no se compartir\u00e1 con la RSA a menos que usted mismo informe de que es COVID-19 positivo. En ese caso, la herramienta notificar\u00e1 al equipo apropiado de la RSA, y su direcci\u00f3n de correo electr\u00f3nico se conservar\u00e1 durante un m\u00e1ximo de 30 d\u00edas (sujeto a las leyes locales) para que la RSA pueda ponerse en contacto con usted mientras toma las medidas adecuadas para proteger la salud y la seguridad de las personas en las ubicaciones f\u00edsicas de la RSA. Su estado de COVID-19 positivo ser\u00e1 compartido con el equipo de RSA y las autoridades de salud p\u00fablica aplicables (seg\u00fan lo requerido por la ley). Su estado tambi\u00e9n se compartir\u00e1 de forma an\u00f3nima con personas potencialmente infectadas con fines de rastreo de contactos.<\/p>\n<h3 id=\"your-consumer-privacy-rights\">Sus derechos como consumidor<\/h3>\n<p><b>Usted puede tener los siguientes derechos de privacidad del consumidor bajo las leyes estatales aplicables, incluyendo las leyes de privacidad de California:<\/b><\/p>\n<ul>\n<li><i>Derecho a saber<\/i>: puede tener derecho a solicitar informaci\u00f3n sobre los datos personales que hemos recopilado sobre usted y con qu\u00e9 fin.<\/li>\n<li><i>Derecho de acceso<\/i>: puede tener derecho a solicitar informaci\u00f3n sobre c\u00f3mo procesamos su informaci\u00f3n personal y a obtener una copia de dicha informaci\u00f3n personal.<\/li>\n<li><i>Derecho a la portabilidad<\/i>Puede tener derecho a recibir su informaci\u00f3n personal en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica, y a que esa informaci\u00f3n se transmita a otra organizaci\u00f3n en determinadas circunstancias.<\/li>\n<li><i>Derecho de supresi\u00f3n<\/i>Puede tener derecho a solicitar la supresi\u00f3n de la informaci\u00f3n personal que hayamos recopilado sobre usted.<\/li>\n<li><i>Derecho a no sufrir discriminaci\u00f3n<\/i>: RSA no le discriminar\u00e1 por ejercer su derecho a la intimidad como consumidor.<\/li>\n<\/ul>\n<p>CATEGOR\u00cdAS DE INFORMACI\u00d3N PERSONAL QUE PODAMOS HABER RECOPILADO SOBRE USTED Y DIVULGADO CON FINES COMERCIALES A NUESTROS SOCIOS COMERCIALES<br \/>\n\u00daltima actualizaci\u00f3n: 1 de enero de 2020<\/p>\n<ul>\n<li>DATOS DE CONTACTO E IDENTIFICADORES: Identificadores como nombre real, alias, direcci\u00f3n postal, identificador personal \u00fanico, identificador en l\u00ednea, n\u00famero de etiqueta de servicio, direcci\u00f3n de correo electr\u00f3nico, nombre de cuenta, n\u00famero de la seguridad social, n\u00famero del permiso de conducir, n\u00famero de pasaporte u otros identificadores similares.<\/li>\n<li>INFORMACI\u00d3N T\u00c9CNICA, DE RENDIMIENTO Y EN L\u00cdNEA: Cookies e informaci\u00f3n de seguimiento como la direcci\u00f3n de protocolo de Internet, balizas web, identificador de dispositivo, localizador uniforme de recursos, datos de geolocalizaci\u00f3n, tipo de navegador e idioma, horas de acceso, otros identificadores \u00fanicos y otros datos t\u00e9cnicos que puedan identificar de forma exclusiva el dispositivo, el sistema o el navegador, registros de registro del servidor (incluidas las solicitudes de p\u00e1ginas), datos recogidos por medios automatizados para medir la respuesta de los consumidores a los contenidos en l\u00ednea, informes de errores e informaci\u00f3n sobre el rendimiento, credenciales, datos telem\u00e9tricos, informaci\u00f3n sobre la actividad en Internet u otras redes electr\u00f3nicas, incluidos, entre otros, el historial de navegaci\u00f3n, el historial de b\u00fasqueda y la informaci\u00f3n relativa a la interacci\u00f3n de un residente con un sitio web, una aplicaci\u00f3n o un anuncio en Internet.<\/li>\n<li>INFORMACI\u00d3N DE SERVICIOS AL CLIENTE: Registros de clientes que contienen informaci\u00f3n personal, como nombre, direcci\u00f3n, n\u00famero de tel\u00e9fono, documentos de identidad expedidos por el gobierno, educaci\u00f3n, empleo, estado civil, n\u00famero de cuenta bancaria, n\u00famero de tarjeta de cr\u00e9dito, n\u00famero de tarjeta de d\u00e9bito o cualquier otra informaci\u00f3n financiera, informaci\u00f3n m\u00e9dica, opiniones y comentarios recogidos de los distintos tipos de encuestas, datos de asistencia a cursos, datos de sitios comunitarios.<\/li>\n<li>CLASIFICACIONES PROTEGIDAS: Caracter\u00edsticas de clasificaciones protegidas en virtud de la legislaci\u00f3n californiana o federal, como raza, sexo, edad, fecha de nacimiento, origen nacional, discapacidad, condici\u00f3n de ciudadan\u00eda e informaci\u00f3n gen\u00e9tica.<\/li>\n<li>HISTORIAL DE COMPRAS E INFORMACI\u00d3N DE CUENTAS: Informaci\u00f3n comercial, incluidos registros de productos o servicios comprados, obtenidos o considerados, u otros historiales o tendencias de compra o consumo.<\/li>\n<li>INFORMACI\u00d3N BIOM\u00c9TRICA: caracter\u00edsticas fisiol\u00f3gicas, biol\u00f3gicas o de comportamiento que pueden utilizarse solas o en combinaci\u00f3n con otras para establecer la identidad individual, grabaciones de voz, salud e informaci\u00f3n visual.<\/li>\n<li>INFORMACI\u00d3N LABORAL: Informaci\u00f3n profesional o relacionada con el empleo.<\/li>\n<li>PERFILES E INFERENCIAS: Inferencias extra\u00eddas de cualquiera de las informaciones identificadas anteriormente para crear un perfil sobre un residente que refleje sus preferencias, caracter\u00edsticas, tendencias psicol\u00f3gicas, predisposiciones, comportamiento, actitudes, inteligencia, habilidades y aptitudes, informaci\u00f3n demogr\u00e1fica, datos de redes sociales.<\/li>\n<\/ul>\n<h3>Presentar una solicitud<\/h3>\n<p>Si tiene alguna pregunta sobre el tipo de informaci\u00f3n personal que tenemos sobre usted o si desea solicitar la supresi\u00f3n de la informaci\u00f3n personal que podamos tener sobre usted, o ejercer cualquier otro derecho de privacidad del consumidor seg\u00fan lo establecido anteriormente, p\u00f3ngase en contacto con nosotros mediante:<\/p>\n<ul>\n<li>Enviando una solicitud por escrito a <a href=\"mailto:privacy@rsa.com\">privacy@rsa.com,<\/a> o<\/li>\n<li>Escribi\u00e9ndonos a la direcci\u00f3n postal que figura al pie de esta Declaraci\u00f3n de confidencialidad o en su Resumen.<\/li>\n<\/ul>\n<p>Tenga en cuenta que su solicitud no garantiza el acceso completo ni la eliminaci\u00f3n total, ya que la ley puede no permitir o exigir la eliminaci\u00f3n en determinadas circunstancias.<\/p>\n<h3 id=\"your-marketing-choices\">Sus opciones de marketing<\/h3>\n<p>Puede elegir c\u00f3mo le enviamos ofertas de marketing y otros usos de su informaci\u00f3n. Para actualizar sus preferencias, puede hacerlo:<\/p>\n<ul>\n<li>Haga clic en \"cancelar suscripci\u00f3n\" en cualquier comunicaci\u00f3n de marketing por correo electr\u00f3nico que le enviemos.<\/li>\n<li>Acceda a su MyAccount o visite nuestro <a href=\"https:\/\/www2.rsa.com\/communication-preference-management\" target=\"_blank\" rel=\"noopener\">Centro de Gesti\u00f3n de Preferencias<\/a> para seleccionar sus opciones de comunicaci\u00f3n comercial.<\/li>\n<li>Visite nuestro <a href=\"https:\/\/www2.rsa.com\/global-email-unsub\" target=\"_blank\" rel=\"noopener\">P\u00e1gina de eliminaci\u00f3n <\/a>no recibir comunicaciones comerciales.<\/li>\n<\/ul>\n<p>Tenga en cuenta que sus preferencias de correo electr\u00f3nico pueden tardar hasta 10 d\u00edas laborables en surtir efecto.<\/p>\n<h3>C\u00f3mo protegemos su informaci\u00f3n<\/h3>\n<p>Utilizamos medidas de seguridad t\u00e9cnicas, organizativas y f\u00edsicas adecuadas para proteger los datos contra el acceso, uso o divulgaci\u00f3n no autorizados de la informaci\u00f3n que recopilamos, utilizamos o almacenamos. Las formas en que lo hacemos incluyen:<\/p>\n<ul>\n<li>Utilizar el cifrado al recoger o transferir informaci\u00f3n sensible, como datos de tarjetas de cr\u00e9dito.<\/li>\n<li>Dise\u00f1ar nuestras salvaguardias de seguridad de los datos para garantizar la seguridad, integridad, disponibilidad y resistencia permanentes de los sistemas y servicios de procesamiento.<\/li>\n<li>Limitar el acceso f\u00edsico a nuestras instalaciones.<\/li>\n<li>Limitar el acceso a la informaci\u00f3n que recopilamos sobre usted.<\/li>\n<li>Garantizar que nuestros socios comerciales cuentan con las medidas de seguridad t\u00e9cnicas y organizativas adecuadas para mantener protegida su informaci\u00f3n personal.<\/li>\n<li>Destruir o desidentificar la informaci\u00f3n personal seg\u00fan lo exija la ley.<\/li>\n<\/ul>\n<p>Le recomendamos que mantenga la confidencialidad de las contrase\u00f1as que utilice y que tenga cuidado para evitar estafas de \"phishing\" en las que alguien puede enviarle un correo electr\u00f3nico que parece ser de RSA solicitando su informaci\u00f3n personal. RSA no solicitar\u00e1 su ID o contrase\u00f1a a trav\u00e9s del correo electr\u00f3nico.<\/p>\n<h3>Recogida y uso de informaci\u00f3n sobre menores<\/h3>\n<p>Somos conscientes de la importancia de tomar precauciones adicionales para proteger la privacidad y la seguridad de los ni\u00f1os que utilizan nuestros productos, servicios y sitios web. Los ni\u00f1os menores de 13 a\u00f1os o la edad m\u00ednima equivalente en la jurisdicci\u00f3n pertinente, no deben compartir su informaci\u00f3n personal a menos que sus padres o tutores proporcionen un consentimiento verificable. Si en alg\u00fan momento un padre o tutor necesita acceder a los datos asociados a la cuenta de su hijo o tutor o eliminarlos, puede ponerse en contacto con nosotros a trav\u00e9s de una de las opciones previstas en esta Declaraci\u00f3n de privacidad.<\/p>\n<h3>Enlaces a sitios web y servicios de terceros<\/h3>\n<p>En ocasiones podemos ofrecer enlaces a otros sitios web que, si hace clic en ellos, pueden recopilar informaci\u00f3n personal sobre usted y dirigirle a esos sitios web. Las pr\u00e1cticas en materia de informaci\u00f3n de esos sitios web de terceros enlazados a nuestro sitio web est\u00e1n cubiertas por las propias declaraciones de privacidad de los terceros, por lo que le recomendamos que las lea.<\/p>\n<h3>Contacte con nosotros<\/h3>\n<p>Si desea hacer ejercicio <a href=\"#your-consumer-privacy-rights\">Sus derechos como consumidor<\/a> como se describe en esta Declaraci\u00f3n de privacidad, tiene alguna pregunta, duda o queja sobre privacidad, p\u00f3ngase en contacto con nosotros en <a href=\"mailto:privacy@rsa.com\">privacy@rsa.com<\/a> o escr\u00edbanos a<\/p>\n<p>RSA Security LLC<br \/>\nAtenci\u00f3n Departamento Jur\u00eddico - Privacidad<br \/>\n176 Middlesex Turnpike<br \/>\nBedford, MA 01730 EE.UU.<\/p>\n<p><b>Fecha de entrada en vigor: 1 de enero de 2020.<br \/>\n\u00daltima actualizaci\u00f3n: 1 de septiembre de 2020<\/b><\/p>\n<h2>Pol\u00edtica de uso aceptable<\/h2>\n<h3><b>En general<\/b><\/h3>\n<p>La Pol\u00edtica de Uso Aceptable (\"PUA\") de RSA Security LLC y sus filiales (\"RSA\") tiene por objeto fomentar el uso responsable de la infraestructura, redes, ofertas basadas en la nube, sistemas, servicios, sitios web, instalaciones y productos de RSA (colectivamente, la \"Infraestructura y Servicios de RSA\") por parte de nuestros clientes y otros Usuarios. Los Usuarios aceptan regirse por los t\u00e9rminos de esta PUA. RSA se reserva el derecho de modificar esta PUA a su discreci\u00f3n en cualquier momento. Las modificaciones entrar\u00e1n en vigor cuando se publiquen y se espera que los Usuarios consulten esta p\u00e1gina de vez en cuando para tomar conocimiento de cualquier cambio que realicemos, ya que son legalmente vinculantes para cada Usuario. El uso por parte de los Usuarios de los sitios web de RSA despu\u00e9s de que realicemos modificaciones constituye la aceptaci\u00f3n de nuestras modificaciones.<\/p>\n<h3><b>Suspensi\u00f3n; cese<\/b><\/h3>\n<p>Si RSA determina que cualquier usuario ha violado cualquier parte de esta PUA, RSA puede terminar el uso de los usuarios del sitio web. RSA suspender\u00e1 el servicio por violaci\u00f3n de la PUA sobre la base m\u00e1s limitada que RSA determine que es razonablemente pr\u00e1ctica bajo las circunstancias para hacer frente a la violaci\u00f3n subyacente. RSA intentar\u00e1 notificar al Usuario antes de suspender el servicio por violaci\u00f3n de la PUA (que puede ser a trav\u00e9s de correo electr\u00f3nico o cualquier otra notificaci\u00f3n). Sin embargo, RSA puede suspender el servicio sin previo aviso si RSA tiene conocimiento de una violaci\u00f3n de esta PUA o de cualquier ley o reglamento aplicable que exponga a RSA a responsabilidad penal o civil, o que exponga a RSA o a cualquier propiedad de terceros a da\u00f1os. El da\u00f1o puede incluir, pero no se limita a, el riesgo de tener una o m\u00e1s direcciones IP colocadas en listas negras. RSA puede tomar cualquier otra medida que considere apropiada dadas las circunstancias para eliminar o impedir la repetici\u00f3n de infracciones. RSA no se hace responsable de ning\u00fan tipo de da\u00f1os que los Usuarios o terceros puedan sufrir como consecuencia, en todo o en parte, del ejercicio por parte de RSA de sus derechos en virtud de la presente PUA. Esta exclusi\u00f3n de responsabilidad no incluye la responsabilidad de RSA por muerte o da\u00f1os personales causados por su negligencia, o cualquier otra responsabilidad que RSA no pueda excluir o limitar por ley.<\/p>\n<h2>Conductas prohibidas<\/h2>\n<h3><b>En general<\/b><\/h3>\n<p>Los usuarios s\u00f3lo podr\u00e1n utilizar los sitios web de la RSA para los fines previstos. Los usuarios no deben utilizar los sitios web de la RSA para fines il\u00edcitos.<\/p>\n<h3><b>Contenido inapropiado<\/b><\/h3>\n<p>Los usuarios no deben utilizar los sitios web de RSA para transmitir, distribuir o almacenar contenidos: (a) que infrinjan cualquier ley o normativa aplicable, incluidas las leyes o normativas de exportaci\u00f3n o encriptaci\u00f3n; (b) que puedan afectar negativamente a los sitios web de RSA o a otros clientes de RSA; o (c) que puedan exponer a RSA a responsabilidad penal o civil.<\/p>\n<p>Los usuarios no deben utilizar los sitios web de la RSA para transmitir, distribuir o almacenar material que sea inapropiado, seg\u00fan lo determine razonablemente la RSA, o material que sea obsceno (incluida la pornograf\u00eda infantil), difamatorio, calumnioso, amenazante, abusivo, odioso, ofensivo desde el punto de vista racial o \u00e9tnico, acosador, humillante para otras personas (p\u00fablicamente o de otro modo), o de otro modo objetable. Para ser absolutamente claros, los Usuarios no deben almacenar (ni permanente ni temporalmente), procesar ni transmitir a trav\u00e9s de ninguno de los sitios web de la RSA contenidos pornogr\u00e1ficos de ning\u00fan tipo.<\/p>\n<h3><b>Derechos de propiedad intelectual<\/b><\/h3>\n<p>El material accesible a trav\u00e9s de los sitios web de RSA o contenido en los mismos puede estar sujeto a protecci\u00f3n en virtud de leyes de privacidad, protecci\u00f3n de datos o confidencialidad y puede contener derechos de propiedad intelectual propiedad de RSA o de terceros. La propiedad intelectual puede incluir, entre otros, derechos de autor, patentes, marcas comerciales, nombres comerciales, secretos comerciales u otra informaci\u00f3n de propiedad. Los usuarios no deben utilizar los sitios web de RSA de manera que infrinjan, diluyan, se apropien indebidamente, violen o infrinjan de otro modo cualquiera de estos derechos o leyes. Los usuarios son responsables de garantizar que disponen de todos los derechos y licencias necesarios para todos los contenidos que coloquen en los sitios web de RSA. Los Usuarios deben indemnizar plenamente a RSA con respecto a cualquier reclamaci\u00f3n de terceros presentada contra RSA basada en una alegaci\u00f3n de que el Usuario no cumpli\u00f3 con sus obligaciones en virtud del presente p\u00e1rrafo.<\/p>\n<h3><b>Contenido y conducta malintencionados<\/b><\/h3>\n<p>Los usuarios no deben utilizar los sitios web de la RSA para transmitir, distribuir o almacenar material que pueda da\u00f1ar o interferir con los sitios web de la RSA o las redes, sistemas, servicios o sitios web de terceros. El contenido malicioso incluye, entre otros, virus, gusanos y troyanos.<\/p>\n<p>Los usuarios no deben utilizar los sitios web de RSA para llevar a cabo actividades que puedan ser perjudiciales o interferir con los sitios web de RSA o las redes, sistemas, servicios o sitios web de terceros, incluyendo, pero no limitado a, inundaciones, bombardeo de correo o ataques de denegaci\u00f3n de servicio. Se proh\u00edbe a los usuarios violar o intentar violar la seguridad de los sitios web de RSA o los ordenadores, cuentas o redes de terceros. Tambi\u00e9n se proh\u00edbe a los usuarios cualquier actividad considerada precursora de intentos de violaci\u00f3n de la seguridad, incluyendo, entre otras, cualquier forma de escaneo, sondeo u otra actividad de prueba o recopilaci\u00f3n de informaci\u00f3n. La actividad inapropiada puede dar lugar a responsabilidad civil o penal. RSA puede investigar dicha actividad, y puede involucrar y cooperar con las autoridades policiales en la persecuci\u00f3n de los Usuarios involucrados en dicha actividad.<\/p>\n<h3><b>Contenidos fraudulentos y enga\u00f1osos<\/b><\/h3>\n<p>Los usuarios no deben utilizar los sitios web de la RSA para transmitir o distribuir material que contenga ofertas fraudulentas de bienes o servicios, o cualquier material publicitario, promocional o de otro tipo que contenga declaraciones, afirmaciones o representaciones falsas, enga\u00f1osas o que no cumplan con las leyes de publicidad aplicables o las pr\u00e1cticas comerciales habituales. Los usuarios no deben utilizar los sitios web de la RSA para enmascarar su verdadera identidad o para fingir ser alguien o algo que no son.<\/p>\n<h3><b>Recopilaci\u00f3n de datos personales<\/b><\/h3>\n<p>Los Usuarios no deben utilizar los sitios web de la RSA para recopilar, procesar o almacenar, o intentar recopilar, procesar o almacenar, datos personales relativos a terceros en contravenci\u00f3n de la legislaci\u00f3n aplicable. Si los Usuarios recopilan datos personales de terceros, deber\u00e1n cumplir en todo momento las leyes y normativas aplicables en materia de protecci\u00f3n de datos.<\/p>\n<h3><b>Correo electr\u00f3nico y mensajes no solicitados<\/b><\/h3>\n<p>Los usuarios no deben utilizar los sitios web de RSA para transmitir mensajes de correo electr\u00f3nico no solicitados, incluyendo, sin limitaci\u00f3n, correo electr\u00f3nico masivo no solicitado (\"spam\"), o correos electr\u00f3nicos destinados a acosar o molestar a otros. Adem\u00e1s, los Usuarios no deben utilizar el servicio de otro proveedor para enviar spam con el fin de promocionar un sitio web alojado en los sitios web de RSA o conectado a ellos.<\/p>\n<h3><b>Responsabilidad del contenido<\/b><\/h3>\n<p>RSA no tiene ninguna responsabilidad por cualquier contenido proporcionado por el Usuario o contenido al que el Usuario pueda acceder en o a trav\u00e9s de los sitios web de RSA. RSA no est\u00e1 obligada a supervisar o ejercer control editorial sobre dicho contenido. Si RSA tiene conocimiento de que cualquier contenido puede violar esta PUA, exponer a RSA a responsabilidad civil o penal, o ambas, entonces RSA puede bloquear el acceso a ese contenido y suspender o terminar la provisi\u00f3n de los sitios web de RSA a cualquier Usuario que cree, almacene o difunda dicho material. RSA tambi\u00e9n puede cooperar con las autoridades legales y terceros en cualquier investigaci\u00f3n de presuntas infracciones.<\/p>\n<h3><strong>Notificaci\u00f3n de infracciones<\/strong><\/h3>\n<p>RSA solicita que cualquier persona que tenga conocimiento de una violaci\u00f3n de esta PUA comunique esta informaci\u00f3n a RSA por correo electr\u00f3nico a <a href=\"mailto:Dell_Legal_Notices@dell.com\">privacy@rsa.com<\/a> o cualquier otra direcci\u00f3n de notificaci\u00f3n que pueda estar indicada en las Condiciones Complementarias del servicio aplicable. RSA podr\u00e1 tomar las medidas que considere oportunas a su entera discreci\u00f3n con respecto a dichas infracciones.<\/p>\n<h3><b>Notificaci\u00f3n de infracciones de derechos de autor<\/b><\/h3>\n<p>Si alg\u00fan Usuario cree que su trabajo protegido por derechos de autor ha sido copiado y est\u00e1 accesible en los sitios web de la RSA de forma que constituye una infracci\u00f3n de los derechos de autor, env\u00ede una notificaci\u00f3n a:<\/p>\n<p>RSA Security LLC<br \/>\nA la atenci\u00f3n de: RSA Legal<br \/>\n176 Middlesex Turnpike<br \/>\nBedford, MA 01730<\/p>\n<p>Los avisos deben incluir cada uno de los siguientes elementos<br \/>\n(1) La firma electr\u00f3nica o f\u00edsica del titular del derecho exclusivo presuntamente infringido, o la firma electr\u00f3nica o f\u00edsica de una persona autorizada para actuar en nombre del titular;<br \/>\n(2) Identificaci\u00f3n del trabajo protegido por derechos de autor cuya infracci\u00f3n se alega o, si una \u00fanica notificaci\u00f3n abarca varios trabajos protegidos por derechos de autor en un \u00fanico sitio en l\u00ednea, una lista representativa de dichos trabajos en ese sitio;<br \/>\n(3) Identificaci\u00f3n del material supuestamente infractor o que es objeto de una actividad infractora, para el que se solicita la desactivaci\u00f3n del acceso o la eliminaci\u00f3n, e informaci\u00f3n razonablemente suficiente para permitirnos localizar el material;<br \/>\n(4) Si la infracci\u00f3n alegada se debe al almacenamiento intermedio y temporal, o cach\u00e9, de material, incluya tambi\u00e9n una declaraci\u00f3n que confirme que el material infractor ha sido retirado del sitio de origen o que el acceso al mismo ha sido deshabilitado o que un tribunal ha ordenado que el material sea retirado o que el acceso a dicho material sea deshabilitado;<br \/>\n(5) Si la infracci\u00f3n reclamada se debe a que se remite o enlaza a los usuarios a una ubicaci\u00f3n en l\u00ednea que contiene material infractor o actividad infractora, mediante el uso de herramientas de localizaci\u00f3n de informaci\u00f3n, entonces, en lugar de la identificaci\u00f3n conforme a los apartados (3) o (4), proporcione la identificaci\u00f3n de la referencia o enlace, al material o actividad reclamados, que se va a eliminar o cuyo acceso se va a inhabilitar, e informaci\u00f3n razonablemente suficiente para permitirnos localizar dicha referencia o enlace;<br \/>\n(6) Informaci\u00f3n razonablemente suficiente para permitirnos ponernos en contacto con usted, como una direcci\u00f3n, un n\u00famero de tel\u00e9fono y, si est\u00e1 disponible, una direcci\u00f3n de correo electr\u00f3nico en la que se le pueda contactar;<br \/>\n(7) Una declaraci\u00f3n de que usted cree de buena fe que el uso del material de la manera reclamada no est\u00e1 autorizado por el propietario de los derechos de autor, su agente o la ley; y,<br \/>\n(8) Una declaraci\u00f3n de que la informaci\u00f3n contenida en la notificaci\u00f3n es exacta y, bajo pena de perjurio, que usted est\u00e1 autorizado a actuar en nombre del titular de un derecho exclusivo que presuntamente se ha infringido.<\/p>\n<p><em>\u00a92022 RSA Security LLC o sus filiales. Todos los derechos reservados. El logotipo de RSA Conference, RSA y otras marcas comerciales son marcas comerciales de RSA Security LLC o sus filiales. Otras marcas pueden ser marcas comerciales de sus respectivos propietarios.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Su privacidad es importante para nosotros, por lo que hemos desarrollado esta Declaraci\u00f3n de Privacidad que describe nuestra pr\u00e1ctica de privacidad sobre c\u00f3mo procesamos, recopilamos, utilizamos y compartimos su informaci\u00f3n personal, as\u00ed como sus derechos de privacidad bajo ciertas leyes de privacidad. Esta Declaraci\u00f3n de Privacidad (\u201cDeclaraci\u00f3n de Privacidad\u201d) se aplica a RSA Security LLC (\u201cRSA\u201d \u201cnosotros\u201d o \u201cnuestro\u201d). Descripci\u00f3n general de ... <a href=\"https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/\">Contin\u00faa en<\/a><\/p>","protected":false},"author":2,"featured_media":0,"parent":3,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-policy.blade.php","meta":{"_acf_changed":false,"_searchwp_excluded":"","inline_featured_image":false,"footnotes":""},"class_list":["post-3615","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - January 2022 - RSA<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - January 2022 - RSA\" \/>\n<meta property=\"og:description\" content=\"Your privacy is important to us so we have developed this Privacy Statement that outlines our privacy practice on how we process, collect, use and share your personal information as well as your privacy rights under certain privacy laws. This Privacy Statement (&#8220;Privacy Statement&#8221;) applies to RSA Security LLC (&#8220;RSA&#8221; &#8220;we&#8221; or &#8220;our&#8221;). Overview of &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"RSA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T19:50:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/privacy\\\/privacy-policy-january-2022\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/privacy\\\/privacy-policy-january-2022\\\/\",\"name\":\"Privacy Policy - January 2022 - RSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\"},\"datePublished\":\"2022-08-08T19:37:49+00:00\",\"dateModified\":\"2026-03-24T19:50:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/privacy\\\/privacy-policy-january-2022\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rsa.com\\\/es\\\/privacy\\\/privacy-policy-january-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/privacy\\\/privacy-policy-january-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\",\"item\":\"https:\\\/\\\/www.rsa.com\\\/es\\\/privacy\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Privacy Policy &#8211; January 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"name\":\"RSA\",\"description\":\"Cybersecurity and Digital Risk Management Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rsa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#organization\",\"name\":\"RSA\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"contentUrl\":\"https:\\\/\\\/www.rsa.com\\\/wp-content\\\/uploads\\\/rsa.png\",\"width\":2880,\"height\":1020,\"caption\":\"RSA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rsa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - Enero 2022 - RSA","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Privacy Policy - January 2022 - RSA","og_description":"Your privacy is important to us so we have developed this Privacy Statement that outlines our privacy practice on how we process, collect, use and share your personal information as well as your privacy rights under certain privacy laws. This Privacy Statement (&#8220;Privacy Statement&#8221;) applies to RSA Security LLC (&#8220;RSA&#8221; &#8220;we&#8221; or &#8220;our&#8221;). Overview of &hellip; Continued","og_url":"https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/","og_site_name":"RSA","article_modified_time":"2026-03-24T19:50:54+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa-og-image.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/","url":"https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/","name":"Pol\u00edtica de privacidad - Enero 2022 - RSA","isPartOf":{"@id":"https:\/\/www.rsa.com\/#website"},"datePublished":"2022-08-08T19:37:49+00:00","dateModified":"2026-03-24T19:50:54+00:00","breadcrumb":{"@id":"https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rsa.com\/es\/privacy\/privacy-policy-january-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rsa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy","item":"https:\/\/www.rsa.com\/es\/privacy\/"},{"@type":"ListItem","position":3,"name":"Privacy Policy &#8211; January 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.rsa.com\/#website","url":"https:\/\/www.rsa.com\/","name":"RSA","description":"Soluciones de ciberseguridad y gesti\u00f3n de riesgos digitales","publisher":{"@id":"https:\/\/www.rsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.rsa.com\/#organization","name":"RSA","url":"https:\/\/www.rsa.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","contentUrl":"https:\/\/www.rsa.com\/wp-content\/uploads\/rsa.png","width":2880,"height":1020,"caption":"RSA"},"image":{"@id":"https:\/\/www.rsa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/pages\/3615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/comments?post=3615"}],"version-history":[{"count":4,"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/pages\/3615\/revisions"}],"predecessor-version":[{"id":37425,"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/pages\/3615\/revisions\/37425"}],"up":[{"embeddable":true,"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/pages\/3"}],"wp:attachment":[{"href":"https:\/\/www.rsa.com\/es\/wp-json\/wp\/v2\/media?parent=3615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}